{"id":51107,"date":"2013-08-02T18:10:44","date_gmt":"2013-08-02T21:10:44","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=51107"},"modified":"2013-08-04T20:02:54","modified_gmt":"2013-08-04T23:02:54","slug":"centenas-de-pessoas-participam-do-lancamento-do-programa-mais-sopa-em-itaporanga","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/centenas-de-pessoas-participam-do-lancamento-do-programa-mais-sopa-em-itaporanga\/","title":{"rendered":"Centenas de pessoas participam do programa Mais Sopa em Itaporanga"},"content":{"rendered":"<p style=\"text-align: justify;\">A Prefeitura de Itaporanga D\u2019Ajuda, atrav\u00e9s da Secretaria Municipal de Assist\u00eancia Social, lan\u00e7ou na tarde desta quinta-feira (01), na Rua Francisco Sobral Garcez, 291, no Bairro da Esta\u00e7\u00e3o, o programa social Mais Sopa.<\/p>\n<div id=\"attachment_51109\" style=\"width: 598px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-51109\" class=\"size-full wp-image-51109\" alt=\" Centenas de pessoas participam do lan\u00e7amento do programa Mais Sopa em Itaporanga D' Ajuda. (Divulga\u00e7\u00e3o\/Ascom\/PMI)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630.jpg\" width=\"588\" height=\"441\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630.jpg 588w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630-342x256.jpg 342w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630-60x45.jpg 60w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630-150x113.jpg 150w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/20130801_162630-269x201.jpg 269w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/a><p id=\"caption-attachment-51109\" class=\"wp-caption-text\"><br \/>Centenas de pessoas participam do lan\u00e7amento do programa Mais Sopa em Itaporanga D&#8217; Ajuda. (Divulga\u00e7\u00e3o\/Ascom\/PMI)<\/p><\/div>\n<p style=\"text-align: justify;\">Idealizado pela primeira gest\u00e3o da prefeita Maria das Gra\u00e7as (Gracinha), o programa vai atender aproximadamente 400 fam\u00edlias, oriundas de v\u00e1rios bairros da sede do munic\u00edpio, sendo crian\u00e7as, gestantes, adultos, idosos e pessoas com defici\u00eancia, todas em situa\u00e7\u00e3o de vulnerabilidade quanto \u00e0 inseguran\u00e7a alimentar.<\/p>\n<p style=\"text-align: justify;\">O Programa Mais Sopa congrega a\u00e7\u00f5es socioeducativas junto \u00e0s fam\u00edlias, prestando informa\u00e7\u00f5es e orienta\u00e7\u00f5es sobre seguran\u00e7a alimentar, direitos socioassistenciais, atrav\u00e9s de din\u00e2micas, rodas de conversas, relato de hist\u00f3rias, apresenta\u00e7\u00f5es de v\u00eddeos, entre outros.<\/p>\n<p style=\"text-align: justify;\">Bastante emocionada, a prefeita Gracinha destacou a import\u00e2ncia social do programa.<\/p>\n<div id=\"attachment_51110\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/IMG_1903.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-51110\" class=\"size-full wp-image-51110\" alt=\" O programa \u00e9 a concretiza\u00e7\u00e3o de uma uma promessa de campanha da atual prefeita, Gracinha.(Divulga\u00e7\u00e3o\/PMI)\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/IMG_1903.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/IMG_1903.jpg 600w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/IMG_1903-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/08\/IMG_1903-342x227.jpg 342w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-51110\" class=\"wp-caption-text\"><br \/>O programa \u00e9 a concretiza\u00e7\u00e3o de uma uma promessa de campanha da atual prefeita, Gracinha.(Divulga\u00e7\u00e3o\/PMI)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cEsse \u00e9 um programa que faz parte da nossa pol\u00edtica p\u00fablica voltada ao resgate social e \u00e0 promo\u00e7\u00e3o humana. Um programa social que criamos na nossa primeira gest\u00e3o e que ficou esquecido pelo meu antecessor, mas agora resgatamos para atender os anseios do nosso povo\u201d, explica a prefeita.<\/p>\n<p style=\"text-align: justify;\">De acordo com a m\u00e9dica Elma Amorim, os beneficiados pelo programa fazem parte do Cadastro \u00danico dos Programas Sociais do munic\u00edpio e passaram por uma avalia\u00e7\u00e3o nutricional antes de serem inscritos.<\/p>\n<p style=\"text-align: justify;\">\u201cAs fam\u00edlias cadastradas foram selecionadas atrav\u00e9s de um levantamento realizado pela Secretaria de Assist\u00eancia Social. Todas elas atendem os requisitos b\u00e1sicos para terem direito ao benef\u00edcio alimentar. N\u00f3s estamos come\u00e7ando com uma m\u00e9dia de 400 refei\u00e7\u00f5es por dia, mas a inten\u00e7\u00e3o da prefeita \u00e9 aumentar aos poucos o n\u00famero de refei\u00e7\u00f5es\u201d, observa a cl\u00ednica geral.<\/p>\n<p style=\"text-align: justify;\">O Programa Mais Sopa, que foi aprovado pelo Conselho Municipal de Assist\u00eancia Social e de Seguran\u00e7a Alimentar e Nutricional, ser\u00e1 custeado com recursos pr\u00f3prios do munic\u00edpio, mas est\u00e1 aberto para receber doa\u00e7\u00f5es e realizar parcerias.<\/p>\n<p style=\"text-align: justify;\">Inicialmente ser\u00e3o distribu\u00eddas 2 mil refei\u00e7\u00f5es por semana, totalizando 8 mil refei\u00e7\u00f5es por m\u00eas. As refei\u00e7\u00f5es ser\u00e3o servidas na Rua Francisco Sobral Garcez, 291, no Bairro da Esta\u00e7\u00e3o, sempre \u00e0s 16h, de segunda a sexta-feira.<\/p>\n<p style=\"text-align: justify;\"><strong>Prest\u00edgio<\/strong><\/p>\n<p style=\"text-align: justify;\">Apesar das fortes chuvas que ca\u00edram na cidade, centenas de pessoas compareceram ao lan\u00e7amento do programa. Al\u00e9m da popula\u00e7\u00e3o, v\u00e1rias autoridades municipais estiveram acompanhando o lan\u00e7amento do programa, entre elas, o vice-prefeito Adiel dos Campos, a presidente da C\u00e2mara Municipal, Mariza da Mata, e os vereadores Marcelo Anchieta, Bruno Sobral, Renatinho de Z\u00e9 de Lili, Gilson Me Ajude, Tonho de Luquinha, Celinha Sobral e Gordo Propaganda.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m estiveram presentes os secret\u00e1rios Antonio Peu (Controle Interno), Urania Sobral (Planejamento), Rubens Murilo (Administra\u00e7\u00e3o), Elis\u00f4nia Lisboa (Sa\u00fade), Doralice Alfano (Educa\u00e7\u00e3o), Erivalda Santana (Finan\u00e7as), Thiago Luduvice (Governo), C\u00e9sar de Beb\u00e9 (Agricultura), Railda Araujo (Cultura), e Igor Garcez (adjunto de Obras), entre outros.<\/p>\n<p style=\"text-align: justify;\"><strong>Pronunciamentos<\/strong><\/p>\n<p style=\"text-align: justify;\">Assim como a prefeita, o vice-prefeito, e a m\u00e9dica Elma Amorim, os vereadores Gilsom Me Ajude, Tonho de Luquinha, Marcelo Anchieta, Gordo Propaganda e Celinha Sobral, tamb\u00e9m fizeram pronunciamento reconhecendo a import\u00e2ncia social do programa e parabenizando a prefeita pela iniciativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Itaporanga D\u2019Ajuda, atrav\u00e9s da Secretaria Municipal de Assist\u00eancia Social, lan\u00e7ou na tarde desta quinta-feira (01), na Rua Francisco Sobral Garcez, 291, no Bairro da Esta\u00e7\u00e3o, o programa social Mais Sopa. Idealizado pela primeira gest\u00e3o da prefeita Maria das Gra\u00e7as (Gracinha), o programa vai atender aproximadamente 400 fam\u00edlias, oriundas de v\u00e1rios bairros da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,6],"tags":[],"class_list":{"0":"post-51107","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-municipios","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/51107"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=51107"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/51107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/51110"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=51107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=51107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=51107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}