{"id":45110,"date":"2013-03-04T14:11:01","date_gmt":"2013-03-04T17:11:01","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=45110"},"modified":"2013-03-04T14:12:16","modified_gmt":"2013-03-04T17:12:16","slug":"militantes-se-opoem-a-pastor-no-comando-da-comissao-de-direitos-humanos","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/militantes-se-opoem-a-pastor-no-comando-da-comissao-de-direitos-humanos\/","title":{"rendered":"Militantes se op\u00f5em a pastor no comando da Comiss\u00e3o de Direitos Humanos"},"content":{"rendered":"<div id=\"attachment_45111\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/03\/FelicianoAlexandraMartins.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-45111\" class=\"size-full wp-image-45111\" title=\"FelicianoAlexandraMartins\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2013\/03\/FelicianoAlexandraMartins.jpg\" alt=\"\" width=\"290\" height=\"280\" \/><\/a><p id=\"caption-attachment-45111\" class=\"wp-caption-text\">Deputado credita resist\u00eancia ao seu nome a preconceito religioso (Foto: Alexandra Martins\/Ag. C\u00e2mara)<\/p><\/div>\n<p style=\"text-align: justify;\">Pen\u00faltimo colegiado a ser escolhido\u00a0na semana passada pelos l\u00edderes partid\u00e1rios, a Comiss\u00e3o de Direitos Humanos e Minorias (CDH) da C\u00e2mara acabou no centro de uma pol\u00eamica nos \u00faltimos dias. O motivo \u00e9 a poss\u00edvel indica\u00e7\u00e3o do deputado Pastor Marco Feliciano (PSC-SP) para presidir o \u00f3rg\u00e3o. Seu nome, ainda n\u00e3o formalizado pelo PSC, enfrenta resist\u00eancia de deputados ligados \u00e0 defesa dos direitos humanos e de entidades da comunidade de l\u00e9sbicas, gays, bissexuais, travestis, transexuais e transg\u00eaneros (LGBT). H\u00e1 at\u00e9 uma guerra de abaixo-assinados, contra e a favor \u00e0 eventual indica\u00e7\u00e3o dele, na internet.<\/p>\n<p style=\"text-align: justify;\">A rea\u00e7\u00e3o contra Marco Feliciano se deve a algumas declara\u00e7\u00f5es pol\u00eamicas dadas pelo deputado nos \u00faltimos anos. No Twitter, em 2011, ele chamou negros de \u201cdescendentes amaldi\u00e7oados de No\u00e9\u201d. Contra homossexuais, chegou a dizer que \u201ca podrid\u00e3o dos sentimentos dos homoafetivos levam\u00a0<em>(sic)<\/em>\u00a0ao \u00f3dio, ao crime, \u00e0 rejei\u00e7\u00e3o. Amamos os homossexuais, mas abominamos suas pr\u00e1ticas prom\u00edscuas\u201d. Em discurso na C\u00e2mara, ele defendeu a limita\u00e7\u00e3o de div\u00f3rcios a um por pessoa, pois, na avalia\u00e7\u00e3o dele, \u201cuma fam\u00edlia destru\u00edda hoje projeta sequelas por toda uma gera\u00e7\u00e3o\u201d. O deputado diz que a resist\u00eancia ao seu nome \u00e9 fruto de persegui\u00e7\u00e3o religiosa e de \u201ccristofobia\u201d.<\/p>\n<p style=\"text-align: justify;\">A bancada do PSC na C\u00e2mara se re\u00fane amanh\u00e3 para decidir se confirma a indica\u00e7\u00e3o de Marco Feliciano. O simples fato de a comiss\u00e3o ter ficado com um partido que, historicamente, n\u00e3o tem liga\u00e7\u00e3o com a \u00e1rea desperta desconfian\u00e7a e preocupa\u00e7\u00e3o em deputados com atua\u00e7\u00e3o na defesa dos direitos humanos. A bancada do PSC \u00e9 composta, em sua maioria, por parlamentares evang\u00e9licos e pouco afeitos a discuss\u00f5es de temas de g\u00eanero, sexualidade e minorias sociais, geralmente tratados na comiss\u00e3o. Desde 1995, quando foi criada, a Comiss\u00e3o de Direitos Humanos foi tradicionalmente comandada por legendas do campo da esquerda, como PT, PSB e PCdoB. Nilm\u00e1rio Miranda (PT-MG) foi o seu primeiro presidente. Nos \u00faltimos tr\u00eas anos, os deputados Luiz Couto (PT-PB), Manuela D\u2019\u00c1vila (PCdoB-RS) e Domingos Dutra (PT-MA) comandaram a CDH.<\/p>\n<p style=\"text-align: justify;\">Desta vez, por\u00e9m, PT e PCdoB voltaram suas aten\u00e7\u00f5es para outras comiss\u00f5es. Quando os deputados ainda discutiam a cria\u00e7\u00e3o de dois novos colegiados, os petistas decidiram que, das quatro escolhas a que o partido teria direito, a CDH seria a \u00faltima. As comiss\u00f5es de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ), Rela\u00e7\u00f5es Exteriores e Defesa Nacional e a de Sa\u00fade, uma das novas, seriam as tr\u00eas primeiras escolhas. A ideia era manter a CCJ, assumir a Comiss\u00e3o de Rela\u00e7\u00f5es Exteriores no lugar do PCdoB e abrigar o grupo ligado ao ex-presidente da Casa Marco Maia (PT-RS) na Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Com a dificuldade de desmembrar as comiss\u00f5es de Turismo e Desporto (CTD) e Seguridade Social e Fam\u00edlia (CSSF), a solu\u00e7\u00e3o encontrada pelo presidente da C\u00e2mara, Henrique Eduardo Alves (PMDB-RN), foi\u00a0dividir a de Educa\u00e7\u00e3o e Cultura (CEC). A nova Comiss\u00e3o de Educa\u00e7\u00e3o ficou com o PMDB, enquanto a rec\u00e9m-criada Comiss\u00e3o de Cultura, com o PCdoB. Esta \u00e9 a principal \u00e1rea de atua\u00e7\u00e3o da deputada Jandira Feghali (PCdoB-RJ), ex-secret\u00e1ria municipal de Cultura do Rio de Janeiro. O PT, por\u00e9m, n\u00e3o voltou a se reunir para discutir uma nova divis\u00e3o dos colegiados, j\u00e1 que o partido perderia uma escolha com a divis\u00e3o apenas da CEC.<\/p>\n<p style=\"text-align: justify;\"><strong>Bancada ruralista<\/strong><\/p>\n<p style=\"text-align: justify;\">Por causa disso, o PT acabou sendo apontado como um dos culpados pela possibilidade de Marco Feliciano assumir a CDH. No Twitter, o deputado Jean Wyllys (Psol-RJ), principal nome na C\u00e2mara na defesa da causa LGBT, atribuiu a mudan\u00e7a de comando da comiss\u00e3o aos petistas. Na vis\u00e3o dele, ocorreu um acordo para garantir a governabilidade. \u201cO que mostra o quanto o PT est\u00e1 comprometido mais em se manter no poder do que com a defesa dos direitos humanos de minorias\u201d, disparou.<\/p>\n<p style=\"text-align: justify;\">\u201cO PT n\u00e3o tem culpa pela escolha dos outros partidos nas suas comiss\u00f5es\u201d, discordou a deputada Erika Kokay (PT-DF), atual vice-presidenta da Comiss\u00e3o de Direitos Humanos. Para a petista, a poss\u00edvel indica\u00e7\u00e3o de Feliciano para presidir a CDH deve ser imputada somente ao PSC. Ela acredita, no entanto, que haver\u00e1 um \u201cbom senso\u201d da lideran\u00e7a do partido que resulte na indica\u00e7\u00e3o de um deputado \u201cmais flex\u00edvel\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Alian\u00e7a com ruralistas<\/strong><\/p>\n<p style=\"text-align: justify;\">Deputados ligados aos movimentos de direitos humanos do PT acreditam em um outro motivo para o PSC escolher a CDH: uma suposta articula\u00e7\u00e3o da bancada evang\u00e9lica com os ruralistas para evitar debates em quest\u00f5es como reforma agr\u00e1ria e concess\u00e3o de terras para descendentes de quilombolas e \u00edndios. \u201cLamento profundamente este desfecho\u201d, disse o atual presidente da CDH, Domingos Dutra (PT-MA). Para ele, ruralistas e evang\u00e9licos se uniram para esvaziar a comiss\u00e3o. No ano passado, explicou, o colegiado teve audi\u00eancias p\u00fablicas sobre terras ind\u00edgenas e de quilombolas, contrariando interesses de agricultores e pecuaristas interessados em mais espa\u00e7os para produ\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O PSC, na divis\u00e3o pela proporcionalidade das bancadas, ficou com a 20\u00aa escolha das comiss\u00f5es. Quando chegou a vez do partido, apenas duas estavam dispon\u00edveis: a CDH e a Comiss\u00e3o de Legisla\u00e7\u00e3o Participativa (CPL), porta de entrada de sugest\u00f5es legislativas feitas pela sociedade civil. De pouca express\u00e3o, a CPL normalmente \u00e9 a \u00faltima a ser escolhida. \u201cA minha op\u00e7\u00e3o pela Comiss\u00e3o de Direitos Humanos ocorreu porque n\u00e3o t\u00ednhamos muitas escolhas dispon\u00edveis\u201d, disse o l\u00edder do PSC na C\u00e2mara, Andr\u00e9 Moura (SE).<\/p>\n<p style=\"text-align: justify;\">Ele acredita que a rea\u00e7\u00e3o contr\u00e1ria \u00e0 possibilidade de o partido assumir a CDH se deve pelo debate feito pela legenda a respeito de determinados assuntos que causam pol\u00eamica no Congresso, como quest\u00f5es ligadas \u00e0 sexualidade e \u00e0 religiosidade. \u201cIsso faz parte do processo democr\u00e1tico. Voc\u00ea n\u00e3o pode ter apenas um lado. Se todos pensassem e comungassem da mesma opini\u00e3o, n\u00e3o existiria debate\u201d, disse o deputado sergipano.<\/p>\n<p style=\"text-align: justify;\"><strong>Contraponto<\/strong><\/p>\n<p style=\"text-align: justify;\">Segundo ele, o partido espera ter maior visibilidade ao oferecer um contraponto ao atual modelo da comiss\u00e3o. \u201cVai trazer essa contribui\u00e7\u00e3o que at\u00e9 ent\u00e3o n\u00e3o tinha. O pastor era praticamente uma voz sozinha nos debates\u201d, disse Moura, referindo-se \u00e0 atual composi\u00e7\u00e3o do colegiado.<\/p>\n<p style=\"text-align: justify;\">De acordo com o o l\u00edder do PSC, o partido n\u00e3o fez qualquer articula\u00e7\u00e3o com a bancada ruralista para escolher a comiss\u00e3o. \u201cEsse tipo de declara\u00e7\u00e3o \u00e9 precipitada e irrespons\u00e1vel. Exijo respeito com o nosso partido\u201d, retrucou. Ele disse que o PSC est\u00e1 preocupado com \u201cos temas que est\u00e3o sendo debatidos\u201d e que a ideia \u00e9 indicar algu\u00e9m que \u201cmilite na \u00e1rea e que tenha responsabilidade no tema\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Fonte: Congresso em Foco<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pen\u00faltimo colegiado a ser escolhido\u00a0na semana passada pelos l\u00edderes partid\u00e1rios, a Comiss\u00e3o de Direitos Humanos e Minorias (CDH) da C\u00e2mara acabou no centro de uma pol\u00eamica nos \u00faltimos dias. O motivo \u00e9 a poss\u00edvel indica\u00e7\u00e3o do deputado Pastor Marco Feliciano (PSC-SP) para presidir o \u00f3rg\u00e3o. Seu nome, ainda n\u00e3o formalizado pelo PSC, enfrenta resist\u00eancia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[310],"tags":[],"class_list":{"0":"post-45110","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques-da-semana"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/45110"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=45110"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/45110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/45111"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=45110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=45110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=45110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}