{"id":152011,"date":"2026-05-13T15:26:07","date_gmt":"2026-05-13T18:26:07","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=152011"},"modified":"2026-05-13T15:26:07","modified_gmt":"2026-05-13T18:26:07","slug":"delegacia-da-mulher-de-aracaju-ultrapassa-marca-de-mil-inqueritos-instaurados-em-2026","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/delegacia-da-mulher-de-aracaju-ultrapassa-marca-de-mil-inqueritos-instaurados-em-2026\/","title":{"rendered":"Delegacia da Mulher de Aracaju ultrapassa marca de mil inqu\u00e9ritos instaurados em 2026"},"content":{"rendered":"<p style=\"font-weight: 400;\">A Delegacia de Atendimento \u00e0 Mulher de Aracaju (Deam), vinculada ao Departamento de Atendimento a Grupos Vulner\u00e1veis (DAGV), j\u00e1 alcan\u00e7ou, neste ano, a marca de mil inqu\u00e9ritos policiais instaurados para apura\u00e7\u00e3o de crimes de viol\u00eancia dom\u00e9stica, familiar e sexual contra mulheres. O n\u00famero refor\u00e7a a atua\u00e7\u00e3o cont\u00ednua da Pol\u00edcia Civil de Sergipe no enfrentamento \u00e0 viol\u00eancia de g\u00eanero e na prote\u00e7\u00e3o \u00e0s v\u00edtimas.<\/p>\n<p style=\"font-weight: 400;\">Al\u00e9m do volume expressivo de investiga\u00e7\u00f5es instauradas ao longo do ano, o plant\u00e3o do DAGV registrou, somente no \u00faltimo fim de semana, 27 autos de pris\u00e3o em flagrante delito e 31 representa\u00e7\u00f5es por medidas protetivas de urg\u00eancia.<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2026\/05\/IMG_6025-e1778696721485.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-152012 aligncenter\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2026\/05\/IMG_6025-e1778696721485.jpeg\" alt=\"\" width=\"524\" height=\"349\" \/><\/a><\/p>\n<p style=\"font-weight: 400;\">De acordo com a diretora do DAGV, delegada Mariana Diniz, os n\u00fameros representam mais do que estat\u00edsticas e refletem a atua\u00e7\u00e3o firme do Estado no combate \u00e0 viol\u00eancia contra a mulher.<\/p>\n<p style=\"font-weight: 400;\">\u201c\u00c9 com profundo sentimento de responsabilidade que a Deam alcan\u00e7a essa marca expressiva de inqu\u00e9ritos policiais. Esse n\u00famero vai al\u00e9m da estat\u00edstica e representa a presen\u00e7a firme do Estado na apura\u00e7\u00e3o rigorosa de crimes de viol\u00eancia dom\u00e9stica, familiar e de crimes sexuais\u201d, destacou.<\/p>\n<p style=\"font-weight: 400;\">A delegada ressaltou ainda que os resultados do \u00faltimo fim de semana demonstram a capacidade de pronta resposta da Pol\u00edcia Civil diante das ocorr\u00eancias envolvendo viol\u00eancia contra mulheres e grupos vulner\u00e1veis. \u201cA prova de que nosso trabalho \u00e9 ininterrupto e vigilante est\u00e1 nos dados do \u00faltimo fim de semana. Esses resultados demonstram a efici\u00eancia da nossa pronta resposta. Retiramos o agressor no momento do crime e acionamos imediatamente os mecanismos legais para garantir a seguran\u00e7a da v\u00edtima\u201d, afirmou Mariana Diniz.<\/p>\n<p style=\"font-weight: 400;\">Tamb\u00e9m conforme a diretora do DAGV, o trabalho da unidade segue fortalecido tanto no rigor investigativo quanto no acolhimento \u00e0s v\u00edtimas. \u201cNossa miss\u00e3o institucional \u00e9 clara: proteger e acolher a mulher sergipana, garantindo que a impunidade n\u00e3o tenha lugar. O DAGV segue fortalecido e de portas abertas, reafirmando que nossa atua\u00e7\u00e3o ser\u00e1 sempre pautada pelo rigor da lei e pelo acolhimento humanizado\u201d, evidenciou.<\/p>\n<p style=\"font-weight: 400;\">A Pol\u00edcia Civil refor\u00e7a que den\u00fancias de viol\u00eancia dom\u00e9stica e familiar podem ser feitas presencialmente nas unidades especializadas, pelo Disque-Den\u00fancia 181 ou por meio do telefone 190 em situa\u00e7\u00f5es de emerg\u00eancia.<br \/>\n<strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a><\/em><\/strong><br \/>\nFonte: Ssp se<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia de Atendimento \u00e0 Mulher de Aracaju (Deam), vinculada ao Departamento de Atendimento a Grupos Vulner\u00e1veis (DAGV), j\u00e1 alcan\u00e7ou, neste ano, a marca de mil inqu\u00e9ritos policiais instaurados para apura\u00e7\u00e3o de crimes de viol\u00eancia dom\u00e9stica, familiar e sexual contra mulheres. O n\u00famero refor\u00e7a a atua\u00e7\u00e3o cont\u00ednua da Pol\u00edcia Civil de Sergipe no enfrentamento \u00e0 [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,7],"tags":[10809,38393],"class_list":{"0":"post-152011","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-policia","8":"tag-dagv","9":"tag-deam"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/152011"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=152011"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/152011\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=152011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=152011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=152011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}