{"id":146548,"date":"2025-02-17T07:19:12","date_gmt":"2025-02-17T10:19:12","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=146548"},"modified":"2025-02-17T07:19:12","modified_gmt":"2025-02-17T10:19:12","slug":"prefeito-de-lourdes-faz-anuncio-historico-municipio-construira-duas-creches","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/prefeito-de-lourdes-faz-anuncio-historico-municipio-construira-duas-creches\/","title":{"rendered":"Prefeito de Lourdes faz an\u00fancio hist\u00f3rico: Munic\u00edpio construir\u00e1 duas creches"},"content":{"rendered":"<p>O Prefeito de Nossa Senhora de Lourdes, Dr. Saulo Galeguinho, utilizou suas redes sociais na \u00faltima sexta-feira, 14, para anunciar uma grande conquista para a Educa\u00e7\u00e3o: a constru\u00e7\u00e3o de duas creches que ir\u00e3o beneficiar as fam\u00edlias lourdenses. A a\u00e7\u00e3o faz parte de uma s\u00e9rie de decis\u00f5es que est\u00e3o sendo tomadas pelo gestor rec\u00e9m-empossado para transformar a realidade educacional da cidade.<\/p>\n<p>Al\u00e9m de anunciar a constru\u00e7\u00e3o das duas unidades, nos \u00faltimos dias, o prefeito tem explicado \u00e0 popula\u00e7\u00e3o sobre a medida que envolve o fim do regime multisseriado, no qual estudantes de diversas s\u00e9ries diferentes estudam na mesma sala. Ao assumir, Saulo anunciou que cada aluno estudar\u00e1 na sua s\u00e9rie de fato, pondo fim a esse regime que, comprovadamente, dificulta o aprendizado.<\/p>\n<div id=\"attachment_146549\" style=\"width: 606px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2025\/02\/Prefeito-Saulo-Galeguinho-SE-Noticias-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-146549\" class=\"size-full wp-image-146549\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2025\/02\/Prefeito-Saulo-Galeguinho-SE-Noticias-1.jpeg\" alt=\"\" width=\"596\" height=\"555\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2025\/02\/Prefeito-Saulo-Galeguinho-SE-Noticias-1.jpeg 596w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2025\/02\/Prefeito-Saulo-Galeguinho-SE-Noticias-1-300x279.jpeg 300w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/a><p id=\"caption-attachment-146549\" class=\"wp-caption-text\">Prefeito de Nossa Senhora de Lourdes, Dr. Saulo Galeguinho &#8211; Foto: ascom\/divulga\u00e7\u00e3o<\/p><\/div>\n<p>As creches que ser\u00e3o constru\u00eddas s\u00e3o frutos de recursos diferentes, sendo uma com recursos federais e outra com recursos estaduais. Ambas foram liberadas sob a insist\u00eancia e articula\u00e7\u00e3o do prefeito nos \u00faltimos meses, desde que se sagrou vitorioso no pleito municipal de 2024. \u201cEsse foi um compromisso firmado desde a campanha com o nosso povo. O objetivo \u00e9 nada mais que fortalecer a educa\u00e7\u00e3o infantil e atender a crescente demanda de pais que necessitam do servi\u00e7o\u201d, disse Saulo.<\/p>\n<p>Ao anunciar a conquista dupla, o gestor municipal tamb\u00e9m refor\u00e7ou a import\u00e2ncia da participa\u00e7\u00e3o da popula\u00e7\u00e3o no processo, orientando os interessados a realizarem a pr\u00e9-matr\u00edcula no N\u00facleo Escolar para que a administra\u00e7\u00e3o possa mapear a demanda real das fam\u00edlias.<\/p>\n<p>O trabalho continua, e a gest\u00e3o municipal segue empenhada em oferecer mais estrutura e qualidade de vida para a popula\u00e7\u00e3o de Nossa Senhora de Lourdes. \u201cEm menos de dois meses os frutos de um trabalho s\u00e9rio e comprometido est\u00e3o sendo colhidos e o resultado ao final de todo esse processo ser\u00e1 a transforma\u00e7\u00e3o definitiva da nossa hist\u00f3ria\u201d, destacou Saulo Galeguinho.<\/p>\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a><\/em><\/strong>,\u00a0<strong><em>\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>\u00a0e\u00a0no<\/em>\u00a0<em><a href=\"https:\/\/twitter.com\/Senoticias\">X<\/a><\/em><\/strong><\/p>\n<p>Ascom Dr. Saulo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Prefeito de Nossa Senhora de Lourdes, Dr. Saulo Galeguinho, utilizou suas redes sociais na \u00faltima sexta-feira, 14, para anunciar uma grande conquista para a Educa\u00e7\u00e3o: a constru\u00e7\u00e3o de duas creches que ir\u00e3o beneficiar as fam\u00edlias lourdenses. A a\u00e7\u00e3o faz parte de uma s\u00e9rie de decis\u00f5es que est\u00e3o sendo tomadas pelo gestor rec\u00e9m-empossado para transformar [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":146549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,38],"tags":[42220,43250,43251],"class_list":{"0":"post-146548","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-municipios","9":"tag-dr-saulo-galeguinho","10":"tag-prefeito-de-lourdes","11":"tag-prefeito-de-nossa-senhora-de-lourdes"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/146548"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=146548"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/146548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/146549"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=146548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=146548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=146548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}