{"id":146362,"date":"2025-02-05T16:37:22","date_gmt":"2025-02-05T19:37:22","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=146362"},"modified":"2025-02-05T16:41:20","modified_gmt":"2025-02-05T19:41:20","slug":"secretaria-de-estado-do-meio-ambiente-emite-alerta-para-chuvas-intensas-em-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/secretaria-de-estado-do-meio-ambiente-emite-alerta-para-chuvas-intensas-em-sergipe\/","title":{"rendered":"Secretaria de Estado do Meio Ambiente emite alerta para chuvas intensas em Sergipe"},"content":{"rendered":"<p>O estado de Sergipe est\u00e1 sob alerta meteorol\u00f3gico de chuvas moderadas a intensas nas pr\u00f3ximas horas, acompanhadas de ventos fortes, trovoadas, chuvas de granizo e descargas el\u00e9tricas. O boletim foi emitido pela Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac) nesta quarta-feira, 5, e o alerta segue at\u00e9 \u00e0s 11h da pr\u00f3xima sexta-feira, 7, podendo se estender at\u00e9 o s\u00e1bado, 8. O acumulado de chuva deve ultrapassar 50 mm, e os ventos intensos podem variar entre 40 e 60 km\/h.<\/p>\n<p>A ger\u00eancia de Meteorologia da Semac orienta a popula\u00e7\u00e3o para a possibilidade de ocorr\u00eancia de situa\u00e7\u00f5es de risco como alagamentos, deslizamentos de encostas, e transbordamento de pequenos c\u00f3rregos, riachos, rios e lagoas.<\/p>\n<div id=\"attachment_142266\" style=\"width: 607px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/05\/Chuvas-em-Aracaju-SE-Noticias.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-142266\" class=\"size-full wp-image-142266\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/05\/Chuvas-em-Aracaju-SE-Noticias.jpg\" alt=\"\" width=\"597\" height=\"461\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/05\/Chuvas-em-Aracaju-SE-Noticias.jpg 597w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/05\/Chuvas-em-Aracaju-SE-Noticias-300x232.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/05\/Chuvas-em-Aracaju-SE-Noticias-45x35.jpg 45w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/a><p id=\"caption-attachment-142266\" class=\"wp-caption-text\">Alerta segue at\u00e9 \u00e0s 11h da pr\u00f3xima sexta-feira, 7, e pode se estender at\u00e9 o s\u00e1bado, 8 &#8211; Foto: arquivo\/SE Not\u00edcias<\/p><\/div>\n<p>O boletim indica que as condi\u00e7\u00f5es ocorrem devido \u00e0s altas temperaturas e umidade atmosf\u00e9rica, favorecendo a instabilidade termodin\u00e2mica, ou seja, a forma\u00e7\u00e3o de nuvens com trovoadas e descargas.<\/p>\n<p>Esta instabilidade est\u00e1 presente no Nordeste do Brasil devido ao escoamento em m\u00e9dios e altos n\u00edveis da atmosfera sobre o continente e nuvens convectivas associadas a Zona de Converg\u00eancia Intertropical (ZCIT) e V\u00f3rtice Cicl\u00f4nico em Altos N\u00edveis (VCAN). Outro fator \u00e9 o aquecimento e umidade do Oceano Atl\u00e2ntico adjacente. Somados, eles favorecem o transporte de nuvens carregadas para o estado.<\/p>\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a><\/em><\/strong>,\u00a0<strong><em>\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>\u00a0e\u00a0no<\/em>\u00a0<em><a href=\"https:\/\/twitter.com\/Senoticias\">X<\/a><\/em><\/strong><\/p>\n<p>Fonte: Ag\u00eancia Sergipe de Not\u00edcias<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estado de Sergipe est\u00e1 sob alerta meteorol\u00f3gico de chuvas moderadas a intensas nas pr\u00f3ximas horas, acompanhadas de ventos fortes, trovoadas, chuvas de granizo e descargas el\u00e9tricas. O boletim foi emitido pela Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac) nesta quarta-feira, 5, e o alerta segue at\u00e9 \u00e0s 11h da pr\u00f3xima [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":142266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[14087,40990,43154,8021],"class_list":{"0":"post-146362","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-politica","9":"tag-chuvas-intensas","10":"tag-chuvas-intensas-em-sergipe","11":"tag-gerencia-de-meteorologia","12":"tag-secretaria-de-estado-do-meio-ambiente"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/146362"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=146362"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/146362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/142266"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=146362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=146362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=146362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}