{"id":142954,"date":"2024-06-21T10:38:19","date_gmt":"2024-06-21T13:38:19","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=142954"},"modified":"2024-06-21T11:37:19","modified_gmt":"2024-06-21T14:37:19","slug":"posto-do-instituto-de-identificacao-na-rodoviaria-passa-a-funcionar-temporariamente-na-rua-do-turista-no-mes-de-julho","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/posto-do-instituto-de-identificacao-na-rodoviaria-passa-a-funcionar-temporariamente-na-rua-do-turista-no-mes-de-julho\/","title":{"rendered":"Posto do Instituto de Identifica\u00e7\u00e3o na rodovi\u00e1ria passa a funcionar temporariamente na Rua do Turista no m\u00eas de julho"},"content":{"rendered":"\n<p>O Instituto de Identifica\u00e7\u00e3o Papiloscopista Wendel da Silva Gonzaga (IIWSG) informa que o ponto de atendimento do CEAC do Terminal Rodovi\u00e1rio Governador Jos\u00e9 Rollemberg Leite &#8211; Rodovi\u00e1ria Nova &#8211; passar\u00e1 a funcionar na Rua do Turista, no Centro de Aracaju, entre os dias 1\u00ba e 31 de julho. A altera\u00e7\u00e3o \u00e9 tempor\u00e1ria e ocorre em virtude das obras de manuten\u00e7\u00e3o el\u00e9trica na unidade da Rodovi\u00e1ria Nova.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"326\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/06\/RG-se-noticias.jpeg\" alt=\"\" class=\"wp-image-142961\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/06\/RG-se-noticias.jpeg 588w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/06\/RG-se-noticias-300x166.jpeg 300w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><figcaption>Ap\u00f3s o t\u00e9rmino da obra, posto retoma \u00e0 Rodovi\u00e1ria, e nova unidade ser\u00e1 aberta na Rua do Turista &#8211; Foto: SSP\/SE<\/figcaption><\/figure>\n\n\n\n<p>Diante da reforma, os cidad\u00e3os que derem entrada na Carteira de Identidade Nacional (CIN) no posto Rodovi\u00e1ria Nova at\u00e9 o dia 27 de junho, ter\u00e3o que fazer a retirada do documento j\u00e1 no posto da Rua do Turista. Ap\u00f3s o retorno do Ceac Rodovi\u00e1ria Nova, a equipe de identifica\u00e7\u00e3o voltar\u00e1 a atender normalmente no local, e o posto da Rua do Turista tamb\u00e9m permanecer\u00e1 ativo.<\/p>\n\n\n\n<p>De acordo com o diretor do IIWSG, Jenilson Gomes, todas as pessoas que solicitaram a CIN no CEAC Rodovi\u00e1ria e ainda n\u00e3o fizeram a retirada do documento ter\u00e3o de procurar a Rua do Turista. \u201cContinuar\u00e1 funcionando no mesmo hor\u00e1rio de expediente do posto da Rodovi\u00e1ria, ou seja, de 7h \u00e0s 13h. Al\u00e9m da emiss\u00e3o da primeira via da CIN, tamb\u00e9m \u00e9 poss\u00edvel emitir o atestado de bons antecedentes\u201d, detalhou.<\/p>\n\n\n\n<p>Diante da demanda de atendimento, ap\u00f3s a conclus\u00e3o da reforma do posto do CEAC Rodovi\u00e1ria Nova, a popula\u00e7\u00e3o ganha uma nova unidade do IIWSG, j\u00e1 que tanto o posto do Terminal Rodovi\u00e1rio, quanto a Rua do Turista estar\u00e3o em funcionamento. \u201c\u00c9 fruto do esfor\u00e7o da SSP em aumentar a nossa capacidade de atendimento. Assim, teremos uma equipe pronta para continuar o funcionamento no Centro de Aracaju\u201d, acrescentou Jenilson.<\/p>\n\n\n\n<p>Ainda conforme Jenilson Gomes, o procedimento de agendamento segue os mesmos padr\u00f5es j\u00e1 definidos pelo Instituto de Identifica\u00e7\u00e3o. \u201c\u00c0s segundas e quintas, \u00e0s 12h, as senhas s\u00e3o distribu\u00eddas no site da SSP. Diariamente, o atendimento preferencial sem a necessidade de agendamento pr\u00e9vio, a exemplo de idosos, gestantes, menores de dois anos, pessoas com defici\u00eancia, autistas, pacientes oncol\u00f3gicos e cidad\u00e3o com fibromialgia. Basta se dirigir \u00e0s 7h\u201d, finalizou o diretor do Instituto de Identifica\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>A<strong><em>companhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/em><\/strong>,\u00a0<strong><em><strong><em>\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e<\/em><\/strong>\u00a0no<\/em>\u00a0<em><a href=\"https:\/\/twitter.com\/Senoticias\">X<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: SSP\/SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto de Identifica\u00e7\u00e3o Papiloscopista Wendel da Silva Gonzaga (IIWSG) informa que o ponto de atendimento do CEAC do Terminal Rodovi\u00e1rio Governador Jos\u00e9 Rollemberg Leite &#8211; Rodovi\u00e1ria Nova &#8211; passar\u00e1 a funcionar na Rua do Turista, no Centro de Aracaju, entre os dias 1\u00ba e 31 de julho. A altera\u00e7\u00e3o \u00e9 tempor\u00e1ria e ocorre em [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6,1],"tags":[9651,8593,16941],"class_list":{"0":"post-142954","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-politica","8":"category-sem-categoria","9":"tag-instituto-de-identificacao","10":"tag-rg","11":"tag-rua-do-turista"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/142954"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=142954"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/142954\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=142954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=142954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=142954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}