{"id":142058,"date":"2024-04-23T05:51:17","date_gmt":"2024-04-23T08:51:17","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=142058"},"modified":"2024-04-23T06:08:03","modified_gmt":"2024-04-23T09:08:03","slug":"cbf-confirma-datas-horarios-e-locais-da-terceira-fase-da-copa-do-brasil-veja-detalhes","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/cbf-confirma-datas-horarios-e-locais-da-terceira-fase-da-copa-do-brasil-veja-detalhes\/","title":{"rendered":"CBF confirma datas, hor\u00e1rios e locais da terceira fase da Copa do Brasil; veja detalhes"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A CBF (Confedera\u00e7\u00e3o Brasileira de Futebol) divulgou na noite desta segunda-feira a tabela detalhada da terceira fase da Copa Brasil. Os jogos v\u00e3o do dia 30 de abril at\u00e9 23 de maio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2016\/11\/Gremio-vai-a-final-da-copa-do-Brasil-SE-Noticias-1024x683.jpg\" alt=\"\" class=\"wp-image-97641\"\/><figcaption>Terceira Fase da competi\u00e7\u00e3o mais inclusiva do pa\u00eds iniciar\u00e1 na ter\u00e7a-feira (30) e ser\u00e1 conclu\u00edda no dia 23 de maio &#8211; Foto: Lucas Uebel\/Gr\u00eamio FBPA<\/figcaption><\/figure>\n\n\n\n<p>O S\u00e3o Paulo, atuou campe\u00e3o da competi\u00e7\u00e3o, vai encarar o \u00c1guia de Marab\u00e1 no dia 2 de maio, \u00e0s 19h30 (de Bras\u00edlia), no Mangueir\u00e3o. A volta ser\u00e1 disputada no dia 22 do mesmo m\u00eas, no Morumbis, \u00e0s 21 horas.<\/p>\n\n\n\n<p>O Corinthians, finalista da competi\u00e7\u00e3o em 2022, visita o Am\u00e9rica-RN no dia 1\u00ba de maio, \u00e0s 20 horas, na Arena das Dunas. O confronto ser\u00e1 decidido em 21 do mesmo m\u00eas, no mesmo hor\u00e1rio, na Neo Qu\u00edmica Arena.<\/p>\n\n\n\n<p>Campe\u00e3o da Copa do Brasil pela \u00faltima vez em 2020, o Palmeiras recebe o Botafogo-SP no Allianz Parque no dia 2, \u00e0s 21h30. J\u00e1 a volta est\u00e1 marcada para o dia 23, no Est\u00e1dio Santa Cruz, \u00e0s 19 horas.<\/p>\n\n\n\n<p>A CBF estipula que as finais da copa nacional ser\u00e3o disputadas nos finais de semana dos dias 3 e 10 de novembro. A premia\u00e7\u00e3o para o clube vencedor da competi\u00e7\u00e3o ser\u00e1 de R$ 73,5 milh\u00f5es.<\/p>\n\n\n\n<p>Veja detalhes dos jogos da terceira fase da Copa do Brasil:<\/p>\n\n\n\n<p><strong>Jogos de ida<\/strong><br><br>30\/04, 19h: Bahia x Crici\u00fama (Arena Fonte Nova)<br>30\/04, 20h: Oper\u00e1rio-PR x Gr\u00eamio (German Kruger)<br>30\/04, 21h30: Atl\u00e9tico-MG x Sport (Arena MRV)<br>01\/05, 16h: Sampaio Corr\u00eaa x Fluminense (Kleber Andrade)<br>01\/05, 16h: Brusque x Atl\u00e9tico-GO (Arena Joinville)<br>01\/05, 18h: Sousa-PB x Red Bull Bragantino (Mariz\u00e3o)<br>01\/05, 18h: Ypiranga x Athletico (Colosso da Lagoa)<br>01\/05, 19h: Fortaleza x Vasco (Arena Castel\u00e3o)<br>01\/05, 20h: Am\u00e9rica-RN x Corinthians (Arena das Dunas)<br>01\/05, 21h30: Flamengo x Amazonas (Maracan\u00e3)<br>01\/05, 21h30: Internacional x Juventude (Beira-Rio)<br>02\/05, 19h: Botafogo x Vit\u00f3ria (Est\u00e1dio Nilton Santos)<br>02\/05, 19h30: \u00c1guia de Marab\u00e1-PA x S\u00e3o Paulo (Mangueir\u00e3o)<br>02\/05, 20h30: CRB x Cear\u00e1 (Rei Pel\u00e9)<br>02\/05, 21h30: Goi\u00e1s x Cuiab\u00e1 (Serrinha)<br>02\/05, 21h30: Palmeiras x Botafogo-SP (Allianz Parque)<\/p>\n\n\n\n<p><strong>Jogos de volta<\/strong><br><br>21\/05, 19h: Vit\u00f3ria x Botafogo (Barrad\u00e3o)<br>21\/05, 20h: Corinthians x Am\u00e9rica-RN (Neo Qu\u00edmica Arena)<br>21\/05, 21h30: Vasco x Fortaleza (S\u00e3o Janu\u00e1rio)<br>22\/05, 18h30: Bragantino x Sousa-PB (Nabi Abi Chedid)<br>22\/05, 19h: Fluminense x Sampaio Corr\u00eaa (Fluminense)<br>22\/05, 19h: Atl\u00e9tico-GO x Brusque (Ant\u00f4nio Accioly)<br>22\/05, 19h: Sport x Atl\u00e9tico-MG (Arena Pernambuco)<br>22\/05, 19h30: Gr\u00eamio x Oper\u00e1rio-PR (Arena do Gr\u00eamio)<br>22\/05, 20h: Athletico x Ypiranga (Ligga Arena)<br>22\/05, 21h: S\u00e3o Paulo x \u00c1guia de Marab\u00e1-PA (Morumbis)<br>22\/05, 21h30: Amazonas x Flamengo (Arena da Amaz\u00f4nia)<br>22\/05, 21h30: Juventude x Internacional (Alfredo Jaconi)<br>23\/05, 19h: Crici\u00fama x Bahia (Heriberto Hulse)<br>23\/05, 19h: Botafogo-SP x Palmeiras (Santa Cruz)<br>23\/05, 21h30: Cear\u00e1 x CRB (Arena Castel\u00e3o)<br>23\/05, 21h30: Cuiab\u00e1 x Goi\u00e1s (Arena Pantanal)<\/p>\n\n\n\n<p><strong><em>A<strong><em>companhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/em><\/strong>,\u00a0<strong><em><strong><em>\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e<\/em><\/strong><\/em><\/strong>\u00a0<strong><em>no<\/em>\u00a0<em><a href=\"https:\/\/twitter.com\/Senoticias\">X<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: CBF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CBF (Confedera\u00e7\u00e3o Brasileira de Futebol) divulgou na noite desta segunda-feira a tabela detalhada da terceira fase da Copa Brasil. Os jogos v\u00e3o do dia 30 de abril at\u00e9 23 de maio. O S\u00e3o Paulo, atuou campe\u00e3o da competi\u00e7\u00e3o, vai encarar o \u00c1guia de Marab\u00e1 no dia 2 de maio, \u00e0s 19h30 (de Bras\u00edlia), no [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,26,1],"tags":[5947,5399,41479],"class_list":{"0":"post-142058","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-esportes","8":"category-sem-categoria","9":"tag-cbf","10":"tag-copa-do-brasil","11":"tag-terceira-fase"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/142058"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=142058"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/142058\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=142058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=142058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=142058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}