{"id":141869,"date":"2024-04-10T09:58:12","date_gmt":"2024-04-10T12:58:12","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=141869"},"modified":"2024-04-10T09:58:23","modified_gmt":"2024-04-10T12:58:23","slug":"operacao-fenix-investigado-por-crimes-em-se-que-fez-cirurgias-plasticas-para-nao-ser-reconhecido-e-preso-em-sp","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/operacao-fenix-investigado-por-crimes-em-se-que-fez-cirurgias-plasticas-para-nao-ser-reconhecido-e-preso-em-sp\/","title":{"rendered":"Opera\u00e7\u00e3o F\u00eanix: Investigado por crimes em SE que fez cirurgias pl\u00e1sticas para n\u00e3o ser reconhecido \u00e9 preso em SP"},"content":{"rendered":"\n<p>Em desdobramento da Opera\u00e7\u00e3o F\u00eanix, deflagrada em Sergipe, um investigado por diversos crimes envolvendo roubo de carga, tr\u00e1fico de drogas e falsidade ideol\u00f3gica foi preso ap\u00f3s passar por procedimentos est\u00e9ticos para mudar a apar\u00eancia f\u00edsica do rosto em S\u00e3o Paulo. A pris\u00e3o foi poss\u00edvel ap\u00f3s troca de informa\u00e7\u00f5es entre a Divis\u00e3o de Intelig\u00eancia (Dipol) de Sergipe e a Pol\u00edcia Civil de S\u00e3o Paulo. A a\u00e7\u00e3o policial, que aconteceu em Itaquaquecetuba, na Grande S\u00e3o Paulo, foi divulgada nesta quarta-feira, 10.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2024\/04\/cope-senoticias-1024x682.jpg\" alt=\"\" class=\"wp-image-141870\"\/><figcaption>Ele \u00e9 investigado por crimes de roubo de carga, tr\u00e1fico de drogas e falsidade ideol\u00f3gica em ao menos tr\u00eas estados<\/figcaption><\/figure>\n\n\n\n<p>De acordo com a delegada Mayra Moinhos, diretora da Dipol, a pris\u00e3o do investigado \u00e9 decorrente da Opera\u00e7\u00e3o F\u00eanix, que aconteceu em 2018. \u201cIniciamos em 2016 a coleta de algumas identidades que tinha autenticidade duvidosa e chegamos ao investigado. Ele tinha sido preso transportando drogas com uma identidade falsa da Bahia. A pris\u00e3o havia sido feita pela Pol\u00edcia Federal\u201d, detalhou.<\/p>\n\n\n\n<p>Naquela \u00e9poca, ele estava preso no sistema penitenci\u00e1rio de Sergipe quando progrediu para o uso de tornozeleira eletr\u00f4nica. \u201cEle rompeu a tornozeleira e conseguiu tirar um novo documento de identidade em Sergipe, com um terceiro nome. Com as identidades, ele passou a se esquivar das pol\u00edcias de Sergipe, Bahia e S\u00e3o Paulo\u201d, complementou a delegada que atua como diretora da Dipol.<\/p>\n\n\n\n<p>Em 2021, a Dipol, junto ao N\u00facleo de Intelig\u00eancia e Apoio \u00e0 Atividade Policial, constatou de forma pericial que as identidades eram da mesma pessoa, ou seja do investigado. \u201cE continuamos a troca de informa\u00e7\u00f5es com as pol\u00edcias Civil e Militar de S\u00e3o Paulo para que nos ajudasse com a pris\u00e3o do investigado, pois sab\u00edamos que ele \u00e9 do estado de S\u00e3o Paulo\u201d, acrescentou Mayra Moinhos.<\/p>\n\n\n\n<p>J\u00e1 em 2024, com o trabalho do Deic de S\u00e3o Paulo, a pris\u00e3o do investigado foi viabilizada, conforme explicou a diretora da Dipol. \u201c\u00c9 interessante destacar que, quando foi preso, ele se utilizava de uma t\u00e9cnica muito conhecida pelos criminosos procurados pela pol\u00edcia, que \u00e9 a altera\u00e7\u00e3o das caracter\u00edsticas faciais. No entanto, as caracter\u00edsticas b\u00e1sicas permanecem, e a papiloscopia demonstrou que se tratava do investigado\u201d, revelou.<\/p>\n\n\n\n<p><strong>Crimes do investigado<\/strong><\/p>\n\n\n\n<p>Conforme Mayra Moinhos, o investigado veio foragido de S\u00e3o Paulo pelo crime de associa\u00e7\u00e3o criminosa de roubo de carga. Ao migrar para a regi\u00e3o Nordeste, ele se envolveu com o tr\u00e1fico de drogas, sendo preso em Sergipe por tr\u00e1fico de entorpecentes, quando apresentou documento falso emitido na Bahia. \u201cAl\u00e9m de responder pelo crime origin\u00e1rio em S\u00e3o Paulo, ele vai responder por tr\u00e1fico e falsidade ideol\u00f3gica\u201d, detalhou.<\/p>\n\n\n\n<p><strong>Fugitivo da Opera\u00e7\u00e3o F\u00eanix<\/strong><\/p>\n\n\n\n<p>Durante a investiga\u00e7\u00e3o que resultou na Opera\u00e7\u00e3o F\u00eanix, todos os investigados que se utilizaram de documentos falsos e tiveram a real identidade reveladas foram indiciados. \u201cNa \u00e9poca, n\u00f3s n\u00e3o conseguimos identificar que ele era aquele investigado. Mas hoje n\u00f3s sabemos que ele \u00e9 a mesma pessoa, e essa informa\u00e7\u00e3o ser\u00e1 agregada ao processo\u201d, destacou a delegada diretora da Dipol.<\/p>\n\n\n\n<p>Embora esse investigado tenha sido efetivamente identificado e agora estando preso tamb\u00e9m no \u00e2mbito da Opera\u00e7\u00e3o F\u00eanix, as investiga\u00e7\u00f5es prosseguem para chegar a outros envolvidos nos crimes apurados por Sergipe. \u201cAgora, o preso em S\u00e3o Paulo permanecer\u00e1 naquele estado, j\u00e1 que h\u00e1 processos contra ele tamb\u00e9m no estado da regi\u00e3o Sudeste do pa\u00eds\u201d, pontuou Mayra Moinhos.<\/p>\n\n\n\n<p><strong><em><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/em><\/strong>,\u00a0<strong><em><strong><em>\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e<\/em><\/strong><\/em><\/strong>\u00a0<strong><em>no<\/em>\u00a0<em><a href=\"https:\/\/twitter.com\/Senoticias\">X<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: SSP SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em desdobramento da Opera\u00e7\u00e3o F\u00eanix, deflagrada em Sergipe, um investigado por diversos crimes envolvendo roubo de carga, tr\u00e1fico de drogas e falsidade ideol\u00f3gica foi preso ap\u00f3s passar por procedimentos est\u00e9ticos para mudar a apar\u00eancia f\u00edsica do rosto em S\u00e3o Paulo. A pris\u00e3o foi poss\u00edvel ap\u00f3s troca de informa\u00e7\u00f5es entre a Divis\u00e3o de Intelig\u00eancia (Dipol) de [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,7],"tags":[41413,5726,41412],"class_list":{"0":"post-141869","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-policia","8":"tag-cirurgias-plasticas","9":"tag-dipol","10":"tag-operacao-fenix-2"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/141869"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=141869"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/141869\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=141869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=141869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=141869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}