{"id":139258,"date":"2023-10-03T17:36:05","date_gmt":"2023-10-03T20:36:05","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=139258"},"modified":"2023-10-03T17:50:25","modified_gmt":"2023-10-03T20:50:25","slug":"139258-2","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/139258-2\/","title":{"rendered":"Ciganos sequestrados em Boquim s\u00e3o resgatados pelo Cope; dois suspeitos morreram em confronto"},"content":{"rendered":"\n<p>O Centro de Opera\u00e7\u00f5es Policiais Especiais (Cope), com apoio da Delegacia Regional de Est\u00e2ncia e da Divis\u00e3o de Intelig\u00eancia e Planejamento Policial (Dipol), localizou na tarde desta ter\u00e7a-feira, 3, um cativeiro no Povoado Terra Ca\u00edda, munic\u00edpio de Indiaroba, e libertou dois ciganos, ref\u00e9ns de uma extors\u00e3o mediante sequestro, iniciada na noite dessa segunda-feira, em Boquim.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"410\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/10\/Cope-SE-Noticias.jpg\" alt=\"\" class=\"wp-image-139260\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/10\/Cope-SE-Noticias.jpg 591w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/10\/Cope-SE-Noticias-300x208.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><figcaption>Segundo os policiais do Cope, os homens foram localizados no povoado Terra Ca\u00edda, munic\u00edpio de Indiaroba &#8211; Foto: arquivo\/SSP\/SE<\/figcaption><\/figure>\n\n\n\n<p>Durante a abordagem, os sequestradores, identificados como Odenilton de Santana e Reginaldo da Silva Santana, reagiram \u00e0 chegada dos policiais e, meio ao confronto, acabaram atingidos. Apesar do socorro imediato, a dupla, que \u00e9 do estado da Bahia, evoluiu a \u00f3bito ap\u00f3s entrada no Hospital de Est\u00e2ncia.<\/p>\n\n\n\n<p>Al\u00e9m deles, dois outros homens estavam no local e foram presos por envolvimento no crime e levados ao Cope. Outras pessoas ainda est\u00e3o sendo investigadas de participa\u00e7\u00e3o no caso.<\/p>\n\n\n\n<p>O grupo criminoso j\u00e1 vinha sendo investigado pela Pol\u00edcia Civil sergipana por outra extors\u00e3o mediante sequestro ocorrida no dia 18 de agosto deste ano, no munic\u00edpio de Est\u00e2ncia. Na ocasi\u00e3o, a v\u00edtima foi libertada em circunst\u00e2ncias ainda investigadas pela pol\u00edcia.<\/p>\n\n\n\n<p>Em raz\u00e3o do primeiro crime ocorrido, na opera\u00e7\u00e3o de hoje foram cumpridos mandados de pris\u00e3o contra os dois homens conduzidos ao Cope, bem como quatro mandados de busca domiciliar deferidos pelo Ju\u00edzo de Direito de Est\u00e2ncia.<\/p>\n\n\n\n<p>As investiga\u00e7\u00f5es continuam e novas medidas cautelares ser\u00e3o pleiteadas ao Poder Judici\u00e1rio. As v\u00edtimas foram libertadas ilesas em menos de 24 horas ap\u00f3s o in\u00edcio do sequestro.<\/p>\n\n\n\n<p>Com os investigados, foram apreendidas duas pistolas calibre .380, um rev\u00f3lver calibre .38, al\u00e9m de uma espingarda calibre 12 e um simulacro de fuzil do tipo airsoft. Estas armas foram apreendidas e ser\u00e3o anexadas ao inqu\u00e9rito policial.<\/p>\n\n\n\n<p><strong>Entenda o caso<\/strong><\/p>\n\n\n\n<p>O crime foi iniciado na noite dessa segunda-feira, 2, quando quatro homens se passaram por policiais e abordaram as v\u00edtimas na cidade de Boquim. A partir da\u00ed, elas foram colocadas em um carro roubado, com placas clonadas, tendo dinheiro e joias extorquidos e sendo levadas a um cativeiro em Indiaroba, at\u00e9 serem localizadas hoje.<\/p>\n\n\n\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: ascom\/SSP\/SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro de Opera\u00e7\u00f5es Policiais Especiais (Cope), com apoio da Delegacia Regional de Est\u00e2ncia e da Divis\u00e3o de Intelig\u00eancia e Planejamento Policial (Dipol), localizou na tarde desta ter\u00e7a-feira, 3, um cativeiro no Povoado Terra Ca\u00edda, munic\u00edpio de Indiaroba, e libertou dois ciganos, ref\u00e9ns de uma extors\u00e3o mediante sequestro, iniciada na noite dessa segunda-feira, em Boquim. [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,2961,1],"tags":[3196,40144,612,8218,40145],"class_list":{"0":"post-139258","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-nacional","8":"category-sem-categoria","9":"tag-boquim","10":"tag-ciganos-sequestrados","11":"tag-cope","12":"tag-dois-mortos","13":"tag-povoado-terra-caida"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/139258"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=139258"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/139258\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=139258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=139258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=139258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}