{"id":138769,"date":"2023-08-29T09:58:36","date_gmt":"2023-08-29T12:58:36","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=138769"},"modified":"2023-08-29T09:58:49","modified_gmt":"2023-08-29T12:58:49","slug":"em-itaporanga-deputado-georgeo-mostra-que-primeira-obra-anunciada-por-mitidieri-ainda-nao-comecou","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/em-itaporanga-deputado-georgeo-mostra-que-primeira-obra-anunciada-por-mitidieri-ainda-nao-comecou\/","title":{"rendered":"Em Itaporanga, deputado Georgeo mostra que primeira obra anunciada por Mitidieri ainda n\u00e3o come\u00e7ou"},"content":{"rendered":"\n<p>No dia 10 de fevereiro, o rec\u00e9m-empossado governador F\u00e1bio Mitidieri assinou aquela que seria a primeira ordem de servi\u00e7o de sua gest\u00e3o: a obra de pavimenta\u00e7\u00e3o no trecho do Km 16 da Rodovia SE 270, que d\u00e1 acesso ao Povoado Costa, em Itaporanga. No entanto, de l\u00e1 para c\u00e1, pouco mudou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"422\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-29-at-09.12.38.jpeg\" alt=\"\" class=\"wp-image-138770\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-29-at-09.12.38.jpeg 563w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-29-at-09.12.38-300x225.jpeg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-29-at-09.12.38-45x35.jpeg 45w\" sizes=\"(max-width: 563px) 100vw, 563px\" \/><figcaption>Deputado mostra que primeira obra anunciada por Mitidieri ainda n\u00e3o come\u00e7ou &#8211; Foto: ascom<\/figcaption><\/figure>\n\n\n\n<p>O deputado estadual Georgeo Passos (Cidadania) esteve na rodovia nesta segunda-feira, 28, e constatou que a obra n\u00e3o foi iniciada at\u00e9 agora. O parlamentar criticou o fato, lamentando: &#8220;J\u00e1 estamos no final de agosto, mas o povo continua na poeira e na lama.&#8221;<\/p>\n\n\n\n<p>A ordem de servi\u00e7o assinada teve um investimento de R$ 10.486.000,00. O ato, acompanhado com pompa por diversas autoridades, ocorreu apenas 40 dias ap\u00f3s o in\u00edcio do governo de F\u00e1bio Mitidieri. Para Georgeo, justamente por ser a primeira, a obra deveria receber mais cuidado.<\/p>\n\n\n\n<p>&#8220;Isso \u00e9 o que nos chama a aten\u00e7\u00e3o. A ordem de servi\u00e7o foi dada, mas tudo ficou na promessa. Se uma obra como essa, com t\u00e3o poucos quil\u00f4metros, n\u00e3o p\u00f4de ser pavimentada, o que esperar da constru\u00e7\u00e3o de uma ponte, como a que o governador anunciou recentemente?&#8221;, concluiu Georgeo.<\/p>\n\n\n\n<p><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/strong><\/em><\/p>\n\n\n\n<p>Fonte: ascom\/parlamentar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 10 de fevereiro, o rec\u00e9m-empossado governador F\u00e1bio Mitidieri assinou aquela que seria a primeira ordem de servi\u00e7o de sua gest\u00e3o: a obra de pavimenta\u00e7\u00e3o no trecho do Km 16 da Rodovia SE 270, que d\u00e1 acesso ao Povoado Costa, em Itaporanga. No entanto, de l\u00e1 para c\u00e1, pouco mudou. O deputado estadual Georgeo [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[17066,39853],"class_list":{"0":"post-138769","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-politica","8":"tag-deputado-georgeo-passos","9":"tag-povoado-costa"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/138769"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=138769"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/138769\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=138769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=138769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=138769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}