{"id":132855,"date":"2022-06-02T13:25:27","date_gmt":"2022-06-02T16:25:27","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=132855"},"modified":"2022-06-02T13:34:05","modified_gmt":"2022-06-02T16:34:05","slug":"projeto-do-governo-para-suspensao-da-contribuicao-extraordinario-para-inativos-e-aprovado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/projeto-do-governo-para-suspensao-da-contribuicao-extraordinario-para-inativos-e-aprovado\/","title":{"rendered":"Projeto do Governo para suspens\u00e3o da contribui\u00e7\u00e3o extraordin\u00e1rio para inativos \u00e9 aprovado"},"content":{"rendered":"\n<p>O Projeto de Lei Complementar de n\u00ba 14\/2022, encaminhado pelo governador Belivaldo Chagas no m\u00eas passado, que retira a contribui\u00e7\u00e3o previdenci\u00e1ria de 14% para aposentados e pensionistas do estado, foi aprovado na tarde desta quarta-feira, 1\u00ba de junho, na Assembleia Legislativa do Estado de Sergipe (Alese). A decis\u00e3o j\u00e1 ter\u00e1 efeitos a partir de 1\u00ba de julho.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"544\" height=\"239\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Belivaldo-Chagas-SE-Noticias.jpeg\" alt=\"\" class=\"wp-image-131596\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Belivaldo-Chagas-SE-Noticias.jpeg 544w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Belivaldo-Chagas-SE-Noticias-300x132.jpeg 300w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/><figcaption>A vota\u00e7\u00e3o do Projeto de Lei Complementar, do Poder Executivo, que revoga artigos de outra lei que disp\u00f5e sobre o regime pr\u00f3prio de previd\u00eancia social do Estado de Sergipe, abrangendo os servidores p\u00fablicos da administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional &#8211; Foto: arquivo\/ASN<\/figcaption><\/figure>\n\n\n\n<p>A partir de uma gest\u00e3o eficiente e planejada, o Governo do Estado conseguiu antecipar o prazo de encerramento da contribui\u00e7\u00e3o, anteriormente previsto para dezembro, e manter o equil\u00edbrio nas contas, possibilitando, assim, a apresenta\u00e7\u00e3o do Projeto de Lei para revoga\u00e7\u00e3o do par\u00e1grafo 2\u00ba e 3\u00ba, al\u00e9m do artigo 94 da Lei Complementar n\u00ba 113 de 1\u00ba de novembro de 2005, que disp\u00f5e sobre o Regime Pr\u00f3prio de Previd\u00eancia Social do Estado de Sergipe (RPPS\/SE)&nbsp;<\/p>\n\n\n\n<p>Com o fim da contribui\u00e7\u00e3o previdenci\u00e1ria extraordin\u00e1ria em rela\u00e7\u00e3o aos valores recebidos at\u00e9 o teto do Regime Geral de Previd\u00eancia Social (RGPS), hoje fixado em R$ 7.087,22, ser\u00e3o beneficiadas 29.963 pessoas. A extin\u00e7\u00e3o da contribui\u00e7\u00e3o previdenci\u00e1ria ter\u00e1 impacto de R$ 84 milh\u00f5es para o Estado at\u00e9 o final de 2022, conforme c\u00e1lculos do SergipePrevid\u00eancia e da Secretaria da Fazenda (Sefaz).<\/p>\n\n\n\n<p>\u201cA respeito desse quantitativo total de beneficiados, merece destaque ainda o fato de que 24.750 inativos e pensionistas civis est\u00e3o completamente isentos, tendo em vista que seus proventos est\u00e3o abaixo do referido teto do RGPS\u201d, afirma a mensagem encaminhada \u00e0 Alese pelo Executivo estadual<\/p>\n\n\n\n<p><strong>Isen\u00e7\u00e3o<\/strong>&nbsp;<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.se.gov.br\/noticias\/governo\/isencao_da_contribuicao_previdenciaria_para_inativos_do_estado_que_ganham_ate_dois_salarios_minimos_e_aprovada\" target=\"_blank\">Em mar\u00e7o<\/a>, a partir da Lei Complementar N\u00ba 368, com efeitos a partir de maio de 2022, o Estado j\u00e1 tinha autorizado que a contribui\u00e7\u00e3o ordin\u00e1ria dos aposentados e pensionistas do Regime Pr\u00f3prio de Previd\u00eancia Social do Estado de Sergipe (RPPS\/SE) passasse a incidir apenas sobre o valor dos proventos que superassem dois sal\u00e1rios-m\u00ednimos.\u00a0<\/p>\n\n\n\n<p><em>Quer receber as principais not\u00edcias do\u00a0<strong>SE Not\u00edcias<\/strong>\u00a0no seu\u00a0<strong>WhatsApp?<\/strong>\u00a0<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Sergipe de Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto de Lei Complementar de n\u00ba 14\/2022, encaminhado pelo governador Belivaldo Chagas no m\u00eas passado, que retira a contribui\u00e7\u00e3o previdenci\u00e1ria de 14% para aposentados e pensionistas do estado, foi aprovado na tarde desta quarta-feira, 1\u00ba de junho, na Assembleia Legislativa do Estado de Sergipe (Alese). A decis\u00e3o j\u00e1 ter\u00e1 efeitos a partir de 1\u00ba [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6,1],"tags":[2806,36681,36682],"class_list":{"0":"post-132855","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-politica","8":"category-sem-categoria","9":"tag-belivaldo-chagas","10":"tag-revogacao-de-lei","11":"tag-suspensao-da-contribuicao"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/132855"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=132855"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/132855\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=132855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=132855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=132855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}