{"id":131521,"date":"2022-02-03T19:36:19","date_gmt":"2022-02-03T22:36:19","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=131521"},"modified":"2022-02-03T20:09:41","modified_gmt":"2022-02-03T23:09:41","slug":"secretaria-de-estado-da-saude-recebeu-nova-remessa-de-imunizantes-da-janssen","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/secretaria-de-estado-da-saude-recebeu-nova-remessa-de-imunizantes-da-janssen\/","title":{"rendered":"Secretaria de Estado da Sa\u00fade recebeu nova remessa de imunizantes da Janssen"},"content":{"rendered":"\n<p>A Secretaria de Estado da Sa\u00fade (SES) recebeu nesta quinta-feira, 03, novo lote contendo 38.700 vacinas da Janssen que ser\u00e3o destinados para aplica\u00e7\u00e3o de doses de refor\u00e7o na popula\u00e7\u00e3o. Os imunobiol\u00f3gicos chegaram ao aeroporto de Aracaju por volta das 14h40.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"416\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Jansen-SE-Noticias.jpeg\" alt=\"\" class=\"wp-image-131522\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Jansen-SE-Noticias.jpeg 589w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2022\/02\/Jansen-SE-Noticias-300x212.jpeg 300w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><figcaption>Estado de Sergipe <strong>recebe nova remessa de imunizantes da Janssen<\/strong> &#8211; Foto: SES<br><br><\/figcaption><\/figure>\n\n\n\n<p>Essa \u00e9 a quarta remessa que a SES recebeu do Minist\u00e9rio da Sa\u00fade esta semana, na ter\u00e7a-feira foram 60.560 doses do imunizante da Coronavac e na quarta-feira, 36.250 doses da Astrazeneca e 20.700 doses da Pfizer pedi\u00e1trica, destinadas \u00e0 imuniza\u00e7\u00e3o de crian\u00e7as.. O quantitativo de doses recebidas do Governo Federal chega \u00e0 marca de 4.381.375, a SES j\u00e1 enviou aos munic\u00edpios 4.172.295 doses, foram aplicadas como primeira dose 1.798.743, como segunda dose 1.571.328; como dose \u00fanica 40.125 e 466.156 como dose de refor\u00e7o.<\/p>\n\n\n\n<p><em><strong>Quer receber as principais not\u00edcias do<\/strong>\u00a0<strong>SE Not\u00edcias<\/strong>\u00a0<strong>no seu<\/strong>\u00a0<strong>WhatsApp?<\/strong>\u00a0<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p>Fonte Secretaria de Estado da Sa\u00fade<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Sa\u00fade (SES) recebeu nesta quinta-feira, 03, novo lote contendo 38.700 vacinas da Janssen que ser\u00e3o destinados para aplica\u00e7\u00e3o de doses de refor\u00e7o na popula\u00e7\u00e3o. Os imunobiol\u00f3gicos chegaram ao aeroporto de Aracaju por volta das 14h40. Essa \u00e9 a quarta remessa que a SES recebeu do Minist\u00e9rio da Sa\u00fade esta semana, [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6,1],"tags":[14279,555,34457],"class_list":{"0":"post-131521","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-politica","8":"category-sem-categoria","9":"tag-covid19","10":"tag-estado-de-sergipe","11":"tag-vacina-janssen"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/131521"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=131521"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/131521\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=131521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=131521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=131521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}