{"id":130781,"date":"2021-12-08T08:22:48","date_gmt":"2021-12-08T11:22:48","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=130781"},"modified":"2021-12-08T08:42:26","modified_gmt":"2021-12-08T11:42:26","slug":"franca-vive-5a-onda-do-coronavirus-com-quase-60-mil-novos-casos-por-dia","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/franca-vive-5a-onda-do-coronavirus-com-quase-60-mil-novos-casos-por-dia\/","title":{"rendered":"Fran\u00e7a vive 5\u00aa onda do coronav\u00edrus, com quase 60 mil novos casos por dia."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A Fran\u00e7a come\u00e7a a sentir os efeitos da quinta onda de cont\u00e1gio pelo coronav\u00edrus no n\u00famero de infec\u00e7\u00f5es, com <strong>60 mil novos casos nas \u00faltimas 24 horas<\/strong>, e na quantidade de pessoas internadas em unidades de terapia intensiva, com um total de 2.351, 160 a mais que ontem.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"373\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/12\/5-onda-Coronavirus-SE-Noticias.jpg\" alt=\"\" class=\"wp-image-130782\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/12\/5-onda-Coronavirus-SE-Noticias.jpg 567w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/12\/5-onda-Coronavirus-SE-Noticias-300x197.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/12\/5-onda-Coronavirus-SE-Noticias-90x60.jpg 90w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><figcaption>5\u00aa Onda do coronav\u00edrus na Fran\u00e7a se espalha &#8211; Foto: Marcelo Camargo\/Abr<\/figcaption><\/figure>\n\n\n\n<p>Os dados foram divulgados <strong>nesta ter\u00e7a-feira, 07,<\/strong> pelas autoridades sanit\u00e1rias francesas, que disseram tamb\u00e9m que o n\u00famero m\u00e9dio de casos nos \u00faltimos sete dias \u00e9 de 44.584, bem acima dos 30 mil de uma semana atr\u00e1s.<\/p>\n\n\n\n<p>A publica\u00e7\u00e3o dos n\u00fameros foi feita um dia depois que o primeiro-ministro da Fran\u00e7a, Jean Castex, ter anunciado o fechamento das casas noturnas a partir da pr\u00f3xima sexta-feira por um m\u00eas, al\u00e9m de novas restri\u00e7\u00f5es voltadas paras as festas de fim de ano.<\/p>\n\n\n\n<p>Apesar do aumento das interna\u00e7\u00f5es em UTIs, os 2.351 leitos ocupados por pacientes com Covid-19 ainda est\u00e3o longe dos 7 mil da primeira vaga no in\u00edcio de 2020.<\/p>\n\n\n\n<p>As autoridades sanit\u00e1rias tamb\u00e9m informaram que 687 mil doses de refor\u00e7o de vacinas contra o coronav\u00edrus foram aplicadas nas \u00faltimas 24 horas em um \u00fanico dia, em um pa\u00eds onde 75% da popula\u00e7\u00e3o j\u00e1 tem pelo menos duas doses.<\/p>\n\n\n\n<p><em><strong>Quer receber as principais not\u00edcias do<\/strong>&nbsp;<strong>SE Not\u00edcias<\/strong>&nbsp;<strong>no seu<\/strong>&nbsp;<strong>WhatsApp?<\/strong>&nbsp;<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>&nbsp;e no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: <strong><a href=\"https:\/\/noticias.uol.com.br\/ultimas-noticias\/efe\/2021\/12\/08\/franca-vive-5-onda-de-contagio-por-coronavirus-com-quase-60-mil-novos-casos.htm\">UOL<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Fran\u00e7a come\u00e7a a sentir os efeitos da quinta onda de cont\u00e1gio pelo coronav\u00edrus no n\u00famero de infec\u00e7\u00f5es, com 60 mil novos casos nas \u00faltimas 24 horas, e na quantidade de pessoas internadas em unidades de terapia intensiva, com um total de 2.351, 160 a mais que ontem. Os dados foram divulgados nesta ter\u00e7a-feira, 07, [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6,1],"tags":[35502,14279,14369],"class_list":{"0":"post-130781","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-politica","8":"category-sem-categoria","9":"tag-5a-onda-do-coronavirus","10":"tag-covid19","11":"tag-pandemia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/130781"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=130781"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/130781\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=130781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=130781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=130781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}