{"id":130175,"date":"2021-10-16T07:26:52","date_gmt":"2021-10-16T10:26:52","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=130175"},"modified":"2021-10-16T07:26:56","modified_gmt":"2021-10-16T10:26:56","slug":"joao-doria-realiza-agenda-das-previas-em-sergipe-e-defende-a-pre-candidatura-de-eduardo-amorim-ao-senado","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/joao-doria-realiza-agenda-das-previas-em-sergipe-e-defende-a-pre-candidatura-de-eduardo-amorim-ao-senado\/","title":{"rendered":"Jo\u00e3o Doria realiza agenda das pr\u00e9vias em Sergipe e defende a pr\u00e9-candidatura de Eduardo Amorim ao Senado"},"content":{"rendered":"\n<p>Candidato nas pr\u00e9vias do PSDB que definir\u00e1 o nome que disputar\u00e1 a presid\u00eancia da Rep\u00fablica pelo partido em 2022, o governador de S\u00e3o Paulo, Jo\u00e3o Doria, esteve em Sergipe, nesta sexta-feira (15), para participar de um encontro com a milit\u00e2ncia e um evento com empres\u00e1rios do estado. Na oportunidade, Doria falou de sua gest\u00e3o em S\u00e3o Paulo e suas propostas para o pa\u00eds e ainda reafirmou a pr\u00e9-candidatura de Eduardo Amorim ao Senado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias.jpg\" alt=\"\" class=\"wp-image-130176\" width=\"554\" height=\"369\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias.jpg 554w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias-90x60.jpg 90w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias-180x120.jpg 180w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/10\/Joao-Dorea-em-Sergipe-SE-Noticias-95x64.jpg 95w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><figcaption>Jo\u00e3o Doria realiza agenda das pr\u00e9vias em Sergipe &#8211; Foto: ascom\/divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>\u201cO PSDB tem essa caracter\u00edstica democr\u00e1tica e valorosa de respeitar a decis\u00e3o dos seus filiados e este ano realiza as pr\u00e9vias para a escolha do pr\u00e9-candidato a presidente no que considero a melhor via. Sou um grande defensor das pr\u00e9vias pela sua democracia, capilaridade e pela oportunidade de trazermos dentro do que a Lei estabelece as propostas do PSDB para o Brasil em uma poss\u00edvel presid\u00eancia da Rep\u00fablica\u201d, afirmou o governador.<\/p>\n\n\n\n<p>Jo\u00e3o Doria agradeceu a receptividade em Sergipe e defendeu a pr\u00e9-candidatura do presidente do PSDB Sergipe, Eduardo Amorim, ao Senado Federal. \u201cFiz quest\u00e3o de vir a Sergipe pelo respeito ao estado e \u00e0s lideran\u00e7as do partido, al\u00e9m de manter esse di\u00e1logo. Espero que Eduardo Amorim, que tem constru\u00eddo uma linda biografia ao longo de anos a frente do PSDB, possa voltar ao Senado, onde ele faz falta. Se eu pudesse votar aqui, meu candidato ao Senado seria Eduardo Amorim\u201d, enfatizou.<\/p>\n\n\n\n<p>O presidente do PSDB Sergipe, o m\u00e9dico e ex-senador Eduardo Amorim, destacou o exemplo de democracia dado pelo partido, agradeceu a visita de Doria ao estado e disse que o Diret\u00f3rio est\u00e1 aberto para receber a todos. \u201cFicamos felizes em receber o governador Doria, que incluiu Sergipe em sua agenda de visitas aos estados neste per\u00edodo de pr\u00e9vias partid\u00e1ria\u201d, ressaltou.<\/p>\n\n\n\n<p>\u201cE estamos abertos para receber e dialogar com os outros dois candidatos, o governador Eduardo Leite e o ex-senador Arthur Virg\u00edlio. O PSDB refor\u00e7a o compromisso com o Brasil ao apresentar, por meio deste dispositivo, bons quadros para uma pr\u00e9-candidatura a Presidente da Rep\u00fablica\u201d, complementou Eduardo Amorim.<\/p>\n\n\n\n<p><em><strong>Quer receber as principais not\u00edcias do<\/strong>&nbsp;<strong>SE Not\u00edcias<\/strong>&nbsp;<strong>no seu<\/strong>&nbsp;<strong>WhatsApp?<\/strong>&nbsp;<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n\n\n\n<p>Fonte: ascom \/ Jo\u00e3o Doria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Candidato nas pr\u00e9vias do PSDB que definir\u00e1 o nome que disputar\u00e1 a presid\u00eancia da Rep\u00fablica pelo partido em 2022, o governador de S\u00e3o Paulo, Jo\u00e3o Doria, esteve em Sergipe, nesta sexta-feira (15), para participar de um encontro com a milit\u00e2ncia e um evento com empres\u00e1rios do estado. Na oportunidade, Doria falou de sua gest\u00e3o em [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,2961],"tags":[696,35140,35141,5523,35139,35138],"class_list":{"0":"post-130175","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-nacional","8":"tag-eduardo-amorim","9":"tag-eduardo-amorim-ao-senado","10":"tag-governador-de-sao-paulo","11":"tag-joao-doria","12":"tag-pre-candidatura-de-eduardo-amorim","13":"tag-previas-eleicoes-2022"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/130175"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=130175"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/130175\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=130175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=130175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=130175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}