{"id":128022,"date":"2021-05-14T20:42:34","date_gmt":"2021-05-14T23:42:34","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=128022"},"modified":"2021-05-14T20:51:17","modified_gmt":"2021-05-14T23:51:17","slug":"sergipe-e-lagarto-se-enfrentam-no-batistao-com-direito-ao-var","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/sergipe-e-lagarto-se-enfrentam-no-batistao-com-direito-ao-var\/","title":{"rendered":"Sergipe e Lagarto fazem o primeiro jogo da final do Sergip\u00e3o 2021"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A final do Campeonato Sergipano 2021 se aproxima e o primeiro jogo, que promete ser emocionante, acontecer\u00e1 neste s\u00e1bado (15), quando o Sergipe e Lagarto disputam o titulo estadual numa final para muitos inesperada, o Lagarto tem a melhor campanha, e por isso chega \u00e0 decis\u00e3o com a vantagem do empate.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"304\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/05\/lagarto-x-sergipe-3.jpg\" alt=\"\" class=\"wp-image-128023\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/05\/lagarto-x-sergipe-3.jpg 540w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2021\/05\/lagarto-x-sergipe-3-300x169.jpg 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><figcaption>Sergipe e Lagarto se enfrentam no Batist\u00e3o com direito ao VAR &#8211; Foto: arquivo\/GE\/SE<\/figcaption><\/figure>\n\n\n\n<p>Sergipe precisa tirar a vantagem do Lagarto que joga por dois empates, e como o primeiro jogo \u00e9 no Batist\u00e3o, o time da Capital espera reverter essa vantagem para a partida final que ser\u00e1 no interior, em Lagarto.<\/p>\n\n\n\n<p>A disputa \u00e9 tamb\u00e9m um duelo entre dois t\u00e9cnicos campe\u00f5es, no comando do Sergipe, Elias Borges, que ganhou o t\u00edtulo em 2018, com o pr\u00f3prio Sergipe, j\u00e1 o t\u00e9cnico Betinho, do Lagarto espera conquistar o quarto t\u00edtulo estadual. Ele foi Bicampe\u00e3o com o Confian\u00e7a e tamb\u00e9m ganhou t\u00edtulo com o Freipaulistano.<\/p>\n\n\n\n<p><strong>Novidade com o VAR<\/strong><\/p>\n\n\n\n<p>Um das grandes novidades dessa decis\u00e3o, ser\u00e1 o uso da tecnologia do VAR, que \u00e9 \u00e1rbitro assistente de v\u00eddeo para auxiliar a arbitragem. O recurso ser\u00e1 usado pela primeira vez no futebol sergipano, em parceria da Federa\u00e7\u00e3o Sergipana de Futebol com A CBF. O jogo ser\u00e1 comandando por uma mulher, a \u00e1rbitra ser\u00e1 Tayslane de Melo Costha, sergipana de Propri\u00e1 que faz parte do quadro da FIFA.<\/p>\n\n\n\n<p>A TV Atalaia, emissora oficial do Sergip\u00e3o vai transmitir todos os detalhes a partir das 16h deste s\u00e1bado (15) e o torcedor poder\u00e1 acompanhar todos os detalhes tamb\u00e9m pelo Youtube da emissora e Facebook do Portal A8SE.<\/p>\n\n\n\n<p><em>Quer receber as principais not\u00edcias do&nbsp;<strong>SE Not\u00edcias<\/strong>&nbsp;no seu&nbsp;<strong>WhatsApp?<\/strong>&nbsp;<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>&nbsp;e no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fonte: A8SE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A final do Campeonato Sergipano 2021 se aproxima e o primeiro jogo, que promete ser emocionante, acontecer\u00e1 neste s\u00e1bado (15), quando o Sergipe e Lagarto disputam o titulo estadual numa final para muitos inesperada, o Lagarto tem a melhor campanha, e por isso chega \u00e0 decis\u00e3o com a vantagem do empate. Sergipe precisa tirar a [&hellip;]<\/p>\n","protected":false},"author":6552,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,26],"tags":[34180,1638,34229],"class_list":{"0":"post-128022","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-esportes","8":"tag-campeonato-sergipano-2021","9":"tag-futebol-sergipano","10":"tag-sergipe-e-lagarto"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/128022"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6552"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=128022"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/128022\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=128022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=128022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=128022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}