{"id":126147,"date":"2020-12-31T12:08:32","date_gmt":"2020-12-31T15:08:32","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=126147"},"modified":"2020-12-31T12:08:44","modified_gmt":"2020-12-31T15:08:44","slug":"ipva-2021-para-automoveis-ficara-em-media-529-mais-barato-em-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ipva-2021-para-automoveis-ficara-em-media-529-mais-barato-em-sergipe\/","title":{"rendered":"IPVA 2021 para autom\u00f3veis ficar\u00e1, em m\u00e9dia, 5,29% mais barato em Sergipe"},"content":{"rendered":"\n<p>Em Sergipe, o Imposto Sobre a Propriedade de Ve\u00edculos Automotores (IPVA) sofrer\u00e1 redu\u00e7\u00e3o geral m\u00e9dia de 3,53% em 2021, em rela\u00e7\u00e3o a 2020. O menor \u00edndice \u00e9 incidente sobre os autom\u00f3veis, cuja redu\u00e7\u00e3o m\u00e9dia chega a 5,29%. De acordo com a Secretaria de Estado da Fazenda (Sefaz\/SE), a quantidade de ve\u00edculos tributados em 2021 \u00e9 estimada em 602.099, que dever\u00e1 adequar-se ao calend\u00e1rio de pagamento e licenciamento divulgado pelo \u00f3rg\u00e3o no final do m\u00eas de novembro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/12\/ipva-senoticias-1024x703.jpeg\" alt=\"\" class=\"wp-image-126148\"\/><figcaption>Pagamento pode ser feito em cota \u00fanica ou parcelado em at\u00e9 10 vezes\n\n<\/figcaption><\/figure>\n\n\n\n<p>O c\u00e1lculo da redu\u00e7\u00e3o m\u00e9dia \u00e9 realizado pela Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (FIPE). Para camionetas e utilit\u00e1rios, o valor da redu\u00e7\u00e3o \u00e9 de 4,42%, enquanto para \u00f4nibus e micro\u00f4nibus o tributo ser\u00e1 em m\u00e9dia 3,15% menor. Para caminh\u00f5es, a redu\u00e7\u00e3o m\u00e9dia \u00e9 de 1,61%, e para motos e similares \u00e9 de 1,97%. No caso de ve\u00edculos tipo motorhome (motor-casa), a redu\u00e7\u00e3o \u00e9 de 1,81%.<\/p>\n\n\n\n<p>O contribuinte que efetuar o pagamento em cota \u00fanica at\u00e9 26 de fevereiro de 2021 ter\u00e1 direito a desconto de 10%, desde que n\u00e3o possua d\u00e9bitos do imposto relativos a anos anteriores. Caso opte pelo parcelamento do IPVA, juntamente ao licenciamento anual do ve\u00edculo, o motorista poder\u00e1 dividir o pagamento em at\u00e9 10 vezes no cart\u00e3o de cr\u00e9dito.<\/p>\n\n\n\n<p>\u201cOferecemos diversas condi\u00e7\u00f5es para que o contribuinte possa ficar em dia com o IPVA, desde o desconto na cota \u00fanica at\u00e9 o parcelamento. \u00c9 importante ficar atento aos prazos, e, se necess\u00e1rio, consultar informa\u00e7\u00f5es junto \u00e0 equipe de atendimento da Sefaz\/SE\u201d, afirma o secret\u00e1rio de Estado da Fazenda, Marco Ant\u00f4nio Queiroz. Para informa\u00e7\u00f5es via WhatsApp, a coordenadoria de IPVA do \u00f3rg\u00e3o atende pelo n\u00famero (79) 99191 2184.<\/p>\n\n\n\n<p>Para realizar o pagamento, o contribuinte deve emitir o Documento \u00danico de Arrecada\u00e7\u00e3o (DUA) por meio do site do Departamento Estadual de Tr\u00e2nsito de Sergipe &#8211; Detran\/SE (<a href=\"http:\/\/www.detran.se.gov.br\" data-type=\"URL\" data-id=\"www.detran.se.gov.br\">www.detran.se.gov.br<\/a>) e o Documento de Arrecada\u00e7\u00e3o Estadual (DAE) pelo site da Sefaz\/SE (<a href=\"http:\/\/www.sefaz.se.gov.br\" data-type=\"URL\" data-id=\"www.sefaz.se.gov.br\">www.sefaz.se.gov.br<\/a>) ou aplicativo SEFAZ Mais F\u00e1cil. A emiss\u00e3o est\u00e1 dispon\u00edvel a partir de 1\u00ba de janeiro.<\/p>\n\n\n\n<p><em>Quer receber as principais not\u00edcias do&nbsp;<strong>SE Not\u00edcias<\/strong>&nbsp;no seu&nbsp;<strong>WhatsApp?<\/strong>&nbsp;<strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=5579991715289\">Clique aqui<\/a><\/strong>.<\/em><\/p>\n\n\n\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>&nbsp;e no&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Sergipe, o Imposto Sobre a Propriedade de Ve\u00edculos Automotores (IPVA) sofrer\u00e1 redu\u00e7\u00e3o geral m\u00e9dia de 3,53% em 2021, em rela\u00e7\u00e3o a 2020. O menor \u00edndice \u00e9 incidente sobre os autom\u00f3veis, cuja redu\u00e7\u00e3o m\u00e9dia chega a 5,29%. De acordo com a Secretaria de Estado da Fazenda (Sefaz\/SE), a quantidade de ve\u00edculos tributados em 2021 \u00e9 [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,38],"tags":[3956,16174,3118],"class_list":{"0":"post-126147","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-municipios","8":"tag-ipva","9":"tag-ipva-mais-barato-em-sergipe","10":"tag-sefaz"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/126147"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=126147"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/126147\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=126147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=126147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=126147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}