{"id":124759,"date":"2020-08-22T06:33:22","date_gmt":"2020-08-22T09:33:22","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=124759"},"modified":"2020-08-22T06:36:45","modified_gmt":"2020-08-22T09:36:45","slug":"com-reabertura-de-bares-e-restaurantes-cptran-reforca-blitze-da-lei-seca","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/com-reabertura-de-bares-e-restaurantes-cptran-reforca-blitze-da-lei-seca\/","title":{"rendered":"Com reabertura de bares e restaurantes, CPTran refor\u00e7a blitze da Lei Seca"},"content":{"rendered":"<p style=\"text-align: justify;\">Com a reabertura de bares e restaurantes, autorizada por meio de decreto governamental, na \u00faltima quarta-feira, 19, a Companhia de Policiamento de Tr\u00e2nsito (CPTran) refor\u00e7ou as blitze da Lei Seca na capital e demais cidades da Grande Aracaju. O objetivo da a\u00e7\u00e3o \u00e9 inibir a combina\u00e7\u00e3o \u00e1lcool e dire\u00e7\u00e3o para evitar acidentes no tr\u00e2nsito.<\/p>\n<div id=\"attachment_124760\" style=\"width: 609px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/08\/CPTRan-SE-Noticias-e1598088858500.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-124760\" class=\"size-full wp-image-124760\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/08\/CPTRan-SE-Noticias-e1598088858500.jpeg\" alt=\"\" width=\"599\" height=\"449\" \/><\/a><p id=\"caption-attachment-124760\" class=\"wp-caption-text\">A\u00e7\u00f5es j\u00e1 resultaram em pris\u00e3o e recolhimento de Carteira Nacional de Habilita\u00e7\u00e3o (CNH) (foto: CPTran)<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com a CPTran, j\u00e1 entre a noite dessa quinta-feira, 20, e a madrugada desta sexta-feira, 21, cinco autos de embriaguez foram feitos. Na a\u00e7\u00e3o, uma pris\u00e3o foi registrada decorrente da constata\u00e7\u00e3o de 0,65 mg\/L no teste de etil\u00f4metro. Ainda durante a blitz, foram recolhidos tr\u00eas Carteiras Nacional de Habilita\u00e7\u00e3o (CNH) e dois ve\u00edculos.<\/p>\n<p style=\"text-align: justify;\">Segundo o comandante da CPTran, capit\u00e3o Aldevan Silveira, foi montando um planejamento especial para atua\u00e7\u00e3o da companhia nesse momento de flexibiliza\u00e7\u00e3o da economia. \u201cDevido \u00e0 reabertura dos bares e restaurantes, estamos refor\u00e7ando com efetivo extraordin\u00e1rio. Ser\u00e3o convocados policiais de folga para refor\u00e7ar a Lei Seca, de quinta-feira a domingo\u201d, destacou.<\/p>\n<p style=\"text-align: justify;\">Ele explicou que no pa\u00eds n\u00e3o h\u00e1 toler\u00e2ncia para a presen\u00e7a de \u00e1lcool em condutores de ve\u00edculos. \u201cApesar do CTB delimitar que o \u00edndice deve ser de 0.0, h\u00e1 a toler\u00e2ncia pela margem do etil\u00f4metro. Ent\u00e3o, at\u00e9 0.04 o cidad\u00e3o n\u00e3o \u00e9 multado. J\u00e1 de 0.05 at\u00e9 0.33, o cidad\u00e3o \u00e9 autuado, mas n\u00e3o preso. Acima disso, passa a ser detido e levado \u00e0 delegacia\u201d, citou.<\/p>\n<p style=\"text-align: justify;\">O capit\u00e3o reiterou sobre os encaminhamentos que devem ser adotados em casos mais graves envolvendo acidentes de tr\u00e2nsito. \u201cSe, por acaso, o condutor se envolver em acidentes, atropelar, deixar les\u00f5es e at\u00e9 matar algu\u00e9m, o crime passa a ser inafian\u00e7\u00e1vel. \u00c9 um homic\u00eddio culposo, qualificado pela embriaguez, conforme o artigo 302 do CTB\u201d, frisou.<\/p>\n<p style=\"text-align: justify;\">Aldevan Silveira informou sobre a possibilidade de recusa do teste do baf\u00f4metro pelo condutor, ressaltando que, se houver provas da embriaguez ao volante, todos os procedimentos cab\u00edveis ao caso ser\u00e3o utilizados.<\/p>\n<p style=\"text-align: justify;\">\u201cO cidad\u00e3o pode sim se recusar a fazer o teste. Mas pode haver o auto de constata\u00e7\u00e3o de embriaguez, a partir da percep\u00e7\u00e3o de sintomas, como o odor, comportamento, olhos vermelhos e desequil\u00edbrio. Tamb\u00e9m podem ser utilizados \u00e1udios e v\u00eddeos na constata\u00e7\u00e3o, assim como acionadas testemunhas, que comprovem a embriaguez. Mesmo assim, se ele se recusar e n\u00e3o houver nenhum ind\u00edcio de embriaguez, ele \u00e9 autuado conforme o artigo 165-A, do C\u00f3digo de Tr\u00e2nsito Brasileiro\u201d, pontuou.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/08\/Logo-SE-Noticias-1-1-e1597675148375.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-124612\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/08\/Logo-SE-Noticias-1-1-e1597675148375.jpg\" alt=\"\" width=\"550\" height=\"72\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a><\/em><\/strong><\/p>\n<p><em>Mat\u00e9ria extra\u00edda do site da SSP\/SE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a reabertura de bares e restaurantes, autorizada por meio de decreto governamental, na \u00faltima quarta-feira, 19, a Companhia de Policiamento de Tr\u00e2nsito (CPTran) refor\u00e7ou as blitze da Lei Seca na capital e demais cidades da Grande Aracaju. O objetivo da a\u00e7\u00e3o \u00e9 inibir a combina\u00e7\u00e3o \u00e1lcool e dire\u00e7\u00e3o para evitar acidentes no tr\u00e2nsito. De [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":124760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,7,1],"tags":[15392,14609,631,86],"class_list":{"0":"post-124759","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-policia","9":"category-sem-categoria","10":"tag-blitze-da-lei-seca","11":"tag-companhia-de-policiamento-de-transito","12":"tag-cptran","13":"tag-policia-militar"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/124759"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=124759"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/124759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/124760"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=124759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=124759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=124759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}