{"id":122353,"date":"2020-03-09T07:22:59","date_gmt":"2020-03-09T10:22:59","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=122353"},"modified":"2020-03-09T07:22:59","modified_gmt":"2020-03-09T10:22:59","slug":"marinha-abre-33-vagas-para-oficiais-no-corpo-de-saude","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/marinha-abre-33-vagas-para-oficiais-no-corpo-de-saude\/","title":{"rendered":"Marinha abre 33 vagas para oficiais no Corpo de Sa\u00fade"},"content":{"rendered":"<p style=\"text-align: justify;\">Estar\u00e3o abertas, de 09 a 23\/03\/20, as inscri\u00e7\u00f5es no concurso p\u00fablico para a admiss\u00e3o de m\u00e9dicos, dentistas, enfermeiros e farmac\u00eauticos, no Corpo de Sa\u00fade da Marinha. A inscri\u00e7\u00e3o \u00e9 realizada no site<a href=\"http:\/\/www.ingressonamarinha.mar.mil.br\/\"> www.ingressonamarinha.mar.mil.br<\/a>, onde tamb\u00e9m pode ser encontrado o edital. A taxa de inscri\u00e7\u00e3o \u00e9 de R$126,00.<\/p>\n<div id=\"attachment_122354\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/03\/corpodesaude_marinhadobrasil_fotomarinha_050320.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-122354\" class=\"size-full wp-image-122354\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/03\/corpodesaude_marinhadobrasil_fotomarinha_050320.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/03\/corpodesaude_marinhadobrasil_fotomarinha_050320.jpg 500w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/03\/corpodesaude_marinhadobrasil_fotomarinha_050320-300x225.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/03\/corpodesaude_marinhadobrasil_fotomarinha_050320-45x35.jpg 45w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-122354\" class=\"wp-caption-text\">Marinha abre vagas para m\u00e9dicos, dentistas, enfermeiros e farmac\u00eauticos (Foto: Marinha do Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\">Para concorrer \u00e9 necess\u00e1rio ser brasileiro nato, de ambos os sexos, ter menos de 36 anos de idade, no dia 01\/01\/21, ter conclu\u00eddo o curso ou estar em fase de conclus\u00e3o para os concorrentes \u00e0s vagas de \u00e2mbito nacional e ter conclu\u00eddo a Resid\u00eancia M\u00e9dica, para as vagas de Medicina de \u00e2mbito regional, dentre outros requisitos previstos em Edital.<\/p>\n<p style=\"text-align: justify;\">S\u00e3o diversas as habilita\u00e7\u00f5es da Medicina, para o concurso de \u00e2mbito nacional, como Cardiologia, Cl\u00ednica M\u00e9dica, Proctologia, Hematologia, Gastroenterologia, etc. As vagas de Medicina, em \u00e2mbito regional para Salvador, s\u00e3o para Endocrinologia\/Metabologia e Gastroenterologia. Em Odontologia, no \u00e2mbito nacional, as vagas s\u00e3o para Endodontia, Patologia Bucal\/Estomatologia e Pr\u00f3tese Dent\u00e1ria. Nas \u00e1reas de Apoio \u00e0 Sa\u00fade, em \u00e2mbito nacional, as vagas s\u00e3o para Enfermagem e Farm\u00e1cia.<\/p>\n<p style=\"text-align: justify;\">Os candidatos ser\u00e3o submetidos a prova objetiva de conhecimentos profissionais, reda\u00e7\u00e3o e exames complementares. Ap\u00f3s a aprova\u00e7\u00e3o em todas as etapas do Concurso, os alunos realizar\u00e3o o Curso de Forma\u00e7\u00e3o de Oficiais (CFO), como Guardas-Marinhas, na cidade do Rio de Janeiro, com a dura\u00e7\u00e3o de 31 semanas, ap\u00f3s o qual ser\u00e3o promovidos a 1\u00ba Tenente. Durante o curso os candidatos receber\u00e3o vencimentos brutos de R$9.070,00, al\u00e9m de alimenta\u00e7\u00e3o, uniforme, assist\u00eancia m\u00e9dico\/odontol\u00f3gica\/psicol\u00f3gica\/social\/religiosa.<br \/>\nConcurso P\u00fablico de N\u00edvel Superior \u2013 Corpo de Sa\u00fade da Marinha<\/p>\n<p style=\"text-align: justify;\">Inscri\u00e7\u00e3o: 09 a 23\/03\/20<\/p>\n<p style=\"text-align: justify;\">Valor: R$ 126,00<\/p>\n<p style=\"text-align: justify;\">Edital: www.ingressonamarinha.mar.mil.br<\/p>\n<p style=\"text-align: justify;\">Acompanhe-nos: www.facebook\/ingressonamarinha; contato:com2dn.concursos@marinha.mil.br ou (71) 3507-3825.<\/p>\n<p>Fonte: Marinha do Brasil<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/02\/Logo-novo-fone-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-121966 aligncenter\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/02\/Logo-novo-fone-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/02\/Logo-novo-fone-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/02\/Logo-novo-fone-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><br \/>\n<em><strong>A<\/strong><strong>companhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/home\">Twitter<\/a>\u00a0e no\u00a0<a href=\"https:\/\/web.facebook.com\/senoticias1\/\">Facebook<\/a><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estar\u00e3o abertas, de 09 a 23\/03\/20, as inscri\u00e7\u00f5es no concurso p\u00fablico para a admiss\u00e3o de m\u00e9dicos, dentistas, enfermeiros e farmac\u00eauticos, no Corpo de Sa\u00fade da Marinha. A inscri\u00e7\u00e3o \u00e9 realizada no site www.ingressonamarinha.mar.mil.br, onde tamb\u00e9m pode ser encontrado o edital. A taxa de inscri\u00e7\u00e3o \u00e9 de R$126,00. Para concorrer \u00e9 necess\u00e1rio ser brasileiro nato, de [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,15],"tags":[14197,3847,3028],"class_list":{"0":"post-122353","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-concursos","7":"category-destaques","8":"tag-corpo-de-saude","9":"tag-marinha","10":"tag-vagas"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/122353"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=122353"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/122353\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=122353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=122353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=122353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}