{"id":121806,"date":"2020-01-27T19:37:30","date_gmt":"2020-01-27T22:37:30","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=121806"},"modified":"2020-01-27T19:46:04","modified_gmt":"2020-01-27T22:46:04","slug":"grupo-de-voluntarios-realiza-acao-com-idosos-do-lar-isaias-gileno-barreto","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/grupo-de-voluntarios-realiza-acao-com-idosos-do-lar-isaias-gileno-barreto\/","title":{"rendered":"Grupo de volunt\u00e1rios realiza a\u00e7\u00e3o com idosos do Lar Isa\u00edas Gileno Barreto"},"content":{"rendered":"<p style=\"text-align: justify;\">As boas a\u00e7\u00f5es realizadas pela <strong>Oficina do Amor<\/strong> n\u00e3o param, e a turma composta por assistente social, psic\u00f3logo, fisioterapeuta, nutricionista, enfermeiro (a), m\u00e9dico e t\u00e9cnico de enfermagem estiveram presentes no <strong>Asilo Lar Isa\u00edas Gileno Barreto<\/strong>, no \u00faltimo dia 25, para atender ao p\u00fablico idoso com servi\u00e7os de sa\u00fade e assistenciais.<\/p>\n<div id=\"attachment_121807\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/230beb16-c5af-4898-8b74-f34ab47d97e3-e1580164493647.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-121807\" class=\"size-full wp-image-121807\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/230beb16-c5af-4898-8b74-f34ab47d97e3-e1580164493647.jpg\" alt=\"\" width=\"550\" height=\"414\" \/><\/a><p id=\"caption-attachment-121807\" class=\"wp-caption-text\">Volunt\u00e1rios do Grupo Oficina do Amor, reunidos durante a\u00e7\u00e3o no Lar Isa\u00edas Gileno Barreto. Foto: Enviada pela enfermeira Camila para a Reda\u00e7\u00e3o do SE Not\u00edcias<\/p><\/div>\n<p style=\"text-align: justify;\">O asilo est\u00e1 localizado em S\u00e3o Crist\u00f3v\u00e3o, e podemos dizer que a visita do s\u00e1bado foi o ponta p\u00e9 inicial de algumas mudan\u00e7as estruturais no <strong>Lar Isa\u00edas Gileno<\/strong>. A equipe do Oficina do amor, somando -se com o projeto &#8220;M\u00e3os realizando sonhos&#8221;, sob a orienta\u00e7\u00e3o da professora Beijamini, otimizou o acesso para a ala feminina. Onde havia antes uma escada, foi feito uma rampa, reduzindo assim a probabilidade de quedas por quem transita frequentemente pelo local.<\/p>\n<p style=\"text-align: justify;\">O Pr\u00f3ximo passo ser\u00e1 a ambienta\u00e7\u00e3o da futura sala de reabilita\u00e7\u00e3o do lar, junto com a coloca\u00e7\u00e3o de algumas barras (corrim\u00e3os) nos corredores e demais locais da institui\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Para a enfermeira e volunt\u00e1ria, Camila Freire Barreto, a a\u00e7\u00e3o vale muito apena, e \u00e9 gratificante. \u201cO trabalho volunt\u00e1rio proporciona receber amor dos nossos idosos e retribui-los com o cuidado e carinho, levando um pouco do nosso lado profissional e humano, sendo esse AMOR e LUZ\u00a0 por onde for\u201d , disse Camila.<\/p>\n<p style=\"text-align: justify;\">O grupo de volunt\u00e1rios tamb\u00e9m realiza a\u00e7\u00e3o para angariar alimentos e produtos de limpezas, que s\u00e3o essenciais e mant\u00e9m o <strong>Asilo Lar Isa\u00edas Gileno Barreto<\/strong>. Atividades l\u00fadicas tamb\u00e9m fazem parte da programa\u00e7\u00e3o com o p\u00fablico assistido, a exemplo de natal, 7 de setembro e carnaval dos idosos, tudo preparado com brincadeiras e lanches.<\/p>\n<p style=\"text-align: justify;\">Por Yslla Vanessa, <strong>Reda\u00e7\u00e3o SE Not\u00edcias<\/strong><\/p>\n<div id=\"attachment_121281\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-121281\" class=\"size-full wp-image-121281\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><p id=\"caption-attachment-121281\" class=\"wp-caption-text\"><em><strong>A<\/strong><strong>companhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/home\">Twitter<\/a>\u00a0e no\u00a0<a href=\"https:\/\/web.facebook.com\/senoticias1\/\">Facebook<\/a>\u00a0<\/strong><\/em><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>As boas a\u00e7\u00f5es realizadas pela Oficina do Amor n\u00e3o param, e a turma composta por assistente social, psic\u00f3logo, fisioterapeuta, nutricionista, enfermeiro (a), m\u00e9dico e t\u00e9cnico de enfermagem estiveram presentes no Asilo Lar Isa\u00edas Gileno Barreto, no \u00faltimo dia 25, para atender ao p\u00fablico idoso com servi\u00e7os de sa\u00fade e assistenciais. O asilo est\u00e1 localizado em [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[4612,13916,13917],"class_list":{"0":"post-121806","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"tag-acao","8":"tag-asilo-lar-isaias-gileno-barreto","9":"tag-grupo-de-voluntarios"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/121806"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=121806"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/121806\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=121806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=121806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=121806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}