{"id":121730,"date":"2020-01-22T08:34:50","date_gmt":"2020-01-22T11:34:50","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=121730"},"modified":"2020-01-22T08:34:50","modified_gmt":"2020-01-22T11:34:50","slug":"mec-afirma-que-notas-das-redacoes-do-enem-nao-foram-prejudicadas","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/mec-afirma-que-notas-das-redacoes-do-enem-nao-foram-prejudicadas\/","title":{"rendered":"MEC afirma que notas das reda\u00e7\u00f5es do Enem n\u00e3o foram prejudicadas"},"content":{"rendered":"<p style=\"text-align: justify;\">O Minist\u00e9rio da Educa\u00e7\u00e3o informou ontem (21) que o processo que pontua as reda\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (Enem) \u00e9 diferente da corre\u00e7\u00e3o das quest\u00f5es objetivas. Por isso, de acordo com o minist\u00e9rio, as notas dos textos n\u00e3o ser\u00e3o prejudicadas pelas inconsist\u00eancias na corre\u00e7\u00e3o das provas objetivas. O MEC informa tamb\u00e9m que cinco mil avaliadores s\u00e3o respons\u00e1veis pela corre\u00e7\u00e3o manual das reda\u00e7\u00f5es.<\/p>\n<div id=\"attachment_121731\" style=\"width: 560px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-121731\" class=\"wp-image-121731 size-full\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229.jpg\" alt=\"\" width=\"550\" height=\"367\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229.jpg 550w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229-300x200.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229-90x60.jpg 90w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229-180x120.jpg 180w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2020\/01\/enem20019_fotofabiorodrigues_ebc_210120-e1579650709229-95x64.jpg 95w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><p id=\"caption-attachment-121731\" class=\"wp-caption-text\">Cinco mil avaliadores trabalham na corre\u00e7\u00e3o manual dos textos (Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\">Todas as reda\u00e7\u00f5es s\u00e3o avaliadas por dois professores em plataforma online, com texto sem identifica\u00e7\u00e3o. Um professor n\u00e3o tem acesso a nota atribu\u00edda pelo outro. Quando a discrep\u00e2ncia das notas \u00e9 superior a 100 pontos, no total, ou 80 pontos em uma das cinco compet\u00eancias avaliadas, um terceiro professor faz a corre\u00e7\u00e3o. A nota final \u00e9 a m\u00e9dia aritm\u00e9tica das duas notas totais que mais se aproximam.Caso a inconsist\u00eancia persista ap\u00f3s a an\u00e1lise do terceiro professor, a reda\u00e7\u00e3o \u00e9 corrigida por uma banca de professores especializados. Eles t\u00eam poder decis\u00f3rio para definir a nota final.<\/p>\n<p style=\"text-align: justify;\">A reda\u00e7\u00e3o do Enem 2019 avaliou cinco compet\u00eancias: dom\u00ednio da escrita formal; desenvolvimento do tema em estilo dissertativo-argumentativo; relacionar, organizar e interpretar informa\u00e7\u00f5es e argumentos em defesa de uma opini\u00e3o; conhecimento de mecanismos lingu\u00edsticos para construir a argumenta\u00e7\u00e3o; e elabora\u00e7\u00e3o de proposta de interven\u00e7\u00e3o para o problema proposto, com respeito aos direitos humanos.<\/p>\n<p style=\"text-align: justify;\">A nota m\u00e1xima prevista \u00e9 mil. Textos com at\u00e9 sete linhas ou que fugiram ao tema est\u00e3o entre os crit\u00e9rios para zerar a reda\u00e7\u00e3o. Os participantes que tiverem d\u00favidas em rela\u00e7\u00e3o \u00e0s notas das quest\u00f5es objetivas, podem entrar em conato com o Inep, pela central 0800-616161.<\/p>\n<p style=\"text-align: justify;\">* Com informa\u00e7\u00f5es do Minist\u00e9rio da Educa\u00e7\u00e3o<\/p>\n<div id=\"attachment_121281\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-121281\" class=\"wp-image-121281 size-full\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/12\/Logo-novo-fone-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><p id=\"caption-attachment-121281\" class=\"wp-caption-text\"><em><strong>A<\/strong><strong>companhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/home\">Twitter<\/a>\u00a0e no\u00a0<a href=\"https:\/\/web.facebook.com\/senoticias1\/\">Facebook<\/a>\u00a0<\/strong><\/em><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Educa\u00e7\u00e3o informou ontem (21) que o processo que pontua as reda\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (Enem) \u00e9 diferente da corre\u00e7\u00e3o das quest\u00f5es objetivas. Por isso, de acordo com o minist\u00e9rio, as notas dos textos n\u00e3o ser\u00e3o prejudicadas pelas inconsist\u00eancias na corre\u00e7\u00e3o das provas objetivas. O MEC informa tamb\u00e9m que cinco [&hellip;]<\/p>\n","protected":false},"author":6557,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,44],"tags":[764,8746,6175],"class_list":{"0":"post-121730","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-destaques","7":"category-educacao","8":"tag-enem","9":"tag-notas","10":"tag-redacao"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/121730"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6557"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=121730"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/121730\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=121730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=121730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=121730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}