{"id":118711,"date":"2019-06-05T12:34:56","date_gmt":"2019-06-05T15:34:56","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=118711"},"modified":"2019-06-05T12:34:56","modified_gmt":"2019-06-05T15:34:56","slug":"governador-entrega-reforma-da-unidade-de-tratamento-de-queimados-do-huse","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/governador-entrega-reforma-da-unidade-de-tratamento-de-queimados-do-huse\/","title":{"rendered":"Governador entrega reforma da Unidade de Tratamento de Queimados do Huse"},"content":{"rendered":"<p style=\"text-align: justify;\">Com o objetivo de proporcionar melhoria no atendimento aos pacientes v\u00edtimas de queimaduras, bem como oferecer melhores condi\u00e7\u00f5es de trabalho aos profissionais que trabalham no setor, o governador Belivaldo Chagas, acompanhado da vice-governadora Eliane Aquino, entregou, nesta ter\u00e7a-feira(04), no Hospital de Urg\u00eancia de Sergipe(Huse), a reforma da Unidade de Tratamento de Queimados (UTQ) Dr. Jos\u00e9 Olino de Campos Lima. Na ocasi\u00e3o, ainda foi realizado\u00a0o Curso Anual de Atualiza\u00e7\u00e3o ao Atendimento do Paciente Queimado que ir\u00e1 aperfei\u00e7oar o atendimento\u00a0 \u00e0s v\u00edtimas de queimaduras no per\u00edodo junino.<\/p>\n<div id=\"attachment_118712\" style=\"width: 609px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/06\/foto3.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-118712\" class=\"size-full wp-image-118712\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/06\/foto3-e1559748746776.jpeg\" alt=\"\" width=\"599\" height=\"399\" \/><\/a><p id=\"caption-attachment-118712\" class=\"wp-caption-text\">Na ocasi\u00e3o, ainda foi realizado o Curso Anual de Atualiza\u00e7\u00e3o ao Atendimento do Paciente Queimado que ir\u00e1 aperfei\u00e7oar o atendimento \u00e0s v\u00edtimas de queimaduras no per\u00edodo junino (foto: Marco Vieira\/ASN)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201c\u00c9 uma nova a\u00e7\u00e3o que acontece fruto da participa\u00e7\u00e3o do Minist\u00e9rio P\u00fablico que, ao estabelecer algumas san\u00e7\u00f5es a algumas empresas, se transforma em benef\u00edcios para a sociedade. Aqui est\u00e3o sendo investidos R$ 500 mil, na reforma da Unidade de Tratamento de Queimados. Uma unidade moderna, numa parceria com a Energisa, que fez sua a\u00e7\u00e3o, como o Minist\u00e9rio P\u00fablico determinou que\u00a0assim fosse feito, e\u00a0quem sai ganhando \u00e9 a comunidade. Uma obra que chega em boa hora, com a chegada do per\u00edodo junino. Espero que outras a\u00e7\u00f5es como essa venham a acontecer depois. E que a turma tenha cuidado na hora de manusear\u00a0fogos para que n\u00e3o tenha problema de queimadura, mas se vier a acontecer, n\u00f3s estamos melhor preparados para receb\u00ea-los\u201d, disse o governador Belivaldo Chagas.<\/p>\n<p style=\"text-align: justify;\">A reforma da unidade foi realizada pela Energisa em cumprimento \u00e0 solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual e Federal em visita realizada \u00e0 UTQ conjuntamente com a Empresa de Energia, referente ao Inqu\u00e9rito Civil do Minist\u00e9rio P\u00fablico, movido pela Promotoria de Defesa do Consumidor. A a\u00e7\u00e3o \u00e9 um ressarcimento por dano social, sobre os acidentes envolvendo queda de fios de alta-tens\u00e3o da Energisa, vitimando consumidores.<\/p>\n<p style=\"text-align: justify;\">Para a promotora de Justi\u00e7a de Defesa do Consumidor em Aracaju, Euza Missano, a a\u00e7\u00e3o \u00e9 uma forma de compensar a popula\u00e7\u00e3o. \u201cRepresenta o processo de pacifica\u00e7\u00e3o social. N\u00f3s n\u00e3o precisamos judicializar, fizemos um ajuste de conduta, um TAC, na qual o dano social foi revertido para a sociedade. Ent\u00e3o hoje, a\u00a0Energisa reformou toda a parte da UTQ e o governo do Estado entrega \u00e0 popula\u00e7\u00e3o, numa \u00e9poca important\u00edssima de festejos juninos, e a sociedade vai ter revertido esse valor em benef\u00edcio\u201d, revelou.<\/p>\n<p style=\"text-align: justify;\">Na oportunidade, o presidente da Energisa, Roberto Carlos Pereira Currais, ressaltou as melhorias que foram realizadas na unidade. &#8220;Tivemos a grata satisfa\u00e7\u00e3o de participar desta iniciativa. N\u00f3s investimos R$ 500 mil, com a renova\u00e7\u00e3o de toda a unidade da UTQ, da parte infantil, os materiais hospitalares, equipamentos, e agora entregar a UTQ com os melhores equipamentos para poder servir melhor as vitimas acidentadas&#8221;, declarou.<\/p>\n<p style=\"text-align: justify;\">&#8220;\u00c9 um presente que a popula\u00e7\u00e3o do estado de Sergipe est\u00e1 ganhando. Esperamos que poucos precisem usar, mas que saibam que tem \u00e0 disposi\u00e7\u00e3o um espa\u00e7o que \u00e9\u00a0refer\u00eancia, que passou por uma grande reforma e que \u00e9 excel\u00eancia n\u00e3o s\u00f3 no estado, mas tamb\u00e9m no Nordeste&#8221;, exaltou o secret\u00e1rio de Estado da Sa\u00fade, Valberto de Lima.<\/p>\n<p><strong>Parcerias\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Na solenidade, o governador falou tamb\u00e9m sobre parcerias com institui\u00e7\u00f5es e a iniciativa privada que poder\u00e3o ser revertidas em benef\u00edcios da\u00a0popula\u00e7\u00e3o. \u201cOntem, tivemos uma excelente reuni\u00e3o com o Minist\u00e9rio P\u00fablico do Trabalho, onde a\u00e7\u00f5es concretas dever\u00e3o estar acontecendo, fruto de multas que s\u00e3o aplicadas. Enfim,\u00a0 s\u00e3o a\u00e7\u00f5es que est\u00e3o sendo convertidas em prol da sociedade. O governo do Estado, portanto, agradece pelas obras\u201d, comentou\u00a0Belivaldo que\u00a0destacou\u00a0a parceria com Energisa para melhoria das condi\u00e7\u00f5es de funcionamento do Hospital de Urg\u00eancia de Sergipe. \u00a0\u201cAtrav\u00e9s boa vontade da empresa, estamos realizando o redimensionamento da rede de energia do hospital. O Huse possui uma rede el\u00e9trica antiga, onde foram feitas reformas, incremento de equipamentos e necessitava desse redimensionamento\u00a0 para comportar essas adequa\u00e7\u00f5es\u201d, colocou.<\/p>\n<p style=\"text-align: justify;\"><strong>Reforma\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">A reforma compreendeu adequa\u00e7\u00f5es na parte estrutural, el\u00e9trica, al\u00e9m de compra de equipamentos. \u00a0Na parte el\u00e9trica, houve a troca das lumin\u00e1rias, revis\u00e3o el\u00e9trica, aquisi\u00e7\u00e3o de porteiro eletr\u00f4nico com c\u00e2mera, 4 chuveiros el\u00e9tricos, 3 bebedouros e 2 aparelhos de micro-ondas. J\u00e1 na parte da estrutura, troca de portas com visor em todas as enfermarias e sala cir\u00fargica, troca das fechaduras, aquisi\u00e7\u00e3o de 11 aparelhos de ar condicionado, 6 televisores para as enfermarias, 2 geladeiras, uma mesa, 4 cadeiras, 2 bir\u00f4s, 4 arm\u00e1rios, arm\u00e1rio em MDF bancada e arm\u00e1rio suspenso (posto de enfermagem), arm\u00e1rio em MDF para guarda e dispensa\u00e7\u00e3o individualizada de medicamentos (14 leitos), arm\u00e1rio grande MDF (arsenal), arm\u00e1rio em MDF posto de enfermagem, arquivo de prontu\u00e1rios, 8 arm\u00e1rios em MDF suspensos, 14 mesas de cabeceira em MDF com gaveta, com tampo de refei\u00e7\u00e3o e regulagem de altura, p\u00e9s com rod\u00edzios.<\/p>\n<p style=\"text-align: justify;\">Para o superintendente do Hospital de Urg\u00eancia de Sergipe (Huse), Darcy Tavares, a reforma trouxe uma melhoria completa da unidade. \u201cFoi feita uma reforma de toda estrutura f\u00edsica, foi feita uma melhoria em toda nossas instala\u00e7\u00f5es el\u00e9tricas, foi climatizado, colocado cerca de 11 aparelhos de ar-condicionado, comprados equipamentos novos important\u00edssimos para a qualidade do atendimento, inclusive adquirida mesa cir\u00fargica da mais moderna, enfim foi dado um upgrade que foi dado na nossa \u00e1reas de Tratamento de Queimados\u201d.<\/p>\n<p style=\"text-align: justify;\">A unidade contar\u00e1 tamb\u00e9m com materiais cir\u00fargicos como derm\u00e1tomo el\u00e9trico sem fio, mesa cir\u00fargica el\u00e9trica, faca de Blair, 6 monitores card\u00edacos, 3 ox\u00edmetros port\u00e1teis, Barakas (adulto e infantil), Ambu (adulto e infantil), m\u00e1scaras de nebuliza\u00e7\u00e3o (adulto e infantil), esfigmoman\u00f4metro (adulto e infantil), estetosc\u00f3pios, m\u00e1scaras de ventila\u00e7\u00e3o n\u00e3o invasiva (adulto e infantil), camas el\u00e9tricas, cama beliche, cama bicama, cama normal, cadeiras ergon\u00f4micas, arm\u00e1rios de metal para vesti\u00e1rios (masculino e feminino).<\/p>\n<p style=\"text-align: justify;\">\u201cA reforma possibilitou um atendimento mais humanizado, com equipamentos de ponta para a gente prestar uma assist\u00eancia a todos os pacientes que necessitam da nossa unidade. Com os equipamentos de ponta, a gente otimiza o tempo, \u00a0diminui tamb\u00e9m o tempo de interna\u00e7\u00e3o desses pacientes\u201d garantiu a gerente da UTQ, Elmara Salgado.<\/p>\n<p style=\"text-align: justify;\"><strong>Unidade\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">A unidade leva o nome do m\u00e9dico Dr. Jos\u00e9 Olino de Campos Lima. Presente na solenidade, o filho do homenageado,Jos\u00e9 Olino de Campos Lima J\u00fanior, agradeceu a lembran\u00e7a. \u201cSempre digo a meu pai que toda demonstra\u00e7\u00e3o de carinho e reconhecimento que ele recebe \u00e9 bruto do que ele plantou em sua vida pessoal e profissional. Portanto, agradecemos ao governador Belivaldo e toda administra\u00e7\u00e3o por este evento que toca n\u00e3o apenas o cora\u00e7\u00e3o do homenageado, mas de todos os seus filhos, sobrinhos, irm\u00e3os, demais familiares e amigos. Recebam nosso muito obrigado\u201d.<\/p>\n<p style=\"text-align: justify;\">A Unidade de Tratamento de Queimados (UTQ), Dr. Jos\u00e9 Olino de Campos Lima, inaugurada em 17 de junho de 2003, est\u00e1 inserida no Hospital de Urg\u00eancia de Sergipe (HUSE), credenciado pelo Minist\u00e9rio da sa\u00fade como refer\u00eancia no tratamento a queimados, conforme portaria n\u00ba 1.273 de 21 de novembro de 2000.<\/p>\n<p style=\"text-align: justify;\">Possui 14 leitos, sendo 4 pedi\u00e1tricos, 2 semi-intensivo, 8 adultos (4 femininos e 4 masculinos) e uma sala cir\u00fargico. Conta com escala fixa de profissionais respons\u00e1vel t\u00e9cnico m\u00e9dico, gerente, enfermeira assistencial, t\u00e9cnicos e auxiliares de enfermagem, assistente social, fonoaudi\u00f3logo, psic\u00f3logo, secret\u00e1rio de cl\u00ednica, auxiliar de servi\u00e7os gerais, m\u00e9dico plantonista, cirurgi\u00e3o pl\u00e1stico, anestesiologista, instrumentador cir\u00fargico, pediatra, fisioterapeuta e nutricionista.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Curso Anual de Atualiza\u00e7\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s evento, foi realizado mais uma edi\u00e7\u00e3o do Curso de Atualiza\u00e7\u00e3o ao Atendimento do Paciente Queimado. O\u00a0objetivo \u00e9\u00a0preparar os profissionais de sa\u00fade, capacitando-os para um melhor atendimento.<\/p>\n<p style=\"text-align: justify;\">Para a m\u00e9dica Moema Santana, o curso \u00e9 fundamental para aperfei\u00e7oar o atendimento \u00e0s v\u00edtimas de queimadura, que aumenta principalmente no per\u00edodo junino. \u201cA gente faz todo ano justamente essa orienta\u00e7\u00e3o para\u00a0 prevenir e ter essa conduta de orientar aos pacientes que podem vir para o Huse e os que podem ficar no pr\u00f3prio munic\u00edpio e como chegar aqui, como ser atendido aqui. Todo ano a gente prepara uma sala de procedimentos para atendermos esses pacientes queimados, essa sala de procedimento j\u00e1 fica preparada desde o come\u00e7o de junho, mas nossa vaz\u00e3o maior realmente \u00e9 do dia 23 para 24 que \u00e9 justamente o S\u00e3o Jo\u00e3o. No\u00a0ano passado, na v\u00e9spera de S\u00e3o Jo\u00e3o, n\u00f3s atendemos 22 pacientes de 44 que foram atendidos durante todo o m\u00eas s\u00f3 relacionados a fogos de artif\u00edcios, desses 22 pacientes apenas 3 foram internados na UTQ&#8221;, informou.<\/p>\n<p style=\"text-align: justify;\">No curso \u00e9 abordado o planejamento do Huse e estrutura da UTQ para o per\u00edodo junino. Al\u00e9m de conceitos b\u00e1sicos, atendimento inicial e crit\u00e9rios de encaminhamento, atendimento pr\u00e9-hospitalar e transporte do paciente queimado. E ainda, cuidados cl\u00ednicos ao paciente queimado e queimaduras em crian\u00e7as e curativos.<\/p>\n<p style=\"text-align: justify;\">A solenidade contou com a participa\u00e7\u00e3o do presidente da Alese, Luciano Bispo; o deputado estadual, Zezinho Sobral; o presidente da Funda\u00e7\u00e3o Hospitalar de Sa\u00fade (FHS), Jorge Kleber; o procurador-geral de Justi\u00e7a do Minist\u00e9rio P\u00fablico de Sergipe (MPSE), Eduardo Barreto D\u2019Avila; o promotor da \u00e1rea da sa\u00fade, Rony Almeida;\u00a0 a superintendente executiva da Secretaria da Sa\u00fade, Adriana Menezes; e o coordenador da unidade de queimados, Bruno Cintra.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-118600\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acompanhe o SE Not\u00edcias no\u00a0<\/strong><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\" rel=\"noopener\"><b>Twitter<\/b><\/a><strong>,\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noopener\"><b>Facebook\u00a0<\/b><\/a><strong>e no\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noopener\"><b>Instagram<\/b><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>Por Agencia Sergipe de Not\u00edcias<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de proporcionar melhoria no atendimento aos pacientes v\u00edtimas de queimaduras, bem como oferecer melhores condi\u00e7\u00f5es de trabalho aos profissionais que trabalham no setor, o governador Belivaldo Chagas, acompanhado da vice-governadora Eliane Aquino, entregou, nesta ter\u00e7a-feira(04), no Hospital de Urg\u00eancia de Sergipe(Huse), a reforma da Unidade de Tratamento de Queimados (UTQ) Dr. Jos\u00e9 [&hellip;]<\/p>\n","protected":false},"author":6552,"featured_media":118712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[12308,2806,555,319,12309],"class_list":{"0":"post-118711","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-politica","9":"tag-atendimento-do-paciente-queimado","10":"tag-belivaldo-chagas","11":"tag-estado-de-sergipe","12":"tag-huse","13":"tag-unidade-de-tratamento-de-queimados-do-huse"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/118711"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6552"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=118711"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/118711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/118712"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=118711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=118711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=118711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}