{"id":118261,"date":"2019-05-05T11:04:05","date_gmt":"2019-05-05T14:04:05","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=118261"},"modified":"2019-05-05T11:07:58","modified_gmt":"2019-05-05T14:07:58","slug":"estacio-realizara-sua-segunda-feira-virtual-de-estagios-e-empregos","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/estacio-realizara-sua-segunda-feira-virtual-de-estagios-e-empregos\/","title":{"rendered":"Est\u00e1cio realizar\u00e1 sua segunda Feira Virtual de Est\u00e1gios e Empregos"},"content":{"rendered":"<p style=\"text-align: justify;\">De 6 a 10 deste m\u00eas, a Est\u00e1cio promover\u00e1 sua 2\u00aa Feira Virtual de Est\u00e1gios e Empregos, da qual poder\u00e3o participar alunos, egressos e n\u00e3o alunos. Para acessar o conte\u00fado, os interessados dever\u00e3o fazer seu pr\u00e9-cadastro no link:\u00a0<a href=\"https:\/\/portal.estacio.br\/feira-empregabilidade\/\" target=\"VdC8EJ5upb5cyu5UwUOjUNA\" rel=\"noopener noreferrer\">https:\/\/portal.estacio.br\/feira-empregabilidade\/<\/a>.<\/p>\n<p style=\"text-align: justify;\">Durante este per\u00edodo, 24 horas por dia, ser\u00e1 poss\u00edvel conferir carreiras em evid\u00eancia e mais de\u00a07 mil\u00a0vagas que ser\u00e3o oferecidas para alunos (vagas exclusivas) , egressos (vagas exclusivas)\u00a0 e n\u00e3o alunos. Empresas como Ambev, IBM, OLX, White Martins, Amil,\u00a0Ita\u00fa Unibanco,\u00a0KPMG, Manpower Group, Huawei, BRMalls,\u00a0Rede D\u00b4Or, Stone, Stefanini, Comit\u00ea Internacional da Cruz Vermelha, Motta Fernandes, Lojas Americanas, CIEE, Mudes,\u00a0Nube,\u00a0SuperEst\u00e1gios, Estante M\u00e1gica, Walljobs,\u00a0Cia de Talentos, dentre outras j\u00e1 aderiram \u00e0 iniciativa.<\/p>\n<div id=\"attachment_118262\" style=\"width: 560px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/feiraestacio_030519.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-118262\" class=\"size-full wp-image-118262\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/feiraestacio_030519.jpg\" alt=\"\" width=\"550\" height=\"360\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/feiraestacio_030519.jpg 550w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/feiraestacio_030519-300x196.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/05\/feiraestacio_030519-90x60.jpg 90w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><p id=\"caption-attachment-118262\" class=\"wp-caption-text\">Est\u00e1cio promover\u00e1 sua 2\u00aa Feira Virtual de Est\u00e1gios e Empregos (foto: divulga\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Os temas abordados na Feira ser\u00e3o: Transi\u00e7\u00e3o de carreira, Home office, Metas e rotinas e Futuro do trabalho, entre outros em forma de palestras e conte\u00fados. A intera\u00e7\u00e3o entre participantes e empresas\u00a0ser\u00e1 por chat conforme programa\u00e7\u00e3o e agenda da feira. O link oficial para acompanhar a 2\u00aa Feira Virtual de Est\u00e1gios e Empregos \u00e9<a href=\"https:\/\/verosolutions.6connex.com\/event\/feiravirtual\/estacio2019\/login\" target=\"VdC8EJ5upb5cyu5UwUOjUNA\" rel=\"noopener noreferrer\">https:\/\/verosolutions.6connex.com\/event\/feiravirtual\/estacio2019\/login<\/a>\u00a0ele s\u00f3 poder\u00e1 ser acessado a partir do dia 6 de maio, data de in\u00edcio da feira.<\/p>\n<p style=\"text-align: justify;\">\u201cA Feira \u00e9 a ferramenta e a oportunidade ideal para todos que desejam aumentar suas chances no mercado de trabalho, al\u00e9m de ser um meio de atualiza\u00e7\u00e3o e, \u00e9 claro, network com grandes empresas. A Feira possui novidades e inova\u00e7\u00f5es, confiram.\u201d afirma Natalie Nitz, coordenadora de Empregabilidade da Est\u00e1cio.<\/p>\n<p style=\"text-align: justify;\">A Est\u00e1cio \u00e9 um dos maiores e mais respeitados grupos do setor educacional do Brasil, atuando h\u00e1 48 anos no segmento de ensino superior. Est\u00e1 presente em 23 estados e no Distrito Federal, por meio do ensino presencial, e em todo o Brasil com o EaD, contando com mais de 500 mil alunos matriculados.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Acompanhe o SE Not\u00edcias no\u00a0<\/strong><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\" rel=\"noopener\"><b>Twitter<\/b><\/a><strong>,\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noopener\"><b>Facebook\u00a0<\/b><\/a><strong>e no\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noopener\"><b>Instagram<\/b><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/04\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-118176\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/04\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/04\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2019\/04\/Logomarca-fone-SE-4-2-1-1-1-1-1-1-1-2-3-4-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Fonte: Assessoria de Imprensa\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 6 a 10 deste m\u00eas, a Est\u00e1cio promover\u00e1 sua 2\u00aa Feira Virtual de Est\u00e1gios e Empregos, da qual poder\u00e3o participar alunos, egressos e n\u00e3o alunos. Para acessar o conte\u00fado, os interessados dever\u00e3o fazer seu pr\u00e9-cadastro no link:\u00a0https:\/\/portal.estacio.br\/feira-empregabilidade\/. Durante este per\u00edodo, 24 horas por dia, ser\u00e1 poss\u00edvel conferir carreiras em evid\u00eancia e mais de\u00a07 mil\u00a0vagas [&hellip;]<\/p>\n","protected":false},"author":6552,"featured_media":118262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,1,8],"tags":[12111,12112,12114,12115,12116,12113],"class_list":{"0":"post-118261","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-sem-categoria","9":"category-esporte-e-cultura","10":"tag-2a-feira-virtual-de-estagios-e-empregos","11":"tag-estacio","12":"tag-home-office","13":"tag-metas-e-rotinas-e-futuro-do-trabalho","14":"tag-segunda-feira-virtual-de-estagios-e-empregos","15":"tag-transicao-de-carreira"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/118261"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6552"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=118261"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/118261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/118262"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=118261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=118261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=118261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}