{"id":115309,"date":"2018-09-20T07:55:52","date_gmt":"2018-09-20T10:55:52","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=115309"},"modified":"2018-09-20T07:55:52","modified_gmt":"2018-09-20T10:55:52","slug":"policia-civil-investiga-triplo-homicidio-que-aconteceu-no-tijuquinha","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/policia-civil-investiga-triplo-homicidio-que-aconteceu-no-tijuquinha\/","title":{"rendered":"Pol\u00edcia Civil investiga triplo homic\u00eddio que aconteceu no Tijuquinha"},"content":{"rendered":"<p style=\"text-align: justify;\">Familiares do casal assassinado no conjunto Tijuquinha, em S\u00e3o Crist\u00f3v\u00e3o, v\u00e3o prestar depoimento nesta quinta-feira, 20, no Departamento de Homic\u00eddios e Prote\u00e7\u00e3o a Pessoa (DHPP).<\/p>\n<p style=\"text-align: justify;\">O delegado Lu\u00eds Carlos Xavier informou que as equipes da Pol\u00edcia Civil estiveram no local para fazer o levantamento de imagens e testemunhas. O delegado tamb\u00e9m aguardo o laudo do Instituto de Criminal\u00edstica, que vai complementar as investiga\u00e7\u00f5es, com fotos e detalhes do crime.<\/p>\n<div id=\"attachment_115310\" style=\"width: 609px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/09\/3718031796--e1537440534648.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-115310\" class=\"size-full wp-image-115310\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/09\/3718031796--e1537440534648.jpg\" alt=\"\" width=\"599\" height=\"402\" \/><\/a><p id=\"caption-attachment-115310\" class=\"wp-caption-text\">O crime aconteceu no loteamento Tijuquinha, em S\u00e3o Crist\u00f3v\u00e3o, na noite desta ter\u00e7a-feira (18). (Foto: redes sociais)<\/p><\/div>\n<p style=\"text-align: justify;\">O jovem Alisson Fernando Rodrigues dos Santos, de 26 anos morreu no local, ele estava com a namorada, a adolescente de 13 anos, Luiza Beatriz Ramos de Carvalho estava gr\u00e1vida de 7 meses, ela tamb\u00e9m morreu no local. Com a chegada do Servi\u00e7o M\u00e9dico de Urg\u00eancia (SAMU), a equipe chegou a fazer o parto da adolescente, o beb\u00ea foi retirado da barriga pela equipe m\u00e9dica, ele nasceu com vida, mas ap\u00f3s tentativas de reanimar, ele tamb\u00e9m n\u00e3o resistiu. O procedimento foi feito na ambul\u00e2ncia do Samu.<\/p>\n<p style=\"text-align: justify;\">A hip\u00f3tese inicial \u00e9 de execu\u00e7\u00e3o, mas conforme o delegado Lu\u00eds Carlos, a Pol\u00edcia Civil vai investigar a vida das v\u00edtimas, sobretudo do homem, para descobrir a verdadeira motiva\u00e7\u00e3o do crime.<\/p>\n<p style=\"text-align: justify;\">O assassinato ocorreu na noite desta ter\u00e7a-feira, 18, na rua Lauro Maia. O casal estava na porta de casa quando criminosos em um t\u00e1xi fizeram v\u00e1rios disparos de arma de fogo. A informa\u00e7\u00e3o \u00e9 que uma adolescente gr\u00e1vida teria se colocado na frente do marido para defend\u00ea-lo. Uma equipe do Samu fez o parto da jovem, mas apesar de ter nascido com sinais vitais, o beb\u00ea n\u00e3o sobreviveu.<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/08\/Logomarca-fone-SE-4-2-1-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-114974\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/08\/Logomarca-fone-SE-4-2-1-1-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/08\/Logomarca-fone-SE-4-2-1-1-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/08\/Logomarca-fone-SE-4-2-1-1-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Acompanhe o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\" rel=\"noopener\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\" rel=\"noopener\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\" rel=\"noopener\"><b>Instagram<\/b><\/a><\/em><\/p>\n<p><em>Informa\u00e7\u00f5es da SSP e portal Infonet<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familiares do casal assassinado no conjunto Tijuquinha, em S\u00e3o Crist\u00f3v\u00e3o, v\u00e3o prestar depoimento nesta quinta-feira, 20, no Departamento de Homic\u00eddios e Prote\u00e7\u00e3o a Pessoa (DHPP). O delegado Lu\u00eds Carlos Xavier informou que as equipes da Pol\u00edcia Civil estiveram no local para fazer o levantamento de imagens e testemunhas. O delegado tamb\u00e9m aguardo o laudo do [&hellip;]<\/p>\n","protected":false},"author":6552,"featured_media":115310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,7],"tags":[335,4070,5156],"class_list":{"0":"post-115309","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-policia","9":"tag-sao-cristovao","10":"tag-tijuquinha","11":"tag-triplo-homicidio"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/115309"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6552"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=115309"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/115309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/115310"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=115309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=115309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=115309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}