{"id":114328,"date":"2018-07-25T14:38:37","date_gmt":"2018-07-25T17:38:37","guid":{"rendered":"https:\/\/senoticias.com.br\/se\/?p=114328"},"modified":"2018-07-25T14:38:37","modified_gmt":"2018-07-25T17:38:37","slug":"rock-in-riomar-homenageia-red-hot-chili-peppers-e-as-divas-do-rock","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/rock-in-riomar-homenageia-red-hot-chili-peppers-e-as-divas-do-rock\/","title":{"rendered":"\u2018Rock in RioMar\u2019 homenageia Red Hot Chili Peppers e as Divas do Rock"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"color: #000000\">Dando continuidade \u00e0s comemora\u00e7\u00f5es do m\u00eas do rock, o RioMar Shopping brinda o p\u00fablico sergipano com covers da banda Red Hot Chili Peppers e o Especial Divas do Rock. Nesta quinta-feira (26), a banda Caju Peppers homenageia o grupo americano Red Hot Chili Peppers, com grandes sucessos da carreira, como \u2018Californication\u2019 e \u2018Other Side\u2019. O show acontece a partir das 19h, na pra\u00e7a de alimenta\u00e7\u00e3o Rio.<\/span><\/p>\n<div id=\"attachment_114329\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Banda-Sargento-Mostarda_Foto-Felippe-Ara\u00fajo-e1532540249446.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-114329\" class=\"wp-image-114329 size-full\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Banda-Sargento-Mostarda_Foto-Felippe-Ara\u00fajo-e1532540249446.jpg\" alt=\"\" width=\"599\" height=\"398\" \/><\/a><p id=\"caption-attachment-114329\" class=\"wp-caption-text\">Foto: Felippe Ara\u00fajo<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">J\u00e1 na sexta-feira (27), a cantora Raquel Diniz leva ao p\u00fablico um especial em homenagem \u00e0s Divas do Rock. Na apresenta\u00e7\u00e3o, que acontece a partir das 19h, na pra\u00e7a de alimenta\u00e7\u00e3o Mar, o p\u00fablico vai poder conferir sucessos de grandes cantoras como Rita Lee e C\u00e1ssia Eller. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">E para brindar o encerramento do m\u00eas do rock, no dia 31 de julho, o Bob\u00b4s inaugura uma moderna opera\u00e7\u00e3o na Pra\u00e7a de Alimenta\u00e7\u00e3o Mar e presenteia o p\u00fablico com um supershow da banda Sargento Mostarda em tributo a The Beatles. A apresenta\u00e7\u00e3o ter\u00e1 in\u00edcio \u00e0s 18 horas.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Logomarca-fone-SE-4-2-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-114026 size-full\" src=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Logomarca-fone-SE-4-2-1-1.jpg\" alt=\"\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Logomarca-fone-SE-4-2-1-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/07\/Logomarca-fone-SE-4-2-1-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>Por Lotti Caldas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dando continuidade \u00e0s comemora\u00e7\u00f5es do m\u00eas do rock, o RioMar Shopping brinda o p\u00fablico sergipano com covers da banda Red Hot Chili Peppers e o Especial Divas do Rock. Nesta quinta-feira (26), a banda Caju Peppers homenageia o grupo americano Red Hot Chili Peppers, com grandes sucessos da carreira, como \u2018Californication\u2019 e \u2018Other Side\u2019. O [&hellip;]<\/p>\n","protected":false},"author":6553,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[10446,10445,2663,10444,4058,10443,6699,5181,648],"class_list":{"0":"post-114328","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-entretenimento","7":"tag-banda","8":"tag-cover","9":"tag-cultura","10":"tag-mes-do-rock","11":"tag-musica","12":"tag-red-hot-chilli-peppears","13":"tag-riomar","14":"tag-shopping","15":"tag-show"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/114328"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/6553"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=114328"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/114328\/revisions"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=114328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=114328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=114328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}