{"id":109797,"date":"2018-01-13T09:18:41","date_gmt":"2018-01-13T12:18:41","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=109797"},"modified":"2018-01-13T09:18:41","modified_gmt":"2018-01-13T12:18:41","slug":"pensando-em-revidar-uma-traicao-veja-5-motivos-para-nao-seguir-esse-caminho","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/pensando-em-revidar-uma-traicao-veja-5-motivos-para-nao-seguir-esse-caminho\/","title":{"rendered":"Pensando em revidar uma trai\u00e7\u00e3o? Veja 5 motivos para n\u00e3o seguir esse caminho"},"content":{"rendered":"<p style=\"text-align: justify;\">Muitas vezes, quando uma pessoa \u00e9 tra\u00edda por algu\u00e9m que ela ama, a primeira coisa que pensa \u00e9 em dar o troco para poder sair por cima na rela\u00e7\u00e3o. Por\u00e9m, a verdade \u00e9 que esse ato impensado pode trazer consequ\u00eancias.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o se esque\u00e7a que o doce sabor da vingan\u00e7a pode ser passageiro e o amargo sabor do arrependimento pode durar um tempo maior. Veja a seguir algumas raz\u00f5es para evitar se vingar de uma trai\u00e7\u00e3o.<\/p>\n<div id=\"attachment_109798\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Pensando-em-revidar-traicao-SEnoticias-e1515845155345.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109798\" class=\"size-full wp-image-109798\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Pensando-em-revidar-traicao-SEnoticias-e1515845155345.jpg\" alt=\"Veja 5 motivos para n\u00e3o seguir esse caminho \" width=\"599\" height=\"331\" \/><\/a><p id=\"caption-attachment-109798\" class=\"wp-caption-text\">Veja 5 motivos para n\u00e3o seguir esse caminho (foto: reprodu\u00e7\u00e3o\/Meu Estilo)<\/p><\/div>\n<p style=\"text-align: justify;\">Quando uma pessoa trai outra pensando que est\u00e1 dando o troco na mesma moeda, corre o risco de dar in\u00edcio a um ciclo sem confian\u00e7a, amizade e parceria na rela\u00e7\u00e3o. Ao inv\u00e9s de eliminar o problema da trai\u00e7\u00e3o, voc\u00ea far\u00e1 com que o problema seja ainda maior, iniciando uma rela\u00e7\u00e3o baseada apenas em trai\u00e7\u00f5es.<\/p>\n<h2>Dar o troco pode ser doloroso<\/h2>\n<p style=\"text-align: justify;\">Quando algu\u00e9m trai por vingan\u00e7a, seu objetivo \u00e9 fazer com que o parceiro sinta a mesma dor, e fazer isso acreditando que sua dor ir\u00e1 diminuir pode n\u00e3o ser o certo. Muitas vezes quem traiu j\u00e1 n\u00e3o est\u00e1 mais se importando com a rela\u00e7\u00e3o, logo, n\u00e3o ser\u00e1 t\u00e3o doloroso para ele, o que poder\u00e1 aumentar ainda mais sua dor e frustra\u00e7\u00e3o.<\/p>\n<h2 style=\"text-align: justify;\">Pode se tornar um padr\u00e3o<\/h2>\n<p style=\"text-align: justify;\">Como n\u00e3o se sabe ao certo qual ser\u00e1 o efeito da vingan\u00e7a, \u00e9 poss\u00edvel que saia ainda mais machucada da situa\u00e7\u00e3o, uma vez que j\u00e1 est\u00e1 com sentimentos abalados e n\u00e3o ter\u00e1 nenhuma satisfa\u00e7\u00e3o na trai\u00e7\u00e3o.<\/p>\n<h2 style=\"text-align: justify;\">Consequ\u00eancia de usar algu\u00e9m<\/h2>\n<p style=\"text-align: justify;\">Quando voc\u00ea seduz outra pessoa com a inten\u00e7\u00e3o de apenar machucar uma terceira, isso n\u00e3o deixa de ser uma trai\u00e7\u00e3o tamb\u00e9m para a outra.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o se esque\u00e7a que a pessoa que est\u00e1 ao seu lado tamb\u00e9m tem sentimentos, ou seja, se ela n\u00e3o sabe de suas reais inten\u00e7\u00f5es, seu problema pode ser ainda maior ao perceber que h\u00e1 um sentimento n\u00e3o correspondido e fazer a descoberta de que foi usado.<\/p>\n<h2>Rela\u00e7\u00e3o estagnada<\/h2>\n<p style=\"text-align: justify;\">Quando algu\u00e9m decide se vingar de uma trai\u00e7\u00e3o, mostra que o relacionamento n\u00e3o \u00e9 maduro o suficiente, quando n\u00e3o h\u00e1 cumplicidade e amizade entre o casal, pode sim rolar uma trai\u00e7\u00e3o, por falta de maturidade, e ambos podem acabar se vingando de modo que a rela\u00e7\u00e3o nunca sair\u00e1 do lugar. Os dois estar\u00e3o apenas se machucando.<\/p>\n<h2>Voc\u00ea se diminui<\/h2>\n<p style=\"text-align: justify;\">N\u00e3o importa o que aconteceu para que voc\u00ea queira se vingar, ao fazer isso voc\u00ea acabar\u00e1 se colocando no mesmo n\u00edvel da pessoa que te machucou. Se a atitude do parceiro te fez sofrer, fazer o que mesmo que ele fez n\u00e3o te faz melhor e nem te d\u00e1 moral para julg\u00e1-lo.<\/p>\n<h2 style=\"text-align: justify;\">Dica: siga em frente<\/h2>\n<p style=\"text-align: justify;\">Se n\u00e3o pode perdoar uma trai\u00e7\u00e3o, a melhor coisa a fazer \u00e9 se afastar e terminar a rela\u00e7\u00e3o, dessa forma n\u00e3o ir\u00e1 se machucar mais e ter\u00e1 tempo para curar suas feridas a ponto de confiar em um novo amor e come\u00e7ar de novo, por\u00e9m, dessa vez com mais maturidade, pois ter\u00e1 aprendido com as li\u00e7\u00f5es da rela\u00e7\u00e3o anterior.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Logomarca-fone-SE-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-109767\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Logomarca-fone-SE-4.jpg\" alt=\"Logomarca-fone-SE-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Logomarca-fone-SE-4.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2018\/01\/Logomarca-fone-SE-4-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a>\u00a0<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Mat\u00e9ria reproduzida do portal <a href=\"https:\/\/meuestilo.r7.com\/\">Meu Estilo<\/a>\/R7<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muitas vezes, quando uma pessoa \u00e9 tra\u00edda por algu\u00e9m que ela ama, a primeira coisa que pensa \u00e9 em dar o troco para poder sair por cima na rela\u00e7\u00e3o. Por\u00e9m, a verdade \u00e9 que esse ato impensado pode trazer consequ\u00eancias. N\u00e3o se esque\u00e7a que o doce sabor da vingan\u00e7a pode ser passageiro e o amargo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":109798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,8],"tags":[8092,8090,8091],"class_list":{"0":"post-109797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-esporte-e-cultura","9":"tag-evitar-traicao","10":"tag-traicao","11":"tag-veja-5-motivos"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/109797"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=109797"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/109797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/109798"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=109797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=109797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=109797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}