{"id":109267,"date":"2017-12-22T11:09:17","date_gmt":"2017-12-22T14:09:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=109267"},"modified":"2017-12-25T20:23:12","modified_gmt":"2017-12-25T23:23:12","slug":"codevasf-entrega-equipamentos-de-inclusao-produtiva-no-sertao-de-sergipe","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/codevasf-entrega-equipamentos-de-inclusao-produtiva-no-sertao-de-sergipe\/","title":{"rendered":"Codevasf entrega equipamentos de inclus\u00e3o produtiva no sert\u00e3o de Sergipe"},"content":{"rendered":"<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">Dia festivo para os sertanejos, nessa quinta-feira, 21. O senador Eduardo Amorim e o deputado federal Valadares Filho participaram de extensa agenda ao lado do superintendente da Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e do Parna\u00edba (Codevasf), C\u00e9sar Mandarino, e de grande parte da equipe da empresa, distribuindo equipamentos de inclus\u00e3o produtiva adquiridos com recursos de emendas parlamentares, entre m\u00e1quinas forrageiras, m\u00e1quinas de costura e kits de irriga\u00e7\u00e3o. O senador Ant\u00f4nio Carlos Valadares foi tamb\u00e9m um dos contempladores.<\/p>\n<div id=\"attachment_109268\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Codevasf8-e1513951393642.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109268\" class=\"size-full wp-image-109268\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Codevasf8-e1513951393642.jpg\" alt=\"Codevasf entrega equipamentos de inclus\u00e3o produtiva no sert\u00e3o de Sergipe\" width=\"599\" height=\"399\" \/><\/a><p id=\"caption-attachment-109268\" class=\"wp-caption-text\">Codevasf entrega equipamentos de inclus\u00e3o produtiva no sert\u00e3o de Sergipe (foto: ascom\/Amorim)<\/p><\/div>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">\u201cN\u00f3s fomos at\u00e9 as cidades de Feira Nova; Graccho Cardoso; Gararu; Porto da Folha; Monte Alegre e Po\u00e7o Redondo. Nossa maratona iniciou pelo sert\u00e3o, mas estaremos tamb\u00e9m na regi\u00e3o do Baixo S\u00e3o Francisco nessa sexta, 22, e daremos sequ\u00eancia no s\u00e1bado, 23. A gente n\u00e3o veio prometer nada, j\u00e1 trouxemos alguns benef\u00edcios em prol do fortalecimento da agricultura familiar. A nossa pretens\u00e3o para 2018 \u00e9 trazer muito mais\u201d, afirmou Eduardo.<\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">C\u00e9sar Mandarino explicou como aconteceu tramita\u00e7\u00e3o para distribui\u00e7\u00e3o das emendas encaminhadas para a Codevasf. \u201cEduardo encaminhou um montante de R$ 500 mil, que deu para adquirirmos 87 m\u00e1quinas forrageiras; equipamentos e materiais de piscicultura, entre balan\u00e7a digital, tanques-rede; barco de alum\u00ednio, boia de ancoragem, ox\u00edmetro, e tantos outros. N\u00f3s difundimos entre as cidades e manuseamos todo o processo por base das necessidades. Assim aconteceu com as emendas de Valadares\u201d, disse.<\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">Para Valadares Filho, essa foi uma a\u00e7\u00e3o conjunta que deu muito certo. \u201cSem as a\u00e7\u00f5es efetivas da Codevasf, sem as nossas emendas individuais, e sem o suporte dos gestores municipais, nada disso estaria acontecendo. \u00c9 uma vit\u00f3ria conjunta. Em nome do povo, para o povo\u201d, acrescentou o deputado.<\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">Leandro Santos, morador do povoado Imbira (Feira Nova) um dos contemplados para receber uma das m\u00e1quinas forrageira, explicou da necessidade de um pequeno produtor\/agricultor adquirir um equipamento para manuseio. \u201cA gente corta o milho no fac\u00e3o para moer. Agora a m\u00e1quina vai facilitar demais. Podemos plantar, e com o pr\u00f3prio produto faremos a ra\u00e7\u00e3o dos animais. Essa m\u00e1quina veio para nos d\u00e1 um grande suporte, e com certeza iremos lucrar muito mais para sobreviv\u00eancia\u201d, pontuou Leandro.<\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">Durante o corrente dia, participaram dos atos, os prefeitos dos munic\u00edpios beneficiados: Painho (Feira Nova); Cassinho de Quixabeira (Graccho Cardoso); Elizabeth Freire (Gararu); Miguel de Dr. Marcos (Porto da Folha); Nena de Luciano (Monte Alegre); Junior Chagas (Po\u00e7o Redondo); o deputado estadual Luciano Pimentel; vice-prefeitos, vereadores, secret\u00e1rios municipais, lideran\u00e7as da regi\u00e3o, e o povo.<\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\"><b>M\u00e1quina forrageira<\/b><\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\" style=\"text-align: justify;\">Essas m\u00e1quinas t\u00eam como fun\u00e7\u00e3o moer, picar, desintegrar e triturar uma grande variedade de produtos. Moe milho debulhado e milho com palha e sabugo, produzindo desde rol\u00e3o at\u00e9 fub\u00e1 grosso, fino e super fino. Pica cana, capins, sorgo e todas as esp\u00e9cies de forrageiras\u00a0e leguminosas. Desintegra produtos como cascas de cereais, ramas, ra\u00edzes, tub\u00e9rculos, etc.<b><\/b><\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Logomarca-fone-SE-4-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-109225\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Logomarca-fone-SE-4-2.jpg\" alt=\"Logomarca-fone-SE-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Logomarca-fone-SE-4-2.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/12\/Logomarca-fone-SE-4-2-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p class=\"m_1273486211392145740gmail-MsoNormal\"><em><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a>\u00a0<\/strong><\/em><\/p>\n<div>\n<div class=\"m_1273486211392145740gmail_signature\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<p><em>Da Assessoria de Imprensa<\/em><\/p>\n<div><em>Senador Eduardo Amorim (PSDB-SE)<\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dia festivo para os sertanejos, nessa quinta-feira, 21. O senador Eduardo Amorim e o deputado federal Valadares Filho participaram de extensa agenda ao lado do superintendente da Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e do Parna\u00edba (Codevasf), C\u00e9sar Mandarino, e de grande parte da equipe da empresa, distribuindo equipamentos de inclus\u00e3o produtiva adquiridos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":109268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1652,696,7714,7712,7713,4355],"class_list":{"0":"post-109267","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-codevasf","9":"tag-eduardo-amorim","10":"tag-equipamentos","11":"tag-inclusao-produtiva","12":"tag-sertao-de-sergipe","13":"tag-valadares"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/109267"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=109267"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/109267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/109268"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=109267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=109267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=109267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}