{"id":104980,"date":"2017-07-19T22:52:42","date_gmt":"2017-07-20T01:52:42","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=104980"},"modified":"2017-07-19T22:52:42","modified_gmt":"2017-07-20T01:52:42","slug":"tecnicos-do-inss-visitam-itaporanga-d-ajuda-para-implantacao-de-posto-de-atendimento","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/tecnicos-do-inss-visitam-itaporanga-d-ajuda-para-implantacao-de-posto-de-atendimento\/","title":{"rendered":"T\u00e9cnicos do INSS visitam Itaporanga D&#8217; Ajuda para implanta\u00e7\u00e3o de Posto de Atendimento"},"content":{"rendered":"<p style=\"text-align: justify;\">A Secretaria Municipal de Assist\u00eancia Social e Trabalho recebeu na manh\u00e3 desta quarta-feira, 19, a visita de t\u00e9cnicos da Previd\u00eancia Social para a implanta\u00e7\u00e3o do Posto de Atendimento do INSS na sede da Secretaria. Os atendimentos ser\u00e3o realizados no \u00f3rg\u00e3o at\u00e9 que seja conclu\u00edda a constru\u00e7\u00e3o da Ag\u00eancia do INSS no munic\u00edpio. A retomada da obra j\u00e1 est\u00e1 sendo planejada e iniciar\u00e1 o mais breve.<\/p>\n<div id=\"attachment_104981\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-104981\" class=\"size-full wp-image-104981\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/07\/IMG-20170719-WA0082-e1500515467663.jpg\" alt=\"T\u00e9cnicos do INSS visitam Secretaria de Assist\u00eancia Social para implanta\u00e7\u00e3o de Posto de Atendimento\" width=\"599\" height=\"401\" \/><p id=\"caption-attachment-104981\" class=\"wp-caption-text\">T\u00e9cnicos do INSS visitam Secretaria de Assist\u00eancia Social para implanta\u00e7\u00e3o de Posto de Atendimento (foto: ascom\/Itaporanga)<\/p><\/div>\n<p style=\"text-align: justify;\">A primeira-dama e secret\u00e1ria de Assist\u00eancia Social, Izabel Sobral, participou da visita e destacou a import\u00e2ncia da implanta\u00e7\u00e3o do servi\u00e7o no munic\u00edpio. \u201cA popula\u00e7\u00e3o de Itaporanga precisa desse servi\u00e7o e a presen\u00e7a de Posto de Atendimento do INSS aqui na cidade \u00e9 muito importante. Al\u00e9m disso, essa foi uma conquista da Administra\u00e7\u00e3o, atrav\u00e9s do prefeito Ot\u00e1vio Sobral, que in\u00fameras vezes esteve em Bras\u00edlia com o intuito de conseguir a disponibilidade alguns servi\u00e7os aos mun\u00edcipes, at\u00e9 que a Ag\u00eancia seja constru\u00edda e inaugurada\u201d, afirmou a secret\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">O chefe da Se\u00e7\u00e3o de Atendimento do INSS, Nivalmir D\u00f3ria, explica quais os servi\u00e7os ser\u00e3o realizados no Posto de Atendimento do INSS de Itaporanga. \u201cOs servi\u00e7os ser\u00e3o basicamente entrega de extratos, orienta\u00e7\u00f5es a popula\u00e7\u00e3o sobre benef\u00edcios do INSS e preparar, na verdade, para uma futura ag\u00eancia. Forneceremos tamb\u00e9m simula\u00e7\u00f5es de aposentadoria e diversos documentos que est\u00e3o dispon\u00edveis pelo site\u201d, explicou.<\/p>\n<p style=\"text-align: justify;\">Nivalmir enfatiza a estrutura que ser\u00e1 montada em uma das salas da Secretaria e diz que todos os outros servi\u00e7os ser\u00e3o dispon\u00edveis no munic\u00edpio quando a Ag\u00eancia for inaugurada. \u201cA ideia inicial \u00e9 que existam dois guich\u00eas de atendimento, um para entrega de senhas mais quinze acentos. Provavelmente esses atendimentos iniciem no final do m\u00eas de agosto e seja dispon\u00edvel de segunda a sexta em apenas um turno. Quando a ag\u00eancia for inaugurada, todos os benef\u00edcios ser\u00e3o fornecidos. Existe j\u00e1 uma obra de constru\u00e7\u00e3o de uma ag\u00eancia aqui no munic\u00edpio e esta ser\u00e1 retomada o mais breve\u201d, afirmou o chefe de Atendimento.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-104856\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/07\/Logo-fone-1-2-1-2-4-6-1.jpg\" alt=\"Logo-fone-1-2-1-2-4-6\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/07\/Logo-fone-1-2-1-2-4-6-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/07\/Logo-fone-1-2-1-2-4-6-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong><em>Acompanhe tamb\u00e9m o SE not\u00edcias no\u00a0<a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\">Twitter<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\">Facebook<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\">Instagram<\/a><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Por Ascom\/Itaporanga<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Assist\u00eancia Social e Trabalho recebeu na manh\u00e3 desta quarta-feira, 19, a visita de t\u00e9cnicos da Previd\u00eancia Social para a implanta\u00e7\u00e3o do Posto de Atendimento do INSS na sede da Secretaria. Os atendimentos ser\u00e3o realizados no \u00f3rg\u00e3o at\u00e9 que seja conclu\u00edda a constru\u00e7\u00e3o da Ag\u00eancia do INSS no munic\u00edpio. A retomada da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":104981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[4792,4093,4791],"class_list":{"0":"post-104980","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-implantacao-de-posto-de-atendimento","9":"tag-itaporanga-d-ajuda","10":"tag-tecnicos-do-inss"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/104980"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=104980"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/104980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/104981"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=104980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=104980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=104980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}