{"id":103289,"date":"2017-05-18T08:30:58","date_gmt":"2017-05-18T11:30:58","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=103289"},"modified":"2017-05-18T08:30:58","modified_gmt":"2017-05-18T11:30:58","slug":"ministro-do-stf-manda-afastar-aecio-neves-do-mandato-de-senador","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ministro-do-stf-manda-afastar-aecio-neves-do-mandato-de-senador\/","title":{"rendered":"Ministro do STF manda afastar A\u00e9cio Neves do mandato de senador"},"content":{"rendered":"<p style=\"text-align: justify;\">O ministro Edson Fachin, relator da Lava Jato no Supremo Tribunal Federal (STF), mandou afastar o presidente nacional do PSDB, A\u00e9cio Neves (MG), do mandato de senador. Endere\u00e7os ligados ao parlamentar tucano tamb\u00e9m s\u00e3o alvo de mandados de busca e apreens\u00e3o na manh\u00e3 desta quinta-feira (18) no Rio de Janeiro e em Bras\u00edlia.<\/p>\n<div id=\"attachment_102326\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-102326\" class=\"size-full wp-image-102326\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/04\/Aecio-Neves-senoticias-e1492095600164.jpg\" alt=\" Pol\u00edcia Federal cumpre nesta quinta (18) mandados de busca e apreens\u00e3o em endere\u00e7os ligados a A\u00e9cio. (Cristiano Mariz\/VEJA)\" width=\"599\" height=\"399\" \/><p id=\"caption-attachment-102326\" class=\"wp-caption-text\"><br \/>Pol\u00edcia Federal cumpre nesta quinta (18) mandados de busca e apreens\u00e3o em endere\u00e7os ligados a A\u00e9cio. (Foto: arquivo\/Cristiano Mariz\/VEJA)<\/p><\/div>\n<p style=\"text-align: justify;\">\nO relator da Lava Jato determinou ainda que o deputado federal Rodrigo Rocha Loures (PMDB-PR) seja afastado da C\u00e2mara.<\/p>\n<p style=\"text-align: justify;\">Reportagem publicada nesta quarta (17) no site do jornal &#8220;O Globo&#8221; revelou que o dono do frigor\u00edfico JBS Joesley Batista entregou \u00e0 Procuradoria Geral da Rep\u00fablica (PGR) uma grava\u00e7\u00e3o na qual A\u00e9cio pede ao empres\u00e1rio R$ 2 milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">No \u00e1udio gravado por Joesley, com dura\u00e7\u00e3o de cerca de 30 minutos, o presidente nacional do PSDB justifica o pedido dizendo que precisava da quantia para pagar sua defesa na Lava Jato. O senador tucano \u00e9 alvo de seis inqu\u00e9ritos no Supremo Tribunal Federal (STF) relacionados \u00e0 Lava Jato.<br \/>\nO G1 ainda n\u00e3o conseguiu contato nesta quinta-feira com a assessoria de A\u00e9cio Neves. Na noite desta quarta, a assessoria de imprensa do parlamentar mineiro afirmou que ele &#8220;est\u00e1 absolutamente tranquilo quanto \u00e0 corre\u00e7\u00e3o de todos os seus atos&#8221;.<\/p>\n<p style=\"text-align: justify;\">O Senado informou \u00e0 TV Globo que, at\u00e9 o momento, ainda n\u00e3o recebeu oficialmente o mandado do ministro do Supremo que mandar afastar A\u00e9cio do parlamento.<br \/>\nAl\u00e9m de afastar o senador do PSDB, Fachin expediu um um mandado de pris\u00e3o contra a irm\u00e3 e assessora de A\u00e9cio, Andr\u00e9a Neves. Segundo a TV Globo apurou, um procurador da Rep\u00fablica foi preso e h\u00e1 mandados contra pessoas ligadas ao deputado cassado e ex-presidente da C\u00e2mara Eduardo Cunha (PMDB-RJ).<br \/>\nNo Rio, est\u00e3o sendo cumpridos mandados de busca e apreens\u00e3o em tr\u00eas endere\u00e7os: os apartamentos de A\u00e9cio e da irm\u00e3 dele e o im\u00f3vel de Altair Alves Pinto, conhecido por ser bra\u00e7o direito de Cunha.<\/p>\n<p style=\"text-align: justify;\">O procurador da Rep\u00fablica \u00c2ngelo Goulart Villela, que atua no Tribunal Superior Eleitoral (TSE), foi preso na manh\u00e3 desta quinta pela Pol\u00edcia Federal. Agentes da PF cumpriram mandados de busca e apreens\u00e3o na sede da Corte eleitoral, em Bras\u00edlia.<\/p>\n<p style=\"text-align: justify;\">Fachin tamb\u00e9m expediu mandado de pris\u00e3o contra o advogado Willer Tomaz, que \u00e9 ligado a Eduardo Cunha.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-103179\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4-2.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4-2.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4-2-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b>Instagram<\/b><\/a><br \/>\nPor Camila Bomfim, <a href=\"http:\/\/g1.globo.com\/politica\/noticia\/fachin-manda-afastar-aecio-neves-do-mandato-de-senador.ghtml\">TV Globo<\/a>, Bras\u00edlia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Edson Fachin, relator da Lava Jato no Supremo Tribunal Federal (STF), mandou afastar o presidente nacional do PSDB, A\u00e9cio Neves (MG), do mandato de senador. Endere\u00e7os ligados ao parlamentar tucano tamb\u00e9m s\u00e3o alvo de mandados de busca e apreens\u00e3o na manh\u00e3 desta quinta-feira (18) no Rio de Janeiro e em Bras\u00edlia. O relator [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":102326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[2838,3658,2833,98,836],"class_list":{"0":"post-103289","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"tag-aecio-neves","9":"tag-afastar","10":"tag-ministro","11":"tag-senador","12":"tag-stf"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/103289"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=103289"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/103289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/102326"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=103289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=103289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=103289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}