{"id":102960,"date":"2017-05-08T09:25:21","date_gmt":"2017-05-08T12:25:21","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=102960"},"modified":"2017-05-08T11:29:51","modified_gmt":"2017-05-08T14:29:51","slug":"um-em-cada-tres-brasileiros-teve-amigo-ou-parente-assassinado-diz-pesquisa","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/um-em-cada-tres-brasileiros-teve-amigo-ou-parente-assassinado-diz-pesquisa\/","title":{"rendered":"Um em cada tr\u00eas brasileiros teve amigo ou parente assassinado, diz pesquisa"},"content":{"rendered":"<p style=\"text-align: justify;\">Um em cada tr\u00eas brasileiros (35%) teve amigos ou parentes assassinados, revela pesquisa do Instituto Datafolha, encomendada pelo F\u00f3rum Brasileiro de Seguran\u00e7a P\u00fablica (FBSP). Segundo o estudo, divulgado nesta segunda, 8, s\u00e3o cerca de 50 milh\u00f5es de brasileiros maiores de 16 anos que perderam uma pessoa pr\u00f3xima v\u00edtima de homic\u00eddio ou latroc\u00ednio (roubo seguido de morte).<\/p>\n<div id=\"attachment_102961\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-102961\" class=\"size-full wp-image-102961\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/trilogy-68582_960_720-e1494246460169.jpg\" alt=\"Imagem ilustrativa. Fonte: freepik\" width=\"599\" height=\"492\" \/><p id=\"caption-attachment-102961\" class=\"wp-caption-text\">Imagem ilustrativa. Fonte: freepik<\/p><\/div>\n<p style=\"text-align: justify;\">O \u00edndice dos que tiveram familiares ou amigos mortos violentamente \u00e9 maior entre os negros, 38%, enquanto entre os brancos \u00e9 de 27%. O levantamento mostra ainda que 12% da popula\u00e7\u00e3o maior de 16 anos, cerca de 16 milh\u00f5es de pessoas, tiveram algu\u00e9m do circulo afetivo morto por um agente de seguran\u00e7a, policial ou guarda municipal. Entre os jovens, de 16 a 24 anos, esse percentual chega a 17%.<\/p>\n<p style=\"text-align: justify;\"><strong>Feridos<\/strong><\/p>\n<p style=\"text-align: justify;\">O levantamento revela ainda que foram v\u00edtimas de ferimentos com armas de fogo 4% dos entrevistados, o que representa na proje\u00e7\u00e3o populacional de 5 milh\u00f5es de indiv\u00edduos com mais de 16 anos. As v\u00edtimas de facas e outras armas brancas somam 8%, ou 10 milh\u00f5es de pessoas. Al\u00e9m disso, 12% dos ouvidos disseram ter sofrido amea\u00e7as de morte.<\/p>\n<p style=\"text-align: justify;\">Quase todos os que responderam a pesquisa (94%) acreditam que o \u00edndice de homic\u00eddios no Brasil \u00e9 muito alto e 96% acham que todas as esferas de governo precisam se unir para reduzir a viol\u00eancia. Segundo o Anu\u00e1rio Brasileiro de Seguran\u00e7a P\u00fablica, que tamb\u00e9m \u00e9 elaborado pelo F\u00f3rum Brasileiro de Seguran\u00e7a P\u00fablica, foram registradas 58.383 mortes violentas no Brasil em 2015.<\/p>\n<p style=\"text-align: justify;\">Para a pesquisa divulgada hoje, foram ouvidas 2.065 pessoas em 150 munic\u00edpios de 3 a 8 de abril. Procurado pela Ag\u00eancia Brasil, o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica n\u00e3o comentou o estudo.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-102798\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4.jpg\" alt=\"SENOTICIAS\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/05\/Logo-fone-1-2-1-2-4-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b>Instagram<\/b><\/a><strong>.<\/strong><\/p>\n<p><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um em cada tr\u00eas brasileiros (35%) teve amigos ou parentes assassinados, revela pesquisa do Instituto Datafolha, encomendada pelo F\u00f3rum Brasileiro de Seguran\u00e7a P\u00fablica (FBSP). Segundo o estudo, divulgado nesta segunda, 8, s\u00e3o cerca de 50 milh\u00f5es de brasileiros maiores de 16 anos que perderam uma pessoa pr\u00f3xima v\u00edtima de homic\u00eddio ou latroc\u00ednio (roubo seguido de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":102961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2961],"tags":[51,370,2999,1303],"class_list":{"0":"post-102960","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-assassinatos","9":"tag-brasil","10":"tag-pesquisa","11":"tag-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/102960"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=102960"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/102960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/102961"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=102960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=102960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=102960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}