{"id":101546,"date":"2017-03-14T20:49:50","date_gmt":"2017-03-14T23:49:50","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=101546"},"modified":"2017-03-15T08:12:15","modified_gmt":"2017-03-15T11:12:15","slug":"itabaianinha-ganhara-escritorio-regional-da-junta-comercial","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/itabaianinha-ganhara-escritorio-regional-da-junta-comercial\/","title":{"rendered":"Itabaianinha ganhar\u00e1 Escrit\u00f3rio Regional da Junta Comercial"},"content":{"rendered":"<p style=\"text-align: justify;\">A Junta Comercial do Estado de Sergipe &#8211; Jucese &#8211; n\u00e3o para de investir na expans\u00e3o dos servi\u00e7os de Registro Empresarial por todas as regi\u00f5es do territ\u00f3rio sergipano. Ap\u00f3s selar, na semana passada, parceria com a Prefeitura de Tobias Barreto para a abertura de um Escrit\u00f3rio Regional no munic\u00edpio, a autarquia implantar\u00e1 tamb\u00e9m uma unidade de atendimento em Itabaianinha &#8211; cidade economicamente ativa, principalmente, nas \u00e1reas de confec\u00e7\u00e3o e da agricultura &#8211; junto com a Administra\u00e7\u00e3o Municipal.<\/p>\n<div id=\"attachment_101547\" style=\"width: 590px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/8fba1ef18d28bfb60f739b2126994885-e1489534463529.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-101547\" class=\"size-full wp-image-101547\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/8fba1ef18d28bfb60f739b2126994885-e1489534463529.jpg\" alt=\"Foto: Ascom\/Jucese\" width=\"580\" height=\"397\" \/><\/a><p id=\"caption-attachment-101547\" class=\"wp-caption-text\">Foto: Ascom\/Jucese<\/p><\/div>\n<p style=\"text-align: justify;\">At\u00e9 o final deste m\u00eas, mar\u00e7o, os moradores de Itabaianinha ganhar\u00e3o um Escrit\u00f3rio Regional da Jucese, que funcionar\u00e1 na Secretaria de Ind\u00fastria, Com\u00e9rcio e Turismo Municipal, na Sala do Empreendedor, de segunda a sexta-feira, gra\u00e7as \u00e0 parceria com a Prefeitura Municipal &#8211; que disponibilizar\u00e1 espa\u00e7o f\u00edsico e servidor para fazer atendimento ao p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Nesta ter\u00e7a-feira, 14, o presidente da Jucese, George da Trindade Gois, e o prefeito de Itabaianinha, Danilo Alves de Carvalho, o Danilo de Joaldo, assinaram o Termo de Coopera\u00e7\u00e3o T\u00e9cnica, que chancela a parceria para a abertura do ponto de atendimento na cidade. Tamb\u00e9m participaram do ato, o secret\u00e1rio-geral da Jucese, Marcelo Passos, o secret\u00e1rio de Ind\u00fastria e Com\u00e9rcio de Itabaianinha, Jairo Floriano, e a vereadora do munic\u00edpio, Maria Iv\u00e2nia dos Santos, a Ledinha.<\/p>\n<p style=\"text-align: justify;\">\u201cO Escrit\u00f3rio Regional da Jucese em Itabaianinha vai facilitar a vida do cidad\u00e3o do munic\u00edpio e beneficiar\u00e1 tamb\u00e9m os moradores das cidades vizinhas, como Umba\u00faba, Tomar do Geru, Cristin\u00e1polis e Arau\u00e1, que n\u00e3o precisar\u00e3o mais se deslocar at\u00e9 Aracaju ou uma unidade de atendimento da Junta Comercial mais longe para abrir sua empresa ou resolver quest\u00f5es relacionadas ao Registro Empresarial\u201d, destaca George Trindade.<\/p>\n<p style=\"text-align: justify;\">O prefeito Danilo tamb\u00e9m ressalta que a chegada do Escrit\u00f3rio Regional da Jucese transformar\u00e1 Itabaianinha numa cidade polo. \u201cTemos que incentivar o desenvolvimento econ\u00f4mico municipal, a aproxima\u00e7\u00e3o dos servi\u00e7os de registro de empresas do empreendedor, seja ele de pequeno, m\u00e9dio ou grande porte, e a implanta\u00e7\u00e3o deste ponto da Junta Comercial \u00e9 de import\u00e2ncia m\u00e1xima\u201d, afirma.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m da implanta\u00e7\u00e3o do Escrit\u00f3rio Regional da Jucese, Itabaianinha \u00e9 um dos 30 munic\u00edpios sergipanos que j\u00e1 fazem parte da Rede Nacional para a Simplifica\u00e7\u00e3o do Registro e da Legaliza\u00e7\u00e3o de Empresas e Neg\u00f3cios (Redesim)\/Agiliza Sergipe e est\u00e1 na fase de amplia\u00e7\u00e3o do projeto na cidade, com a inclus\u00e3o da Vigil\u00e2ncia Sanit\u00e1ria Municipal. \u201cParabenizo o prefeito Danilo pelo dinamismo e vis\u00e3o ao trabalhar pelo desenvolvimento econ\u00f4mico de Itabaianinha\u201d, diz George Trindade.<\/p>\n<p style=\"line-height: 14.25pt; text-align: justify;\"><strong><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/span><\/strong><span class=\"apple-converted-space\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">\u00a0<\/span><\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif';\">Twitter<\/span><\/b><\/a><strong><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">,<\/span><\/strong><span class=\"apple-converted-space\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">\u00a0<\/span><\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif';\">Facebook<\/span><\/b><span class=\"apple-converted-space\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: windowtext; text-decoration: none;\">\u00a0<\/span><\/b><\/span><\/a><strong><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">e no<\/span><\/strong><span class=\"apple-converted-space\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif'; color: #333333;\">\u00a0<\/span><\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b><span style=\"font-size: 10.0pt; font-family: 'Georgia','serif';\">Instagram<\/span><\/b><\/a><\/p>\n<p style=\"line-height: 14.25pt; text-align: justify;\"><a href=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101461\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p style=\"line-height: 14.25pt; text-align: justify;\">Da\u00a0Ascom\/Jucese<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>A Junta Comercial do Estado de Sergipe &#8211; Jucese &#8211; n\u00e3o para de investir na expans\u00e3o dos servi\u00e7os de Registro Empresarial por todas as regi\u00f5es do territ\u00f3rio sergipano. Ap\u00f3s selar, na semana passada, parceria com a Prefeitura de Tobias Barreto para a abertura de um Escrit\u00f3rio Regional no munic\u00edpio, a autarquia implantar\u00e1 tamb\u00e9m uma unidade [&hellip;]<\/p>\n","protected":false},"author":5618,"featured_media":101547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,38],"tags":[2517],"class_list":{"0":"post-101546","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-municipios","9":"tag-itabaianinha-ganhara-escritorio-regional-da-junta-comercial"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101546"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/5618"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=101546"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/101547"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=101546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=101546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=101546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}