{"id":101534,"date":"2017-03-14T16:22:55","date_gmt":"2017-03-14T19:22:55","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=101534"},"modified":"2017-03-14T16:22:55","modified_gmt":"2017-03-14T19:22:55","slug":"emenda-impositiva-para-o-canal-de-xingo-em-2018-e-defendida-por-eduardo-amorim","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/emenda-impositiva-para-o-canal-de-xingo-em-2018-e-defendida-por-eduardo-amorim\/","title":{"rendered":"Emenda impositiva para o Canal de Xing\u00f3 em 2018 \u00e9 defendida por Eduardo Amorim"},"content":{"rendered":"<p style=\"text-align: justify;\">O senador Eduardo Amorim (PSDB-SE) defendeu em entrevista de r\u00e1dio que a mesma emenda impositiva destinada \u00e0 Codevasf &#8211; Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e Parna\u00edba &#8211; em 2017 seja para o Canal de Xing\u00f3 em 2018. &#8220;No pr\u00f3ximo ano, defenderei que uma das duas emendas impositivas favore\u00e7a esse projeto t\u00e3o sonhado pelo homem do sert\u00e3o sergipano&#8221;, disse.<\/p>\n<p style=\"text-align: justify;\">\n<div id=\"attachment_101535\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-101535\" class=\"size-full wp-image-101535\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Eduardo-Amorim-SENOTICIAS-e1489519257736.jpg\" alt=\"senador Eduardo Amorim (PSDB-SE) defendeu em entrevista de r\u00e1dio que a mesma emenda impositiva destinada \u00e0 Codevasf Foto: Marcos Oliveira\/Ag\u00eancia Senado\" width=\"599\" height=\"399\" \/><p id=\"caption-attachment-101535\" class=\"wp-caption-text\">senador Eduardo Amorim (PSDB-SE) defendeu em entrevista de r\u00e1dio que a mesma emenda impositiva destinada \u00e0 Codevasf. (Foto: Marcos Oliveira\/Ag\u00eancia Senado)<\/p><\/div>\n<p style=\"text-align: justify;\">Para o senador Eduardo, o Governo de Sergipe deveria ter avan\u00e7ado com a indica\u00e7\u00e3o da emenda impositiva para o Canal de Xing\u00f3, mas n\u00e3o houve qualquer iniciativa. &#8220;Estamos propondo que essa pr\u00f3xima emenda seja para o sertanejo. Vamos trabalhar em parceria com a bancada baiana, pois o projeto tamb\u00e9m beneficiar\u00e1 alguns munic\u00edpios do noroeste do estado vizinho&#8221;, explicou o parlamentar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8220;Farei essa defesa em parceria com parlamentares da oposi\u00e7\u00e3o, j\u00e1 que n\u00e3o observamos qualquer movimenta\u00e7\u00e3o do atual Governo do Estado para com esse projeto. N\u00e3o adianta s\u00f3 falar, tem que agir. O atual Governo teve muitas oportunidades e n\u00e3o se lembrou do homem do campo&#8221;, disse.<\/p>\n<p style=\"text-align: justify;\">&#8220;A constru\u00e7\u00e3o do Canal de Xing\u00f3 vai representar uma nova vida para os sertanejos. Esta obra representar\u00e1 desenvolvimento para a agricultura irrigada, fortalecimento da pecu\u00e1ria, agroind\u00fastria, apicultura, piscicultura, entre outros pontos. Ser\u00e1 uma mudan\u00e7a para Canind\u00e9, Nossa Senhora da Gl\u00f3ria, Monte Alegre, Po\u00e7o Redondo, Porto da Folha e o Estado como um todo&#8221;, destacou o senador Eduardo Amorim.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Emendas impositivas<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ainda na entrevista, Eduardo explicou que as emendas impositivas s\u00e3o os recursos indicados por parlamentares federais com o prop\u00f3sito de atender a obras e projetos dos munic\u00edpios ou regi\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Atualmente, cada um dos deputados e senadores pode apresentar emendas ao Or\u00e7amento que somem at\u00e9 R$ 15 milh\u00f5es; j\u00e1 as emendas de bancada, sugeridas pelos estados; e de comiss\u00f5es s\u00e3o de valores mais volumosos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8220;As emendas de bancadas s\u00e3o de maior valor, elas geralmente atendem grandes obras, a exemplo daquela que ampliar\u00e1 o Aeroporto Santa Maria, em Aracaju, e a que ir\u00e1 revitalizar os per\u00edmetros irrigados do Baixo S\u00e3o Francisco: Propri\u00e1, Cotinguiba-Pindoba e Betume&#8221;, exemplificou Eduardo.<\/p>\n<p>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101461\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-2-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b>Instagram<\/b><\/a><\/p>\n<p><strong>Assessoria de Imprensa<br \/>\n<\/strong><em>Senador Eduardo Amorim (PSC-SE)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O senador Eduardo Amorim (PSDB-SE) defendeu em entrevista de r\u00e1dio que a mesma emenda impositiva destinada \u00e0 Codevasf &#8211; Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e Parna\u00edba &#8211; em 2017 seja para o Canal de Xing\u00f3 em 2018. &#8220;No pr\u00f3ximo ano, defenderei que uma das duas emendas impositivas favore\u00e7a esse projeto t\u00e3o sonhado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1652,696,2513,2512],"class_list":{"0":"post-101534","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-codevasf","9":"tag-eduardo-amorim","10":"tag-emenda-impositiva","11":"tag-senador-amorim"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101534"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=101534"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/101535"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=101534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=101534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=101534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}