{"id":101438,"date":"2017-03-13T07:01:58","date_gmt":"2017-03-13T10:01:58","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=101438"},"modified":"2017-03-13T07:01:58","modified_gmt":"2017-03-13T10:01:58","slug":"vereador-de-itaporanga-ivan-luciano-e-vitima-de-assalto","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/vereador-de-itaporanga-ivan-luciano-e-vitima-de-assalto\/","title":{"rendered":"Vereador de Itaporanga, Ivan Luciano, \u00e9 v\u00edtima de assalto"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\nO vereador Ivan Luciano Ara\u00fajo, mais conhecido por Ivan do Conselho Tutelar, do SD, foi v\u00edtima de assalto na noite de sexta-feira (10), quando visitava uma fam\u00edlia na rua Major Marcolino, localizado no centro da cidade de Itaporanga D&#8217;Ajuda, distante 29 Km da capital.<\/p>\n<div id=\"attachment_101441\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-101441\" class=\"size-full wp-image-101441\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/IMG_2746-e1489399133611.jpg\" alt=\" Vereador Ivan do Conselho  fazia visita a uma fam\u00edlia na rua Major Marcolino quando foi assaltado. (Foto: SE Not\u00edcias)\" width=\"599\" height=\"399\" \/><p id=\"caption-attachment-101441\" class=\"wp-caption-text\"><br \/>Vereador Ivan do Conselho fazia visita a uma fam\u00edlia na rua Major Marcolino quando foi assaltado. (Foto: SE Not\u00edcias)<\/p><\/div>\n<p style=\"text-align: justify;\">O vereador disse que conversava na sala de uma resid\u00eancia quando dois homens armados com um revolver, fizeram amea\u00e7as e levaram aparelhos celulares, bolsas, documentos pessoais e v\u00e1rios pertences, dele e outras duas pessoas que estavam na resid\u00eancia.<\/p>\n<p style=\"text-align: justify;\">O vereador postou em sua p\u00e1gina pessoal no Facebook uma mensagem em que diz que foi mais uma v\u00edtima da viol\u00eancia em Itaporanga D&#8217;Ajuda.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101307\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-1.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\/\">Facebook <\/a>e no <a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Reda\u00e7\u00e3o SE Not\u00edcias<\/strong><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O vereador Ivan Luciano Ara\u00fajo, mais conhecido por Ivan do Conselho Tutelar, do SD, foi v\u00edtima de assalto na noite de sexta-feira (10), quando visitava uma fam\u00edlia na rua Major Marcolino, localizado no centro da cidade de Itaporanga D&#8217;Ajuda, distante 29 Km da capital. O vereador disse que conversava na sala de uma resid\u00eancia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-101438","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101438"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=101438"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/101441"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=101438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=101438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=101438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}