{"id":101257,"date":"2017-03-07T08:53:17","date_gmt":"2017-03-07T11:53:17","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=101257"},"modified":"2017-03-07T08:54:54","modified_gmt":"2017-03-07T11:54:54","slug":"na-alese-comandante-da-policia-militar-destaca-reducao-dos-numeros-da-violencia","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/na-alese-comandante-da-policia-militar-destaca-reducao-dos-numeros-da-violencia\/","title":{"rendered":"Na Alese: Comandante da Pol\u00edcia Militar destaca redu\u00e7\u00e3o dos n\u00fameros da viol\u00eancia"},"content":{"rendered":"<p style=\"text-align: justify;\">Um dos homenageados na Sess\u00e3o Especial em Comemora\u00e7\u00e3o pelos 182 anos da Pol\u00edcia Militar de Sergipe, promovida pela Assembleia Legislativa, atrav\u00e9s de indica\u00e7\u00e3o do deputado estadual Capit\u00e3o Samuel (PSL), o comandante da PM\/SE, coronel Marcony Cabral Santos, destacou o trabalho que vem sendo desenvolvido pelas for\u00e7as de seguran\u00e7a do Estado para conter a viol\u00eancia.<\/p>\n<div id=\"attachment_101258\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-101258\" class=\"size-full wp-image-101258\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Comandante-da-PM-na-Alese-SENOTICIAS-e1488887545255.jpg\" alt=\"Coronel Marcondes destaca redu\u00e7\u00e3o dos n\u00fameros da viol\u00eancia. (Foto: C\u00e9sar de Oliveira)\" width=\"599\" height=\"272\" \/><p id=\"caption-attachment-101258\" class=\"wp-caption-text\">Coronel Marcondes destaca redu\u00e7\u00e3o dos n\u00fameros da viol\u00eancia. (Foto: C\u00e9sar de Oliveira)<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cA sensa\u00e7\u00e3o para n\u00f3s \u00e9 de dever cumprido. Estendo aqui o meu agradecimento a cada policial militar deste Estado, seja no interior mais distante ou nos bairros mais perif\u00e9ricos da nossa capital que est\u00e3o nas ruas lutando bravamente, cumprindo com sua obriga\u00e7\u00e3o e levando seguran\u00e7a para a popula\u00e7\u00e3o\u201d, destacou o Coronel ao agradecer a homenagem da Assembleia Legislativa.<\/p>\n<p style=\"text-align: justify;\">Marcony Cabral enfatizou que os n\u00fameros da viol\u00eancia come\u00e7am a cair no Estado. \u201cOs registros est\u00e3o sendo controlados. E isso se deve muito ao trabalho das for\u00e7as de seguran\u00e7a do nosso Estado, sob o comando e a integra\u00e7\u00e3o capitaneada pelo secret\u00e1rio Jo\u00e3o Batista. Nos \u00faltimos dois meses n\u00f3s conseguimos reduzir esses n\u00fameros\u201d.<\/p>\n<p style=\"text-align: justify;\">Por fim ele tratou dos homens da For\u00e7a Nacional que chegaram para ajudar no combate \u00e0 viol\u00eancia. \u201cToda ajuda \u00e9 muito bem vinda, ainda mais quando ela \u00e9 do ponto de vista qualitativo. A presen\u00e7a ostensiva \u00e9 apenas um detalhe. N\u00f3s temos investimentos, recebemos materiais, vamos investir em programas sociais para trazer a sensa\u00e7\u00e3o de seguran\u00e7a. S\u00e3o companheiros de fardas de outros Estados, mas \u00e9 o trabalho da Pol\u00edcia Civil e da Pol\u00edcia Militar nas ruas que tem dado as respostas que a sociedade tanto deseja\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Homenagens<\/strong><\/p>\n<p style=\"text-align: justify;\">Foram homenageados os Coron\u00e9is Marcony Cabral Santos e Jos\u00e9 P\u00e9ricles Menezes de Oliveira; o Major Jos\u00e9 Alc\u00e2ntara dos Santos; os Capit\u00e3es Dielson Silva Ara\u00fajo e Evangelina de Deus Santos; os Tenentes Manoel C\u00e9sar dos Santos e Eraldo Oliveira de Almeida; al\u00e9m dos Sargentos Meriele Santos de Freitas, Cleverton Pereira de Oliveira, Sandro Soares Oliveira, No\u00e9liton Francisco dos Santos, Rufino de Souza Neto, Ant\u00f4nio Carlos Bezerra e Di\u00f3genes Nunes dos Santos.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-101146\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/03\/Logo-fone-1-2-1-2-4-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b>Instagram<\/b><\/a><\/p>\n<p><em>Por Ag\u00eancia de Not\u00edcias Alese.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos homenageados na Sess\u00e3o Especial em Comemora\u00e7\u00e3o pelos 182 anos da Pol\u00edcia Militar de Sergipe, promovida pela Assembleia Legislativa, atrav\u00e9s de indica\u00e7\u00e3o do deputado estadual Capit\u00e3o Samuel (PSL), o comandante da PM\/SE, coronel Marcony Cabral Santos, destacou o trabalho que vem sendo desenvolvido pelas for\u00e7as de seguran\u00e7a do Estado para conter a viol\u00eancia. \u201cA [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-101257","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101257"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=101257"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/101257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/101258"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=101257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=101257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=101257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}