{"id":100309,"date":"2017-02-07T07:11:50","date_gmt":"2017-02-07T10:11:50","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=100309"},"modified":"2017-02-07T21:49:52","modified_gmt":"2017-02-08T00:49:52","slug":"ndicado-ao-stf-alexandre-de-moraes-e-afastado-do-ministerio-da-justica-por-30-dias","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/ndicado-ao-stf-alexandre-de-moraes-e-afastado-do-ministerio-da-justica-por-30-dias\/","title":{"rendered":"Indicado ao STF, Alexandre de Moraes \u00e9 afastado do Minist\u00e9rio da Justi\u00e7a por 30 dias"},"content":{"rendered":"<p style=\"text-align: justify;\">Indicado pelo presidente Michel Temer para ocupar o lugar de Teori Zavascki (que morreu no m\u00eas passado) no Supremo Tribunal Federal (STF), Alexandre de Moraes foi afastado do Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, pelo prazo de 30 dias, para tratar de assuntos particulares. O afastamento, autorizado pelo presidente Michel Temer, foi publicado no Di\u00e1rio Oficial da Uni\u00e3o desta ter\u00e7a-feira (7), informa o\u00a0<a href=\"http:\/\/g1.globo.com\/politica\/noticia\/alexandre-de-moraes-e-afastado-do-ministerio-da-justica-por-30-dias.ghtml\"><strong>G1<\/strong><\/a><\/p>\n<div id=\"attachment_100310\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100310\" class=\"size-full wp-image-100310\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/02\/Alexandre-Morais-SENOTICIAS-e1486462200655.jpg\" alt=\"O ministro da Justi\u00e7a Alexandre de Moraes (Foto: Andressa Anholete \/ AFP Photo)\" width=\"599\" height=\"399\" \/><p id=\"caption-attachment-100310\" class=\"wp-caption-text\">O ministro da Justi\u00e7a Alexandre de Moraes (Foto: Andressa Anholete \/ AFP Photo)<\/p><\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"19\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Tamb\u00e9m foi publicada a mensagem de Temer que encaminha a indica\u00e7\u00e3o de Moraes ao STF para aprecia\u00e7\u00e3o do Senado.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"78\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">A indica\u00e7\u00e3o de Moraes aconteceu na segunda (6), informou o porta-voz da Presid\u00eancia, Alexandre Parola. \u201cO presidente da Rep\u00fablica Michel Temer decidiu submeter \u00e0 aprova\u00e7\u00e3o do Senado Federal o nome do ministro de Estado da Justi\u00e7a e da Seguran\u00e7a P\u00fablica, Alexandre de Moraes, para o cargo de ministro do Supremo Tribunal Federal. As s\u00f3lidas credenciais acad\u00eamicas e profissionais do doutor Alexandre de Moraes o qualificam para as elevadas responsabilidades do cargo de ministro da Suprema Corte do Brasil\u201d.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"47\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Com a indica\u00e7\u00e3o, Alexandre de Moraes ser\u00e1 submetido a uma sabatina na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) do Senado \u2013 os integrantes do colegiado ainda n\u00e3o foram definidos, mas a expectativa do presidente da Casa, Eun\u00edcio Oliveira, \u00e9 que a comiss\u00e3o seja instalada nesta quarta (8).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"20\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em seguida, se a comiss\u00e3o aprovar o nome do ministro, a indica\u00e7\u00e3o ter\u00e1 de ser votada pelo plen\u00e1rio do Senado.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com a assessoria do Minist\u00e9rio da Justi\u00e7a, Alexandre de Moraes pediu uma licen\u00e7a de 30 dias at\u00e9 ser sabatinado no Senado. \u201cA inten\u00e7\u00e3o \u00e9 n\u00e3o misturar temas do Minist\u00e9rio com as quest\u00f5es relativas \u00e0 sua indica\u00e7\u00e3o\u201d, informou a assessoria em nota.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"19\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Como ainda n\u00e3o foi anunciado o novo titular da pasta, o substituto tempor\u00e1rio ser\u00e1 o atual secret\u00e1rio-executivo, Jos\u00e9 Levi.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"53\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Alexandre de Moraes tem 48 anos, \u00e9 filiado ao PSDB e foi secret\u00e1rio de Seguran\u00e7a P\u00fablica do estado de S\u00e3o Paulo no governo Geraldo Alckmin. Para se tornar ministro, ele ter\u00e1 de se desfiliar do partido, conforme determina a Constitui\u00e7\u00e3o. O artigo 95 diz que \u00e9 vedado ao juiz \u201cdedicar-se \u00e0 atividade pol\u00edtico-partid\u00e1ria\u201d.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"24\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Pela lei atual, um ministro do Supremo pode ocupar uma cadeira no tribunal at\u00e9 completar 75 anos de idade, quando dever\u00e1 se aposentar compulsoriamente.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"23\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O STF \u00e9 composto por 11 ministros, mas, desde a morte de Teori Zavascki, em 19 de janeiro, vem funcionando com dez ministros.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"22\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Nesta segunda, antes de o governo oficializar a indica\u00e7\u00e3o para o STF, Moraes se reuniu com o presidente Michel Temer no Planalto.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"5\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Atua\u00e7\u00e3o no Minist\u00e9rio da Justi\u00e7a<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"42\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Moraes deixou a Secretaria de Seguran\u00e7a P\u00fablica de S\u00e3o Paulo em maio do ano passado, quando passou a comandar o Minist\u00e9rio da Justi\u00e7a, a convite do presidente Michel Temer &#8211; \u00e0 \u00e9poca, Temer havia assumido o governo no lugar de Dilma Rousseff.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"27\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ao assumir o Minist\u00e9rio da Justi\u00e7a, Moraes passou a atuar, ao lado de outros ministros, em a\u00e7\u00f5es para garantir a seguran\u00e7a na Olimp\u00edada do Rio de Janeiro.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"21\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u00c0 \u00e9poca, Moraes anunciou, por exemplo, uma opera\u00e7\u00e3o da Pol\u00edcia Federal que prendeu dez suspeitos de planejar terrorismo no evento esportivo.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"73\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Em setembro, o ministro se envolveu em uma pol\u00eamica em rela\u00e7\u00e3o \u00e0 Opera\u00e7\u00e3o Lava Jato. No dia anterior \u00e0 pris\u00e3o do ex-ministro petista Ant\u00f4nio Palocci, Moraes havia dito em Ribeir\u00e3o Preto (SP) que haveria mais opera\u00e7\u00e3o da Pol\u00edcia Federal naquela semana. A fala de Moraes gerou uma repercuss\u00e3o negativa, a ponto de a Comiss\u00e3o de \u00c9tica P\u00fablica da presid\u00eancia abrir um processo para apurar a conduta do ministro &#8211; o caso foi arquivado.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Crise carcer\u00e1ria<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Desde o in\u00edcio deste ano, a pasta comandada por Moraes ficou em evid\u00eancia no notici\u00e1rio com a crise do sistema prisional.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"43\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">As diversas rebeli\u00f5es em pres\u00eddios do pa\u00eds, que resultaram em dezenas de mortes de presos, levaram o ministro a visitar cidades onde havia ocorrido os motins e a autorizar homens da For\u00e7a Nacional a fazer a seguran\u00e7a nos estados em situa\u00e7\u00e3o mais emergencial.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"56\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Tamb\u00e9m em decorr\u00eancia das rebeli\u00f5es, o ministro anunciou o Plano Nacional de Seguran\u00e7a, que j\u00e1 vinha sendo elaborado entre o Minist\u00e9rio da Justi\u00e7a e outros \u00f3rg\u00e3os do governo. O plano tem medidas em tr\u00eas \u00e1reas consideradas cruciais pelo governo: o combate a homic\u00eddios, combate ao tr\u00e1fico e ao crime organizado, e a moderniza\u00e7\u00e3o do sistema prisional.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"24\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na semana passada, Moraes viajou para Natal e Aracaju para iniciar a\u00e7\u00f5es do plano nessas duas capitais, consideradas em situa\u00e7\u00e3o mais emergencial pelo governo.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"2\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Lava Jato<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"36\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Embora tenha sido indicado por Temer para ocupar a vaga de Teori Zavascki, Alexandre de Moraes, se tiver o nome aprovado pelo Senado, n\u00e3o herdar\u00e1 a relatoria dos processos relacionados \u00e0 Opera\u00e7\u00e3o Lava Jato na Corte.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"29\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Isso porque, na semana passada, o ministro Luiz Edson Fachin foi sorteado novo relator. Se vier a ocupar a vaga no Supremo, Moraes, entretanto, ser\u00e1 o revisor dos processos.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"1\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Perfil<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"76\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Formado em 1990 pela Faculdade de Direito da Universidade de S\u00e3o Paulo (USP), onde tamb\u00e9m \u00e9 professor associado desde 2002, Alexandre de Moraes teve uma carreira pol\u00edtica de ascens\u00e3o r\u00e1pida, tendo atuado como secret\u00e1rio municipal de Transportes da cidade de S\u00e3o Paulo (de 2007 a 2010), e secret\u00e1rio estadual do governador de S\u00e3o Paulo, Geraldo Alckmin, em duas pastas: de Seguran\u00e7a P\u00fablica (2014 a 2015), e da Justi\u00e7a e da Defesa da Cidadania (2002 a 2005).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Concluiu doutorado em Direito pela USP em 2000 e atuou tamb\u00e9m como professor da Universidade Presbiteriana Mackenzie e das Escolas Superior do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo e Paulista de Magistratura. Atualmente, sua inscri\u00e7\u00e3o na Ordem dos Advogados do Brasil (OAB) S\u00e3o Paulo est\u00e1 como &#8220;inativa, sob licen\u00e7a&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"53\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Pouco antes de assumir a Secretaria da Seguran\u00e7a, em 2014, Moraes defendeu Eduardo Cunha (PMDB-RJ), ex-presidente da C\u00e2mara dos Deputados, em uma a\u00e7\u00e3o sobre uso de documento falso em que conseguiu a absolvi\u00e7\u00e3o do peemedebista. Cunha teve o mandato cassado e est\u00e1 preso preventivamente em Curitiba (Paran\u00e1), no \u00e2mbito da Opera\u00e7\u00e3o Lava Jato.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"72\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda como advogado, Alexandre de Moraes atuou em processos da \u00e1rea civil da Transcooper, uma cooperativa investigada pela Pol\u00edcia Civil e o Minist\u00e9rio P\u00fablico de S\u00e3o Paulo como suspeita em movimenta\u00e7\u00f5es de lavagem de dinheiro e corrup\u00e7\u00e3o engendrado envolvendo a fac\u00e7\u00e3o que atua dentro e fora dos pres\u00eddios de S\u00e3o Paulo, o PCC (Primeiro Comando da Capital). \u00c0 \u00e9poca, a banca de advocacia dele havia renunciado aos processos quando assumiu cargos p\u00fablicos.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"55\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Iniciou sua carreira como promotor de Justi\u00e7a no Minist\u00e9rio P\u00fablico de S\u00e3o Paulo em 1991, cargo que exerceu at\u00e9 2002, quando foi indicado por Alckmin secret\u00e1rio da Justi\u00e7a e da Defesa da Cidadania do Estado de S\u00e3o Paulo, cargo que deixou em maio de 2005, quando foi eleito para o Conselho Nacional de Justi\u00e7a (CNJ).<\/p>\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-100145\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/02\/Logo-fone-1-2-1-2.jpg\" alt=\"Logo-fone-1-2-1-2\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/02\/Logo-fone-1-2-1-2.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/02\/Logo-fone-1-2-1-2-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/twitter.com\/Senoticias\" target=\"_blank\"><b>Twitter<\/b><\/a><strong>,<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.facebook.com\/senoticias1\" target=\"_blank\"><b>Facebook<\/b><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><\/a><strong>e no<\/strong><span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><a href=\"https:\/\/www.instagram.com\/senoticias\/\" target=\"_blank\"><b>Instagram<\/b><\/a><\/p>\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\"><em>Informa\u00e7\u00f5es do G1<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Indicado pelo presidente Michel Temer para ocupar o lugar de Teori Zavascki (que morreu no m\u00eas passado) no Supremo Tribunal Federal (STF), Alexandre de Moraes foi afastado do Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, pelo prazo de 30 dias, para tratar de assuntos particulares. O afastamento, autorizado pelo presidente Michel Temer, foi publicado no Di\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":100310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,6],"tags":[],"class_list":{"0":"post-100309","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/100309"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=100309"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/100309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/100310"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=100309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=100309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=100309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}