{"id":100091,"date":"2017-01-31T13:50:47","date_gmt":"2017-01-31T16:50:47","guid":{"rendered":"http:\/\/senoticias.com.br\/se\/?p=100091"},"modified":"2017-01-31T13:50:47","modified_gmt":"2017-01-31T16:50:47","slug":"conheca-os-candidatos-a-presidencia-da-camara-dos-deputados","status":"publish","type":"post","link":"https:\/\/senoticias.com.br\/se\/conheca-os-candidatos-a-presidencia-da-camara-dos-deputados\/","title":{"rendered":"Conhe\u00e7a os candidatos \u00e0 presid\u00eancia da C\u00e2mara dos Deputados"},"content":{"rendered":"<p style=\"text-align: justify;\">Nesta quinta-feira (2), a C\u00e2mara dos Deputados escolhe quem ficar\u00e1 \u00e0 frente da Casa pelos pr\u00f3ximos dois anos. As inscri\u00e7\u00f5es para se candidatar ao cargo est\u00e3o abertas at\u00e9 as 23h desta quarta-feira (1\u00ba). At\u00e9 o momento, cinco deputados devem disputar o cargo.<\/p>\n<div id=\"attachment_100099\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100099\" class=\"size-full wp-image-100099\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/SENot\u00edcias-noticia_217358_img1_camara.jpg\" alt=\"A elei\u00e7\u00e3o come\u00e7a \u00e0s 9h desta quinta-feira, (2).  (Foto: Reprodu\u00e7\u00e3o) \" width=\"599\" height=\"370\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/SENot\u00edcias-noticia_217358_img1_camara.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/SENot\u00edcias-noticia_217358_img1_camara-300x185.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><p id=\"caption-attachment-100099\" class=\"wp-caption-text\">A elei\u00e7\u00e3o come\u00e7a \u00e0s 9h desta quinta-feira, (2). (Foto: Reprodu\u00e7\u00e3o)<\/p><\/div>\n<p style=\"text-align: justify;\">Entre os candidatos, quatro s\u00e3o considerados de partidos da base aliada do governo: Rodrigo Maia (DEM-RJ) \u2013 que n\u00e3o se lan\u00e7ou oficialmente candidato \u2013, Jovair Arantes (PTB-GO), Rog\u00e9rio Rosso (PSD-DF) e J\u00falio Delgado (PSB-MG). Andr\u00e9 Figueiredo (PDT-CE) \u00e9 da oposi\u00e7\u00e3o. Conhe\u00e7a mais sobre cada um dos candidatos \u00e0 presid\u00eancia da C\u00e2mara.<\/p>\n<div id=\"attachment_100093\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100093\" class=\"size-medium wp-image-100093\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1056510-edit_03699-300x173.jpg\" alt=\"Maia foi eleito presidente da C\u00e2mara em julho de 2016, ap\u00f3s a cassa\u00e7\u00e3o do deputado Eduardo Cunha (Foto: Marcelo Camargo\/Ag\u00eancia Brasil)\" width=\"300\" height=\"173\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1056510-edit_03699-300x173.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1056510-edit_03699.jpg 599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-100093\" class=\"wp-caption-text\">Maia foi eleito presidente da C\u00e2mara em julho de 2016, ap\u00f3s a cassa\u00e7\u00e3o do deputado Eduardo Cunha (Foto: Marcelo Camargo\/Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Rodrigo Maia<\/strong><\/p>\n<p style=\"text-align: justify;\">Embora n\u00e3o tenha se lan\u00e7ado oficialmente para o cargo, Maia \u00e9 um dos favoritos na disputa. Sua candidatura no entanto \u00e9 cercada de pol\u00eamicas. Como foi o \u00faltimo presidente da Casa, ele n\u00e3o poderia, na teoria, concorrer novamente ao cargo. Ontem (30), os quatro deputados que disputam a presid\u00eancia com Maia recorreram ao Supremo para tentar barrar sua candidatura, j\u00e1 que o Artigo 57 da Constitui\u00e7\u00e3o Federal diz que \u00e9 \u201cvedada a recondu\u00e7\u00e3o para o mesmo cargo na elei\u00e7\u00e3o [da Mesa Diretora] imediatamente subsequente\u201d.<\/p>\n<p style=\"text-align: justify;\">Rodrigo Maia, por\u00e9m, segue o entendimento de que n\u00e3o teria realizado um mandato completo. Ele foi eleito presidente da C\u00e2mara em julho de 2016 para um mandato-tamp\u00e3o, ap\u00f3s a cassa\u00e7\u00e3o do ent\u00e3o presidente da Casa, deputado Eduardo Cunha (PMDB-RJ).<\/p>\n<p style=\"text-align: justify;\">A discuss\u00e3o sobre a legalidade da candidatura de Maia passou pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da C\u00e2mara (CCJ) e pelo Supremo Tribunal Federal (STF). Na CCJ, o parecer foi favor\u00e1vel \u00e0 candidatura. J\u00e1 o STF ter\u00e1 uma defini\u00e7\u00e3o s\u00f3 ap\u00f3s as elei\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">O Executivo est\u00e1 de olho nas elei\u00e7\u00f5es porque pretende colocar mat\u00e9rias consideradas primordiais em vota\u00e7\u00e3o neste ano. Entre as mat\u00e9rias que o Executivo quer discutir est\u00e3o a reforma da Previd\u00eancia e a reforma Trabalhista.<\/p>\n<p style=\"text-align: justify;\">Nascido no Chile, ele \u00e9 filho do ex-prefeito do Rio de Janeiro C\u00e9sar Maia. A trajet\u00f3ria dele na C\u00e2mara dos Deputados come\u00e7ou em 1999 e esta \u00e9 sua quinta legislatura. Antes de ser presidente da Casa, foi l\u00edder do PFL (2003-2005) e presidente de diversas comiss\u00f5es tem\u00e1ticas da C\u00e2mara.<\/p>\n<div id=\"attachment_100094\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100094\" class=\"size-medium wp-image-100094\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1008568-28032016dsc_1834--300x173.jpg\" alt=\"Jovair Arantes defende o fim de vota\u00e7\u00f5es noturnas e a independ\u00eancia da C\u00e2mara (Foto: Valter Campanato\/Ag\u00eancia Brasil)\" width=\"300\" height=\"173\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1008568-28032016dsc_1834--300x173.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1008568-28032016dsc_1834-.jpg 599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-100094\" class=\"wp-caption-text\">Jovair Arantes defende o fim de vota\u00e7\u00f5es noturnas e a independ\u00eancia da C\u00e2mara (Foto: Valter Campanato\/Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Jovair Arantes<\/strong><\/p>\n<p style=\"text-align: justify;\">Dentre os postulantes \u00e0 cadeira de presidente, Jovair Arantes \u00e9 o candidato com mais tempo de Casa: est\u00e1 em sua sexta legislatura e ocupa a vaga desde 1995.<\/p>\n<p style=\"text-align: justify;\">Assim como Rosso, Jovair \u00e9 do chamado Bloco do Centr\u00e3o e vai disputar os votos da base com Maia e Rosso. Durante toda a campanha, ele tem viajado \u00e0s bases dos deputados em busca de apoio.<\/p>\n<p style=\"text-align: justify;\">Em sua plataforma, defende o fim de vota\u00e7\u00f5es noturnas e a independ\u00eancia da C\u00e2mara. \u201cVou colocar as mat\u00e9rias importantes que o governo federal quer que coloque. Mas quem vai aprovar ou n\u00e3o s\u00e3o os deputados\u201d, disse em campanha.<\/p>\n<p style=\"text-align: justify;\">Na C\u00e2mara, Jovair foi o relator da comiss\u00e3o especial que analisou o pedido de impeachment da presidente Dilma Roussef, em 2016. Ele chegou a ensaiar uma candidatura para a presid\u00eancia da Casa no ano passado, mas desistiu para apoiar Rog\u00e9rio Rosso.<\/p>\n<div id=\"attachment_100096\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100096\" class=\"size-medium wp-image-100096\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1042376-06-09-2016_pzzb4036-300x173.jpg\" alt=\"Rosso foi o deputado mais votado do Distrito Federal (Foto: Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil)\" width=\"300\" height=\"173\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1042376-06-09-2016_pzzb4036-300x173.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1042376-06-09-2016_pzzb4036.jpg 599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-100096\" class=\"wp-caption-text\">Rosso foi o deputado mais votado do Distrito Federal (Foto: Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Rog\u00e9rio Rosso<\/strong><\/p>\n<p style=\"text-align: justify;\">Derrotado por Rodrigo Maia no segundo turno da elei\u00e7\u00e3o para a presid\u00eancia da C\u00e2mara em 2016, Rosso chegou a suspender a campanha e liberou os deputados do partido para votarem em qualquer candidato. Ontem (30), por\u00e9m, retomou a campanha, depois de ser informado que o pedido de impugna\u00e7\u00e3o da campanha de Maia n\u00e3o est\u00e1 na pauta do STF nesta semana.<\/p>\n<p style=\"text-align: justify;\">A carreira pol\u00edtica de Rosso tamb\u00e9m \u00e9 marcada por um mandato tamp\u00e3o como governador do Distrito Federal. Ele foi escolhido em 2010 por elei\u00e7\u00e3o indireta e substituiu, por oito meses, Jos\u00e9 Roberto Arruda \u2013 afastado por den\u00fancias de corrup\u00e7\u00e3o. Um ano depois, assumiu uma vaga de deputado federal \u2013 Rosso era suplente de Tadeu Filipelli \u2013 e ficou at\u00e9 2012.<\/p>\n<p style=\"text-align: justify;\">Em 2014, Rosso foi o segundo deputado mais votado do Distrito Federal. Na C\u00e2mara, presidiu a Comiss\u00e3o Especial que analisou o pedido de impeachment de Dilma Rousseff.<\/p>\n<p style=\"text-align: justify;\">Como plataforma de campanha, Rosso defende que o legislativo tenha \u201cmais autonomia\u201d em rela\u00e7\u00e3o \u00e0 pauta discutida em Plen\u00e1rio. \u201cNem 3% das proposi\u00e7\u00f5es vem do Legislativo. A C\u00e2mara tem sido reativa e n\u00e3o propositiva\u201d, disse durante transmiss\u00e3o que fez na rede social Facebook ao lan\u00e7ar sua campanha. Rosso tamb\u00e9m defende que sess\u00f5es comecem mais cedo e acabem mais cedo para as vota\u00e7\u00f5es n\u00e3o se extenderem pela madrugada.<\/p>\n<div id=\"attachment_100097\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100097\" class=\"size-medium wp-image-100097\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1014644-20042016dsc_8777--300x173.jpg\" alt=\"Andr\u00e9 Figueiredo \u00e9 o principal nome dos congressistas de oposi\u00e7\u00e3o (Foto:  Antonio Cruz\/ Ag\u00eancia Brasil)\" width=\"300\" height=\"173\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1014644-20042016dsc_8777--300x173.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1014644-20042016dsc_8777-.jpg 599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-100097\" class=\"wp-caption-text\">Andr\u00e9 Figueiredo \u00e9 o principal nome dos congressistas de oposi\u00e7\u00e3o (Foto: Antonio Cruz\/ Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Andr\u00e9 Figueiredo<\/strong><\/p>\n<p style=\"text-align: justify;\">Concorrendo contra tr\u00eas candidatos da base aliada do governo, Andr\u00e9 Figueiredo \u00e9 o principal nome dos congressistas de oposi\u00e7\u00e3o a Michel Temer. \u00daltimo a lan\u00e7ar candidatura, Figueiredo espera contar com o apoio do PT, PCdoB, PSOL, Rede e de parte dos deputados do PSB.<\/p>\n<p style=\"text-align: justify;\">Durante o lan\u00e7amento da candidatura, Figueiredo disse que deseja mudar a rela\u00e7\u00e3o da Casa com o Executivo: \u201cOu a C\u00e2mara servia como elemento de obstru\u00e7\u00e3o ao antigo governo, chantageando, fazendo todo tipo de amea\u00e7as em prol de benef\u00edcios, na maioria das vezes, escusos; ou a C\u00e2mara virou, nos \u00faltimos tempos, um mero carimbador da vontade do Poder Executivo. Ent\u00e3o, n\u00e3o podemos ter uma C\u00e2mara que seja totalmente subserviente ao governo nem conspiradora do Poder Executivo\u201d.<\/p>\n<p style=\"text-align: justify;\">Caso seja eleito presidente da Casa, Figueiredo quer reduzir o n\u00famero de comiss\u00f5es especiais que, de acordo com ele, tira a import\u00e2ncia das comiss\u00f5es permanentes; propor uma ordem do dia que n\u00e3o avance pela madrugada e ampliar o debate de temas como, por exemplo, a proposta de Reforma da Previd\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Figueiredo come\u00e7ou a trajet\u00f3ria na C\u00e2mara dos Deputados em 2005. Na primeira legislatura ficou at\u00e9 2007 e voltou em 2011. Em 2015, assumiu o cargo de ministro das Comunica\u00e7\u00f5es do governo, que ocupou at\u00e9 maio de 2016.<\/p>\n<div id=\"attachment_100098\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-100098\" class=\"size-medium wp-image-100098\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1030612-pzzb6528-300x173.jpg\" alt=\"O deputado J\u00falio Delgado lan\u00e7ou candidatura avulsa dentro do PSB (Foto: Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil) \" width=\"300\" height=\"173\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1030612-pzzb6528-300x173.jpg 300w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/1030612-pzzb6528.jpg 599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-100098\" class=\"wp-caption-text\">O deputado J\u00falio Delgado lan\u00e7ou candidatura avulsa dentro do PSB (Foto: Fabio Rodrigues Pozzebom\/Ag\u00eancia Brasil)<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>J\u00falio Delgado<\/strong><\/p>\n<p style=\"text-align: justify;\">Na segunda-feira (30), o deputado J\u00falio Delgado (PSB-MG) lan\u00e7ou candidatura avulsa dentro do partido. Delgado n\u00e3o tem o apoio do seu partido, o PSB, que deve apoiar Rodrigo Maia.<\/p>\n<p style=\"text-align: justify;\">Em sua p\u00e1gina oficial no Facebook, Delgado afirma que deseja \u201cconsolidar o Legislativo um poder aut\u00f4nomo\u201d. \u201cN\u00e3o podemos ter na presid\u00eancia da Casa uma esp\u00e9cie de l\u00edder do governo ou um opositor a ele. Somente a independ\u00eancia entre os poderes \u00e9 capaz de resgatar o respeito da sociedade ao Parlamento e possibilitar sua representa\u00e7\u00e3o como determina a Constitui\u00e7\u00e3o. E \u00e9 exatamente isso que propomos atrav\u00e9s da nossa candidatura\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Deputado federal desde 1999, Delgado est\u00e1 na quarta legislatura. Ele j\u00e1 foi l\u00edder do PPS em 2004 e 2005 \u2013 partido ao qual foi filiado entre 2001 e 2005 \u2013 e do PSB, em 2014 e 2015. Em 2005, ele foi o relator do processo que cassou o ent\u00e3o deputado federal Jos\u00e9 Dirceu.<\/p>\n<p style=\"text-align: justify;\"><strong>Acompanhe tamb\u00e9m o SE Not\u00edcias no <a href=\"https:\/\/twitter.com\/Senoticias\">Twitter<\/a>, <a href=\"https:\/\/www.facebook.com\/PortalSENoticias\/\">Facebook <\/a>e no <a href=\"https:\/\/www.instagram.com\/senoticias\/\">Instagram<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-100041\" src=\"http:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/Logo-fone-1-2-1-2-4-1.jpg\" alt=\"Logo-fone-1-2-1-2-4\" width=\"599\" height=\"78\" srcset=\"https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/Logo-fone-1-2-1-2-4-1.jpg 599w, https:\/\/senoticias.com.br\/se\/wp-content\/uploads\/2017\/01\/Logo-fone-1-2-1-2-4-1-300x39.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Da Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira (2), a C\u00e2mara dos Deputados escolhe quem ficar\u00e1 \u00e0 frente da Casa pelos pr\u00f3ximos dois anos. As inscri\u00e7\u00f5es para se candidatar ao cargo est\u00e3o abertas at\u00e9 as 23h desta quarta-feira (1\u00ba). At\u00e9 o momento, cinco deputados devem disputar o cargo. Entre os candidatos, quatro s\u00e3o considerados de partidos da base aliada do governo: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":100099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-100091","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/100091"}],"collection":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/comments?post=100091"}],"version-history":[{"count":0,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/posts\/100091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media\/100099"}],"wp:attachment":[{"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/media?parent=100091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/categories?post=100091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senoticias.com.br\/se\/wp-json\/wp\/v2\/tags?post=100091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}